{"id":73555,"date":"2026-07-16T14:32:21","date_gmt":"2026-07-16T17:32:21","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=73555"},"modified":"2026-07-18T10:37:52","modified_gmt":"2026-07-18T13:37:52","slug":"pullaro-por-los-pronosticos-de-el-nino-santa-fe-esta-hoy-mucho-mejor-preparada-que-hace-tres-anos","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/07\/16\/pullaro-por-los-pronosticos-de-el-nino-santa-fe-esta-hoy-mucho-mejor-preparada-que-hace-tres-anos\/","title":{"rendered":"Pullaro por los pron\u00f3sticos de El Ni\u00f1o: \u201cSanta Fe est\u00e1 hoy mucho mejor preparada que hace tres a\u00f1os\u201d"},"content":{"rendered":"<p><strong>Ante los informes que anticipan lluvias intensas desde el \u00faltimo trimestre de 2026, el gobernador reuni\u00f3 en la capital provincial a intendentes y presidentes comunales del centro-norte santafesino para coordinar acciones de prevenci\u00f3n. Destac\u00f3 las inversiones que realiza Provincia en infraestructura h\u00eddrica, equipamiento y Protecci\u00f3n Civil, y pidi\u00f3 a los gobiernos locales avanzar con las tareas que les corresponden para reducir el impacto del fen\u00f3meno.<\/strong><\/p>\n<p>El gobernador Maximiliano Pullaro encabez\u00f3 este jueves, en la ciudad de Santa Fe, una reuni\u00f3n del Comit\u00e9 Interministerial Operativo de Emergencias con intendentes, presidentes comunales, comit\u00e9s de cuenca, entidades productivas e instituciones del centro-norte provincial para coordinar las acciones de prevenci\u00f3n y respuesta frente al fen\u00f3meno clim\u00e1tico El Ni\u00f1o, cuyos pron\u00f3sticos anticipan un escenario de lluvias intensas y excesos h\u00eddricos durante el \u00faltimo trimestre de 2026.<\/p>\n<p>Durante el encuentro, realizado en el Centro Cultural Provincial, el Gobierno repas\u00f3 el conjunto de obras, inversiones y medidas ejecutadas en los \u00faltimos meses para fortalecer la capacidad de respuesta de la provincia y minimizar el impacto sobre la poblaci\u00f3n, la infraestructura y el sistema productivo.<\/p>\n<p>El ministro de Gobierno e Innovaci\u00f3n P\u00fablica y presidente del Comit\u00e9 Interministerial Operativo de Emergencias, Fabi\u00e1n Bastia, repas\u00f3 las acciones coordinadas entre las distintas \u00e1reas del Estado. Luego, el ministro de Obras P\u00fablicas, Lisandro Enrico, y el secretario de Recursos H\u00eddricos, Nicol\u00e1s Mijich, expusieron el avance del Plan H\u00eddrico Provincial.<\/p>\n<p>A su vez, la ministra de Igualdad y Desarrollo Humano, Victoria Tejeda, junto con el secretario de Protecci\u00f3n Civil y Gesti\u00f3n de Riesgos, Marcos Escajadillo, explicaron el funcionamiento del sistema provincial de respuesta ante emergencias, mientras que el secretario de Agricultura y Ganader\u00eda, Ignacio M\u00e1ntaras, present\u00f3 las medidas previstas para los sectores productivos.<\/p>\n<p><strong>\u201cMucho mejor preparados\u201d<\/strong><\/p>\n<p>Al cerrar la jornada, Pullaro sostuvo que el objetivo del encuentro fue prepararse ante un escenario que los pron\u00f3sticos consideran altamente probable. \u201cNo se trata de alarmar, sino de ocuparnos. Los informes indican que este fen\u00f3meno llegar\u00e1 con mayor o menor intensidad y tenemos que estar preparados, invirtiendo los recursos necesarios y coordinando estrat\u00e9gicamente el trabajo\u201d, afirm\u00f3.<\/p>\n<p>El gobernador record\u00f3 que la Provincia comenz\u00f3 a planificar estas acciones incluso antes del inicio de la gesti\u00f3n y asegur\u00f3 que ese trabajo permiti\u00f3 fortalecer la capacidad de respuesta. \u201cHoy estamos mucho mejor preparados de lo que estaba la provincia hace tres a\u00f1os\u201d, remarc\u00f3.<\/p>\n<p>En ese sentido, enumer\u00f3 la limpieza de canales, la incorporaci\u00f3n de maquinaria para acelerar las intervenciones, el trabajo conjunto con los comit\u00e9s de cuenca, la articulaci\u00f3n con las fuerzas de seguridad y las instituciones de cada regi\u00f3n, y las inversiones destinadas a reducir el impacto de las lluvias sobre los vecinos y el aparato productivo.<\/p>\n<p>Tambi\u00e9n destac\u00f3 que m\u00e1s del 70 % de la red de canales estar\u00e1 en condiciones operativas, la creaci\u00f3n de un fondo de 10.000 millones de pesos para asistir a municipios y comunas, las compras centralizadas de insumos para emergencias y el fortalecimiento del equipamiento de Protecci\u00f3n Civil, con nuevas embarcaciones, cuatro helic\u00f3pteros, veh\u00edculos 4&#215;4 y personal especialmente capacitado.<\/p>\n<p><strong>Trabajo conjunto<\/strong><\/p>\n<p>Pullaro insisti\u00f3 en que la preparaci\u00f3n requiere el compromiso de todos los niveles del Estado.<\/p>\n<p>\u201cEsta reuni\u00f3n es importante porque todos vamos a estar involucrados cuando haya que responder. En muchos lugares ya se hicieron las tareas necesarias, pero en otros todav\u00eda no se tom\u00f3 dimensi\u00f3n de lo que puede ocurrir. Tenemos una ventana de aproximadamente 90 d\u00edas para hacer lo que falta y llegar mejor preparados\u201d, se\u00f1al\u00f3.<\/p>\n<p>Finalmente, convoc\u00f3 a los gobiernos locales a intensificar las tareas preventivas. \u201cAqu\u00ed tienen un Gobierno Provincial dispuesto a acompa\u00f1ar a cada localidad; no los vamos a dejar solos. Pero cada uno debe asumir la responsabilidad que le corresponde para que el impacto de este fen\u00f3meno sea el menor posible\u201d, concluy\u00f3.<\/p>\n<p><strong>Obras prioritarias para el Gran Santa Fe<\/strong><\/p>\n<p>Por su parte, el ministro Enrico, destac\u00f3 el avance de las obras de defensa h\u00eddrica en el Gran Santa Fe, retomadas en enero de 2024, entre ellas el terrapl\u00e9n Garello, que registra un avance del 75 %. El funcionario explic\u00f3 que la capital provincial, junto con Arroyo Leyes, San Jos\u00e9 del Rinc\u00f3n y Saladero Cabal, constituye una de las \u00e1reas de mayor vulnerabilidad h\u00eddrica y concentra una parte importante de las inversiones. \u201cSolo en esta regi\u00f3n ya llevamos invertidos m\u00e1s de 30.000 millones de pesos en obras de defensa, estaciones de bombeo, reservorios y sistemas de protecci\u00f3n\u201d, indic\u00f3.<\/p>\n<p>Enrico agreg\u00f3 que, ante la paralizaci\u00f3n de las obras nacionales, la Provincia asumi\u00f3 la ejecuci\u00f3n de proyectos estrat\u00e9gicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante los informes que anticipan lluvias intensas desde el \u00faltimo trimestre de 2026, el gobernador reuni\u00f3 en la capital provincial a intendentes y presidentes comunales del centro-norte santafesino para coordinar acciones de prevenci\u00f3n. Destac\u00f3 las inversiones que realiza Provincia en infraestructura h\u00eddrica, equipamiento y Protecci\u00f3n Civil, y pidi\u00f3 a los gobiernos locales avanzar con las [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":73557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":["post-73555","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provinciales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/73555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=73555"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/73555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/73557"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=73555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=73555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=73555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}