{"id":73537,"date":"2026-07-16T09:09:52","date_gmt":"2026-07-16T12:09:52","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=73537"},"modified":"2026-07-17T10:18:36","modified_gmt":"2026-07-17T13:18:36","slug":"paula-mitre-celebro-un-importante-avance-en-su-tratamiento-ya-tengo-un-motivo-para-celebrar-hoy","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/07\/16\/paula-mitre-celebro-un-importante-avance-en-su-tratamiento-ya-tengo-un-motivo-para-celebrar-hoy\/","title":{"rendered":"Paula Mitre celebr\u00f3 un importante avance en su tratamiento: &#8220;Ya tengo un motivo para celebrar hoy&#8221;"},"content":{"rendered":"<p><strong>La intendente de Vera, Paula Mitre, comparti\u00f3 este martes un emotivo mensaje en sus redes sociales para contar que alcanz\u00f3 una nueva etapa en su tratamiento m\u00e9dico.<\/strong><\/p>\n<p>&#8220;Yo ya tengo un motivo para celebrar hoy. Llegu\u00e9 a mis 15 sesiones de rayos&#8221;, expres\u00f3 junto a un mensaje de profundo agradecimiento hacia quienes la acompa\u00f1an en este proceso.<\/p>\n<p>Mitre destac\u00f3 el apoyo recibido de su familia, amigos y vecinos de Vera: &#8220;Gracias a TODOS por tanto afecto. A mi familia, a mis amigos y a mis queridos vecinos que me acompa\u00f1aron en este proceso. Gracias por cada abrazo, por los besos, por cada palabra de aliento, por cada mensaje, por ponerme en sus oraciones&#8221;.<\/p>\n<p>Finalmente, la mandataria resalt\u00f3 la importancia de la fe y el acompa\u00f1amiento recibido: &#8220;El poder de la fe y del amor sincero es maravilloso. Los quiero&#8221;, concluy\u00f3.<\/p>\n<p>La publicaci\u00f3n recibi\u00f3 numerosas muestras de cari\u00f1o y mensajes de aliento de vecinos, dirigentes e instituciones que le desearon fuerzas para continuar con su recuperaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La intendente de Vera, Paula Mitre, comparti\u00f3 este martes un emotivo mensaje en sus redes sociales para contar que alcanz\u00f3 una nueva etapa en su tratamiento m\u00e9dico. &#8220;Yo ya tengo un motivo para celebrar hoy. Llegu\u00e9 a mis 15 sesiones de rayos&#8221;, expres\u00f3 junto a un mensaje de profundo agradecimiento hacia quienes la acompa\u00f1an en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":73538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-73537","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/73537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=73537"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/73537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/73538"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=73537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=73537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=73537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}