{"id":72490,"date":"2026-05-30T10:26:13","date_gmt":"2026-05-30T13:26:13","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=72490"},"modified":"2026-05-30T10:26:13","modified_gmt":"2026-05-30T13:26:13","slug":"prorrogaron-la-prision-preventiva-de-una-mujer-a-la-que-se-investiga-por-la-venta-de-droga-al-menudeo-en-reconquista","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/05\/30\/prorrogaron-la-prision-preventiva-de-una-mujer-a-la-que-se-investiga-por-la-venta-de-droga-al-menudeo-en-reconquista\/","title":{"rendered":"Prorrogaron la prisi\u00f3n preventiva de una mujer a la que se investiga por la venta de droga al menudeo en Reconquista"},"content":{"rendered":"<p><strong>As\u00ed fue dispuesto en una audiencia en la que el fiscal Sebasti\u00e1n Galleano represent\u00f3 al MPA. La imputada tiene 48 a\u00f1os y cumple la medida cautelar desde febrero de este a\u00f1o. En un allanamiento realizado en el barrio La Cortada, se le secuestr\u00f3 un trozo compacto de 328,9 gramos de coca\u00edna.<\/strong><\/p>\n<p>Una mujer de 48 a\u00f1os, cuyas iniciales son AEC, continuar\u00e1 en prisi\u00f3n preventiva en el marco de un legajo penal en el que se la investiga por vender droga al menudeo en Reconquista. La cautelar prorrogada hab\u00eda sido impuesta en febrero de este a\u00f1o.<\/p>\n<p>La continuidad de la privaci\u00f3n de la libertad fue resuelta por el juez Gustavo Gon en una audiencia realizada en los tribunales reconquistenses.<\/p>\n<p>El fiscal Sebasti\u00e1n Galleano est\u00e1 a cargo de la investigaci\u00f3n y represent\u00f3 al MPA en la audiencia. En tal sentido, indic\u00f3 que \u201caunque la Defensa solicit\u00f3 medidas alternativas, argumentamos que eran insuficientes para mitigar los riesgos procesales porque las circunstancias que hace tres meses motivaron la preventiva siguen vigentes\u201d, y valor\u00f3 que \u201cel juez aval\u00f3 nuestra postura\u201d.<\/p>\n<p>Asimismo, Galleano puntualiz\u00f3 que \u201cal pedir la morigeraci\u00f3n de la cautelar, el abogado de la imputada mencion\u00f3 que ella tiene problemas de salud\u201d, y destac\u00f3 que \u201cel magistrado no hizo lugar a ese agravio porque no hay ning\u00fan indicio de que la mujer no est\u00e9 siendo tratada y no pueda recuperarse dentro del establecimiento penal en el que est\u00e1 alojada\u201d.<\/p>\n<p>El caso se enmarca en los objetivos priorizados por el MPA en su Plan de Persecuci\u00f3n Penal.<\/p>\n<p><strong>Trozo de coca\u00edna<\/strong><\/p>\n<p>El funcionario del MPA afirm\u00f3 que \u201cen un allanamiento realizado el jueves 19 de febrero en una casa del barrio La Cortada en la que resid\u00eda la imputada, se secuestr\u00f3 un trozo compacto de coca\u00edna que pesaba 328,9 gramos\u201d, y especific\u00f3 que \u201cese material estupefaciente podr\u00eda haber sido fraccionado en alrededor de 1.000 dosis\u201d.<\/p>\n<p>\u201cA su vez, en la vivienda\u00a0se encontraron\u00a0un envoltorio con coca\u00edna; utensilios con vestigios\u00a0de esa sustancia;\u00a0dos tel\u00e9fonos celulares, y dinero en efectivo\u00a0presuntamente vinculado al microtr\u00e1fico\u201d,\u00a0enumer\u00f3 Galleano.<\/p>\n<p><strong>Calificaci\u00f3n penal<\/strong><\/p>\n<p>La imputada es investigada como autora de tenencia de estupefacientes con fines de comercializaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed fue dispuesto en una audiencia en la que el fiscal Sebasti\u00e1n Galleano represent\u00f3 al MPA. La imputada tiene 48 a\u00f1os y cumple la medida cautelar desde febrero de este a\u00f1o. En un allanamiento realizado en el barrio La Cortada, se le secuestr\u00f3 un trozo compacto de 328,9 gramos de coca\u00edna. Una mujer de 48 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":37146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[79,61],"tags":[],"class_list":["post-72490","post","type-post","status-publish","format-standard","has-post-thumbnail","category-judiciales","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/72490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=72490"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/72490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/37146"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=72490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=72490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=72490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}