{"id":72031,"date":"2026-05-13T11:05:51","date_gmt":"2026-05-13T14:05:51","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=72031"},"modified":"2026-05-13T11:05:51","modified_gmt":"2026-05-13T14:05:51","slug":"rojas-las-universidades-publicas-en-el-norte-santafesino-son-sinonimo-de-desarrollo","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/05\/13\/rojas-las-universidades-publicas-en-el-norte-santafesino-son-sinonimo-de-desarrollo\/","title":{"rendered":"Rojas: &#8220;Las universidades p\u00fablicas en el norte santafesino son sin\u00f3nimo de desarrollo&#8221;"},"content":{"rendered":"<p><strong>El diputado provincial Sergio \u201cChiqui\u201d Rojas acompa\u00f1\u00f3 la movilizaci\u00f3n universitaria en Reconquista y advirti\u00f3 que el desfinanciamiento nacional pone en riesgo a\u00f1os de construcci\u00f3n educativa en el pa\u00eds y la regi\u00f3n.<\/strong><\/p>\n<p>El diputado se sum\u00f3 ayer a la jornada que se realiz\u00f3 en Reconquista en el marco de la cuarta Marcha Federal Universitaria, convocada en todo el pa\u00eds para exigir el cumplimiento de la Ley de Financiamiento Universitario, que el Gobierno nacional se niega a aplicar pese a haber sido aprobada en el Congreso y avalada por la Justicia.<\/p>\n<p>Adem\u00e1s de la movilizaci\u00f3n, se realiz\u00f3 una charla abierta en la Facultad Regional Reconquista de la Universidad Tecnol\u00f3gica Nacional, organizada en conjunto con el Centro Universitario Reconquista-Avellaneda de Universidad Nacional de Litoral, que cont\u00f3 con la participaci\u00f3n del diputado Rojas y la concejal socialista de Reconquista Marisa Flores.<\/p>\n<p>En ese marco, Rojas remarc\u00f3 la importancia estrat\u00e9gica de las universidades p\u00fablicas para el desarrollo del norte santafesino y llam\u00f3 a acompa\u00f1ar el reclamo desde todos los sectores pol\u00edticos. &#8220;Es necesario acompa\u00f1ar desde todos los sectores pol\u00edticos este reclamo por nuestras universidades p\u00fablicas en el norte santafesino y por eso estamos presentes&#8221;, afirm\u00f3 el diputado.<\/p>\n<p>Por otra parte, destac\u00f3 el esfuerzo hist\u00f3rico que signific\u00f3 llevar la educaci\u00f3n universitaria p\u00fablica a la regi\u00f3n: &#8220;Lograr que nuestros pibes y pibas puedan estudiar en la regi\u00f3n, desde Calchaqu\u00ed a Florencia, llev\u00f3 muchos a\u00f1os y no podemos dejar que un gobierno que se niega a cumplir la ley ponga en jaque esa posibilidad&#8221;.<\/p>\n<p>Rojas tambi\u00e9n subray\u00f3 el rol transformador de las universidades en el entramado productivo local: las casas de estudio del norte vienen desarrollando un trabajo incansable junto a los gobiernos locales y tambi\u00e9n fortaleciendo al sector privado, a las pymes y a las empresas de la regi\u00f3n.<\/p>\n<p>El diputado convoc\u00f3 a sostener la defensa de la educaci\u00f3n p\u00fablica como una causa que trasciende las diferencias partidarias, en un momento en que el desfinanciamiento amenaza d\u00e9cadas de construcci\u00f3n colectiva en uno de los territorios que m\u00e1s necesita del acceso al conocimiento para impulsar su desarrollo.<\/p>\n<p><a href=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-72033\" src=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2.jpeg\" alt=\"\" width=\"3913\" height=\"2934\" srcset=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2.jpeg 3913w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2-560x420.jpeg 560w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2-80x60.jpeg 80w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2-696x522.jpeg 696w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2-1068x801.jpeg 1068w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.01.16-AM-2-265x198.jpeg 265w\" sizes=\"auto, (max-width: 3913px) 100vw, 3913px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado provincial Sergio \u201cChiqui\u201d Rojas acompa\u00f1\u00f3 la movilizaci\u00f3n universitaria en Reconquista y advirti\u00f3 que el desfinanciamiento nacional pone en riesgo a\u00f1os de construcci\u00f3n educativa en el pa\u00eds y la regi\u00f3n. El diputado se sum\u00f3 ayer a la jornada que se realiz\u00f3 en Reconquista en el marco de la cuarta Marcha Federal Universitaria, convocada en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":72032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[56],"tags":[],"class_list":{"0":"post-72031","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacados"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/72031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=72031"}],"version-history":[{"count":1,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/72031\/revisions"}],"predecessor-version":[{"id":72034,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/72031\/revisions\/72034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/72032"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=72031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=72031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=72031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}