{"id":71230,"date":"2026-04-14T08:51:52","date_gmt":"2026-04-14T11:51:52","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=71230"},"modified":"2026-04-14T08:51:52","modified_gmt":"2026-04-14T11:51:52","slug":"dos-detenidos-tras-ingresar-a-una-vivienda-en-calle-estanislao-lopez","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/04\/14\/dos-detenidos-tras-ingresar-a-una-vivienda-en-calle-estanislao-lopez\/","title":{"rendered":"Dos detenidos tras ingresar a una vivienda en calle Estanislao L\u00f3pez"},"content":{"rendered":"<p>En horas de la madrugada de este lunes 14 de abril de 2026, personal del Comando Radioel\u00e9ctrico fue comisionado por la central de emergencias 101 a un domicilio ubicado en inmediaciones de calle Estanislao L\u00f3pez al 1200, donde una mujer alertaba sobre la presencia de personas en el techo de su vivienda.<\/p>\n<p>Al arribar al lugar, los efectivos constataron la situaci\u00f3n y observaron que varios individuos se daban a la fuga hacia un terreno bald\u00edo lindante.<\/p>\n<p>De manera inmediata se realiz\u00f3 un operativo de saturaci\u00f3n en la zona, logrando localizar a tres masculinos ocultos en una vivienda abandonada cercana. Fueron r\u00e1pidamente interceptados y trasladados a sede policial, donde se realizaron las actuaciones correspondientes.<\/p>\n<p>Dos de ellos quedaron detenidos, mientras que el menor de edad fue entregado a un familiar responsable.<\/p>\n<p>Se dio conocimiento al Ministerio P\u00fablico de la Acusaci\u00f3n, que orden\u00f3 las diligencias de rigor.<\/p>\n<p>La Unidad Regional XIX recuerda: ante la presencia de personas que puedan resultar sospechosas y\/o desconocidas, d\u00e9 aviso al T.E 101 emergencias y\/o a la comisar\u00eda m\u00e1s cercana a su domicilio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la madrugada de este lunes 14 de abril de 2026, personal del Comando Radioel\u00e9ctrico fue comisionado por la central de emergencias 101 a un domicilio ubicado en inmediaciones de calle Estanislao L\u00f3pez al 1200, donde una mujer alertaba sobre la presencia de personas en el techo de su vivienda. Al arribar al [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":71231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,53],"tags":[],"class_list":["post-71230","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/71230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=71230"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/71230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/71231"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=71230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=71230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=71230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}