{"id":71215,"date":"2026-04-13T17:39:11","date_gmt":"2026-04-13T20:39:11","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=71215"},"modified":"2026-04-13T17:39:11","modified_gmt":"2026-04-13T20:39:11","slug":"vera-invitan-a-una-charla-debate-sobre-ambiente-con-diego-garcia-rios","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/04\/13\/vera-invitan-a-una-charla-debate-sobre-ambiente-con-diego-garcia-rios\/","title":{"rendered":"Vera: invitan a una charla-debate sobre ambiente con Diego Garc\u00eda R\u00edos"},"content":{"rendered":"<p><strong>Se realizar\u00e1 en la ciudad de Vera una charla-debate a cargo de Diego Garc\u00eda R\u00edos, profesor de Geograf\u00eda, escritor y capacitador ambiental, destinada principalmente a estudiantes secundarios.<\/strong><\/p>\n<p>La propuesta busca generar un espacio de reflexi\u00f3n cr\u00edtica sobre el ambiente, invitando a cuestionar ideas instaladas y analizar los desaf\u00edos actuales desde una mirada m\u00e1s consciente.<\/p>\n<p>La actividad se desarrollar\u00e1 a partir del libro \u201c50 eco-mentiras para salvar el planeta\u201d, obra del disertante que propone debatir, participar y repensar el futuro en clave ambiental.<\/p>\n<p>El encuentro est\u00e1 programado para el martes 14 de abril a las 10:00 horas en el Cine Teatro Espa\u00f1ol.<\/p>\n<p>La iniciativa es impulsada por Espacio Abierto, con el acompa\u00f1amiento del diputado Sergio \u201cChiqui\u201d Rojas, Ana Capello Armando y la Municipalidad de Vera.<\/p>\n<p><a href=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/04\/2C.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-71217\" src=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/04\/2C.png\" alt=\"\" width=\"1077\" height=\"1065\" srcset=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/04\/2C.png 1077w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/04\/2C-425x420.png 425w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/04\/2C-696x688.png 696w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2026\/04\/2C-1068x1056.png 1068w\" sizes=\"auto, (max-width: 1077px) 100vw, 1077px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se realizar\u00e1 en la ciudad de Vera una charla-debate a cargo de Diego Garc\u00eda R\u00edos, profesor de Geograf\u00eda, escritor y capacitador ambiental, destinada principalmente a estudiantes secundarios. La propuesta busca generar un espacio de reflexi\u00f3n cr\u00edtica sobre el ambiente, invitando a cuestionar ideas instaladas y analizar los desaf\u00edos actuales desde una mirada m\u00e1s consciente. La [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":71216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[56],"tags":[],"class_list":["post-71215","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacados"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/71215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=71215"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/71215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/71216"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=71215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=71215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=71215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}