{"id":70087,"date":"2026-02-27T18:05:34","date_gmt":"2026-02-27T21:05:34","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=70087"},"modified":"2026-02-27T18:06:53","modified_gmt":"2026-02-27T21:06:53","slug":"caida-de-consumo-importaciones-y-default-se-concurso-alal-centenaria-empresa-del-norte-provincial","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/02\/27\/caida-de-consumo-importaciones-y-default-se-concurso-alal-centenaria-empresa-del-norte-provincial\/","title":{"rendered":"Ca\u00edda de consumo, importaciones y default: se concurs\u00f3 Alal, centenaria empresa del norte provincial"},"content":{"rendered":"<p><strong>Se trata de Emilio Alal SACIFI, referente del rubro curtiembre, hilander\u00eda de algod\u00f3n, desmotadora de algod\u00f3n, con diversificaci\u00f3n en agronegocios. En enero hab\u00eda cerrado dos plantas textiles y cesanteado a centenares de trabajadores. La Justicia decret\u00f3 la apertura del proceso preventivo.<\/strong><\/p>\n<p>El Juzgado de Primera Instancia en lo Civil y Comercial de Primera Nominaci\u00f3n de Reconquista resolvi\u00f3, con fecha 27 de febrero de 2026, decretar la apertura del concurso preventivo de la empresa Emilio Alal SACIFI.<\/p>\n<p>La solicitud fue presentada por Emilio Miguel Alal, en su car\u00e1cter de presidente de la firma, conforme lo decidido en Asamblea General Ordinaria y Extraordinaria del 9 de febrero de 2026, cumpli\u00e9ndose posteriormente con todos los recaudos exigidos por la Ley de Concursos y Quiebras. Fundada en 1914, la firma es referente del rubro curtiembre, hilander\u00eda de algod\u00f3n, desmotadora de algod\u00f3n, con diversificaci\u00f3n en agronegocios.<\/p>\n<p>Los argumentos expresados por la conducci\u00f3n de la industria norte\u00f1a en su presentaci\u00f3n judicial describen un <strong>contexto econ\u00f3mico adverso compuesto por la ca\u00edda abrupta del consumo interno, la apertura indiscriminada de importaciones, la crisis general del rubro en el que desarrolla su actividad, m\u00e1s el incremento de los costos de energ\u00eda e insumos, no trasladables a precios.<\/strong><\/p>\n<p>Asimismo, Alal cit\u00f3 como factores del declive financiero la imposibilidad de acceder al cr\u00e9dito, la p\u00e9rdida de herramientas habituales de financiamiento del capital de trabajo, como el recorte de l\u00edneas bancarias y el descuento de cheques de terceros, y el impacto del costo laboral, que en conjunto deterioraron los resultados, elevaron la capacidad ociosa y tornaron inviable cumplir en tiempo y forma con las obligaciones exigibles.<\/p>\n<p>Todo es c\u00famulo de inconvenientes derivaron en la ca\u00edda en cesaci\u00f3n de pagos, indicando como hecho revelador principal la imposibilidad de afrontar, el 23 de enero de 2026, el pago de liquidaciones finales e indemnizaciones laborales previstas en el art\u00edculo 247 de la Ley de Contrato de Trabajo.<\/p>\n<p>Esto \u00faltimo, en referencia al <strong>cierre sus plantas productivas de hilados y telas en Goya (Corrientes) y Villa \u00c1ngela (Chaco) debido al \u201ccontexto econ\u00f3mico y comercial adverso que afecta la competitividad de la industria nacional\u201d, ocurrido en enero pasado y que afect\u00f3 a un n\u00famero estimado de entre 220 y 250 empleados.<\/strong><\/p>\n<p><strong>Plazos<\/strong><\/p>\n<p>El juez Franco Raschetti, titular del juzgado donde recay\u00f3 el expediente -la empresa tiene sede central en Reconquista- consider\u00f3 que estas circunstancias configuran hechos reveladores del estado de cesaci\u00f3n de pagos, y que la v\u00eda del concurso preventivo resulta adecuada para intentar la reestructuraci\u00f3n del pasivo y la continuidad de la empresa, conforme a los principios de la ley concursal vigente.<\/p>\n<p>En consecuencia, hizo lugar al planteo empresario y dispuso clasificar el proceso como \u201cGran Concurso \u2013 Categor\u00eda A\u201d, fijando audiencia para el sorteo de la sindicatura el 3 de marzo de 2026 a las 8. Asimismo, orden\u00f3 la publicaci\u00f3n de edictos por cinco d\u00edas en los Boletines Oficiales de Santa Fe, Corrientes, Chaco, Naci\u00f3n y CABA, adem\u00e1s de diarios de amplia circulaci\u00f3n en Reconquista, Corrientes y Resistencia, y extendi\u00f3 los plazos legales del proceso concursal en atenci\u00f3n a su magnitud y complejidad.<\/p>\n<p>En paralelo, fij\u00f3 como fecha l\u00edmite para la verificaci\u00f3n de cr\u00e9ditos el 28 de mayo de 2026, mientras que las impugnaciones podr\u00e1n presentarse hasta el 25 de junio de 2026. Los informes individuales deber\u00e1n presentarse el 27 de agosto de 2026 y el informe general el 19 de noviembre de 2026.<\/p>\n<p>En tanto, condicion\u00f3 la salida del pa\u00eds de los integrantes del Directorio de la Sociedad concursada al cumplimiento de lo establecido por la LCQ. <strong>La medida alcanza a Emilio Miguel Alal (presidente), Eduardo Antonio Alal (vicepresidente), Marcelo Julio Alal (secretario), Luis Antonio Alal (director), Liliana Beatriz Alal (directora), Guillermo Fabi\u00e1n Alal (director), Pablo Ra\u00fal Fabrissin (s\u00edndico titular).<\/strong><\/p>\n<p><strong>Comit\u00e9 de Control<\/strong><\/p>\n<p>Seg\u00fan precis\u00f3 la resoluci\u00f3n el 27 de febrero, suman 320 los acreedores denunciados por la concursada. De all\u00ed surgieron, a efectos de mantener una representaci\u00f3n de la totalidad de los grupos consignados dentro de la categor\u00eda \u201cquirografarios\u201d, los miembros titulares del Comit\u00e9 Provisorio de Control: <strong>Banco de la Naci\u00f3n Argentina, con domicilio en calle San Mart\u00edn N\u00b0802 de Reconquista; Banco Credicoop Coop. Ltdo, con domicilio en calle 9 N\u00b0 499 de la Ciudad de Avellaneda; e Indunor SA, con domicilio en calle Cerrito 1136 piso 11 (CABA).<\/strong><\/p>\n<p>Como suplentes se estatuy\u00f3 a: Banco de Corrientes SA, con domicilio en calle Belgrano N\u00b0 998 de la Ciudad de Goya (Corrientes); Nuevo Banco del Chaco SA, con domicilio en calle San Mart\u00edn N\u00b0 150 de la Ciudad de Villa \u00c1ngela (Chaco); y Cammesa, domiciliada en ruta 34 S km. 3,5 de la Ciudad de P\u00e9rez (Santa Fe).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de Emilio Alal SACIFI, referente del rubro curtiembre, hilander\u00eda de algod\u00f3n, desmotadora de algod\u00f3n, con diversificaci\u00f3n en agronegocios. En enero hab\u00eda cerrado dos plantas textiles y cesanteado a centenares de trabajadores. La Justicia decret\u00f3 la apertura del proceso preventivo. El Juzgado de Primera Instancia en lo Civil y Comercial de Primera Nominaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":70088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[61],"tags":[],"class_list":["post-70087","post","type-post","status-publish","format-standard","has-post-thumbnail","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/70087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=70087"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/70087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/70088"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=70087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=70087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=70087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}