{"id":69142,"date":"2026-01-12T13:59:15","date_gmt":"2026-01-12T16:59:15","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=69142"},"modified":"2026-01-12T13:59:15","modified_gmt":"2026-01-12T16:59:15","slug":"joyas-dolares-y-pesos-millonario-golpe-en-la-country-la-rural","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/01\/12\/joyas-dolares-y-pesos-millonario-golpe-en-la-country-la-rural\/","title":{"rendered":"Joyas, d\u00f3lares y pesos: millonario golpe en la country La Rural"},"content":{"rendered":"<p><strong>Dos hechos contra la propiedad se produjeror durante la madrugada del domingo 11 de enero de 2026 se registraron robos en al menos dos viviendas del country La Rural, en la ciudad de Reconquista.<\/strong><\/p>\n<p>Seg\u00fan el parte oficial, alrededor de las 00:55 horas, personal de la Guardia de Infanter\u00ed fue comisionado por la Central 911 ante la denuncia de un hecho delictivo en el mencionado complejo habitacional.<\/p>\n<p>Al arribar al lugar, los efectivos se entrevistaron con Claudio Jos\u00e9 Scarpin, de 51 a\u00f1os, quien manifest\u00f3 que se hab\u00eda ausentado de su vivienda junto a su familia para cenar y, al regresar, advirti\u00f3 que la puerta y una ventana de acceso desde el garaje se encontraban abiertas. <strong>Al ingresar, constat\u00f3 la faltante de joyas, dinero en distintas monedas, documentaci\u00f3n personal y un pasaporte.<\/strong><\/p>\n<p>Minutos m\u00e1s tarde, se present\u00f3 un vecino lindero, identificado como Hugo \u00c1ngel Sartor, de 64 a\u00f1os, quien denunci\u00f3 que tambi\u00e9n habr\u00edan ingresado a su domicilio, d<strong>onde los cacos violentaron una caja fuerte, sustrayendo una importante suma de dinero en distintas monedas.<\/strong><\/p>\n<p>Ante la situaci\u00f3n, se dio intervenci\u00f3n a la comisar\u00eda de jurisdicci\u00f3n, convoc\u00e1ndose adem\u00e1s a personal de Criminal\u00edstica Regi\u00f3n IV y a la Polic\u00eda de Investigaciones (PDI) para el desarrollo de tareas investigativas.<\/p>\n<p>El personal actuante procedi\u00f3 a delimitar un per\u00edmetro de seguridad, resguardando ambas escenas hasta la llegada de los especialistas, mientras continuaban las diligencias para esclarecer los hechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos hechos contra la propiedad se produjeror durante la madrugada del domingo 11 de enero de 2026 se registraron robos en al menos dos viviendas del country La Rural, en la ciudad de Reconquista. Seg\u00fan el parte oficial, alrededor de las 00:55 horas, personal de la Guardia de Infanter\u00ed fue comisionado por la Central 911 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69143,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,61],"tags":[],"class_list":["post-69142","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/69142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=69142"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/69142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/69143"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=69142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=69142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=69142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}