{"id":69097,"date":"2026-01-10T09:00:32","date_gmt":"2026-01-10T12:00:32","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=69097"},"modified":"2026-01-12T09:00:46","modified_gmt":"2026-01-12T12:00:46","slug":"un-menor-fue-sorprendido-con-una-bacha-de-bano-que-seria-robada","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2026\/01\/10\/un-menor-fue-sorprendido-con-una-bacha-de-bano-que-seria-robada\/","title":{"rendered":"Un menor fue sorprendido con una bacha de ba\u00f1o que ser\u00eda robada"},"content":{"rendered":"<p><strong>Personal de la Secci\u00f3n Comando Radioel\u00e9ctrico de la Unidad Regional XIX, en el marco de patrullajes preventivos, llev\u00f3 adelante un procedimiento de averiguaci\u00f3n de procedencia durante la jornada del 9 de enero de 2026, en la ciudad de Vera.<\/strong><\/p>\n<p>El hecho ocurri\u00f3 alrededor de las 13 horas, cuando los efectivos observaron en la v\u00eda p\u00fablica, en inmediaciones de calle Primero de Mayo, a un adolescente de 16 a\u00f1os que transportaba una bacha de ba\u00f1o con grifer\u00eda completa. Al advertir la presencia policial, el joven arroj\u00f3 los elementos, por lo que fue interceptado e identificado.<\/p>\n<p>Al ser consultado sobre la procedencia de los objetos, el menor no pudo brindar una explicaci\u00f3n clara, motivo por el cual fue trasladado a sede policial, procedi\u00e9ndose adem\u00e1s al secuestro de los elementos para las diligencias correspondientes.<\/p>\n<p>Con intervenci\u00f3n del fiscal en turno, el adolescente fue posteriormente entregado a su progenitor, continu\u00e1ndose con las actuaciones de rigor para establecer el origen de los objetos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal de la Secci\u00f3n Comando Radioel\u00e9ctrico de la Unidad Regional XIX, en el marco de patrullajes preventivos, llev\u00f3 adelante un procedimiento de averiguaci\u00f3n de procedencia durante la jornada del 9 de enero de 2026, en la ciudad de Vera. El hecho ocurri\u00f3 alrededor de las 13 horas, cuando los efectivos observaron en la v\u00eda p\u00fablica, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,53],"tags":[],"class_list":["post-69097","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/69097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=69097"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/69097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/69098"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=69097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=69097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=69097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}