{"id":66986,"date":"2025-10-13T18:38:10","date_gmt":"2025-10-13T21:38:10","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=66986"},"modified":"2025-10-13T19:00:13","modified_gmt":"2025-10-13T22:00:13","slug":"vera-madre-e-hija-chocaron-en-moto-contra-un-auto-estacionado","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/10\/13\/vera-madre-e-hija-chocaron-en-moto-contra-un-auto-estacionado\/","title":{"rendered":"Vera: madre e hija chocaron en moto contra un auto estacionado"},"content":{"rendered":"<p><strong>Este lunes, alrededor de las 09:40, personal de la Comisar\u00eda Primera y del Comando Radioel\u00e9ctrico de la Unidad Regional XIX intervino en un accidente de tr\u00e1nsito ocurrido en la intersecci\u00f3n de calles Moreno y Eugenio Alem\u00e1n de la ciudad de Vera.<\/strong><\/p>\n<p>Por causas que se tratan de establecer, una motocicleta Honda Biz 125 c.c., conducida por una mujer de 47 a\u00f1os y acompa\u00f1ada por su hija de 15, colision\u00f3 contra un autom\u00f3vil Renault Sandero que se encontraba estacionado.<\/p>\n<p>Ambas ocupantes del rodado menor fueron trasladadas en ambulancia al hospital local para recibir atenci\u00f3n m\u00e9dica.<\/p>\n<p>Se prosiguen diligencias con intervenci\u00f3n de la Unidad Fiscal N\u00ba 4 de Vera.<\/p>\n<p><strong>EL PARTE POLICIAL<\/strong><\/p>\n<p><strong>Unidad Regional XIX \u2013 vera<\/strong><br \/>\n<strong>Accidente de tr\u00e1nsito<\/strong><\/p>\n<p>En horas de la ma\u00f1ana (09;40 hs.) de este lunes, personal policial<br \/>\nde la Comisar\u00eda Primera UR XIX y Secci\u00f3n Comando Radioel\u00e9ctrico<br \/>\nintervino en un accidente ocurrido en la intersecci\u00f3n de calles<br \/>\nMoreno y Eugenio Alem\u00e1n, por causas que de tratan de establecer,<br \/>\nuna motocicleta Honda Biz 125 c.c., conducida por una mujer de 47<br \/>\na\u00f1os, acompa\u00f1ada por su hija de 15 a\u00f1os, colision\u00f3 contra un<br \/>\nautom\u00f3vil Renault Sandero que se hallaba estacionado. Ambas<br \/>\nmujeres trasladadas en ambulancia al hospital local para su<br \/>\natenci\u00f3n m\u00e9dica. Se prosiguen diligencias con intervenci\u00f3n de<br \/>\nUFI N\u00ba 4 Vera.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes, alrededor de las 09:40, personal de la Comisar\u00eda Primera y del Comando Radioel\u00e9ctrico de la Unidad Regional XIX intervino en un accidente de tr\u00e1nsito ocurrido en la intersecci\u00f3n de calles Moreno y Eugenio Alem\u00e1n de la ciudad de Vera. Por causas que se tratan de establecer, una motocicleta Honda Biz 125 c.c., conducida [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,53],"tags":[],"class_list":["post-66986","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=66986"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/66987"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=66986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=66986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=66986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}