{"id":66983,"date":"2025-10-13T18:21:03","date_gmt":"2025-10-13T21:21:03","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=66983"},"modified":"2025-10-13T18:21:03","modified_gmt":"2025-10-13T21:21:03","slug":"destruiran-300-kilos-de-marihuana-16-kilos-de-cocaina-y-mas-de-3-mil-cartones-de-cigarrillos-paraguayos-en-avellaneda","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/10\/13\/destruiran-300-kilos-de-marihuana-16-kilos-de-cocaina-y-mas-de-3-mil-cartones-de-cigarrillos-paraguayos-en-avellaneda\/","title":{"rendered":"Destruir\u00e1n 300 kilos de marihuana, 16 kilos de coca\u00edna y m\u00e1s de 3 mil cartones de cigarrillos paraguayos en Avellaneda"},"content":{"rendered":"<p><strong>La actividad ser\u00e1 encabezada por el gobernador Maximiliano Pullaro y el juez federal Aldo Alurralde. La ministra de Seguridad de la Naci\u00f3n, Patricia Bullrich, fue invitada, pero no estar\u00e1 presente.<\/strong><\/p>\n<p>El Juzgado Federal de Reconquista inform\u00f3 que este martes 14 de octubre, a partir de las 13, se realizar\u00e1 un nuevo procedimiento de destrucci\u00f3n de material estupefaciente incautado en distintas causas judiciales tramitadas ante esa sede norte\u00f1a del fuero nacional.<\/p>\n<p>El acto se llevar\u00e1 a cabo en el Crematorio del Cementerio Municipal de la ciudad de Avellaneda y contar\u00e1 con la presencia de autoridades nacionales, provinciales y municipales, adem\u00e1s de miembros del Poder Legislativo, fuerzas de seguridad, funcionarios judiciales, medios de comunicaci\u00f3n y p\u00fablico en general.<\/p>\n<p>Esta medida forma parte de las acciones peri\u00f3dicas del juzgado a cargo del Dr. Aldo Mario Alurralde, para garantizar la correcta disposici\u00f3n final de sustancias ilegales secuestradas en el marco de causas por narcotr\u00e1fico y delitos conexos, se inform\u00f3 en la tarde del lunes.<\/p>\n<p>De la actividad donde ser\u00e1n incinerados 300 kilos de marihuana, 16 kilos de coca\u00edna y 3028 gruesas de cigarrillo participar\u00e1 el gobernador Maximiliano Pullaro, la vicegobernadora Gisela Scaglia y el intendente local Gonzalo Braidot. A pesar de haber sido invitada, la ministra de Seguridad de la Naci\u00f3n, Patricia Bullrich, no ser\u00e1 de la partida por superposici\u00f3n de actividades de su campa\u00f1a electoral a senadora en CABA por LLA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actividad ser\u00e1 encabezada por el gobernador Maximiliano Pullaro y el juez federal Aldo Alurralde. La ministra de Seguridad de la Naci\u00f3n, Patricia Bullrich, fue invitada, pero no estar\u00e1 presente. El Juzgado Federal de Reconquista inform\u00f3 que este martes 14 de octubre, a partir de las 13, se realizar\u00e1 un nuevo procedimiento de destrucci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66984,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[56],"tags":[],"class_list":["post-66983","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacados"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=66983"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/66984"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=66983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=66983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=66983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}