{"id":66975,"date":"2025-10-13T16:39:33","date_gmt":"2025-10-13T19:39:33","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=66975"},"modified":"2025-10-13T16:39:33","modified_gmt":"2025-10-13T19:39:33","slug":"la-iglesia-alerto-que-peligran-300-puestos-de-trabajo-por-el-cierre-definitivo-de-algodonera-avellaneda","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/10\/13\/la-iglesia-alerto-que-peligran-300-puestos-de-trabajo-por-el-cierre-definitivo-de-algodonera-avellaneda\/","title":{"rendered":"La Iglesia alert\u00f3 que peligran 300 puestos de trabajo por el cierre definitivo de Algodonera Avellaneda"},"content":{"rendered":"<strong>La Pastoral Social advirti\u00f3 por la desaparici\u00f3n de la fuente laboral. E hizo un llamado a evitar la zozobra de &#8220;una fuente de vida&#8221;.<\/strong>\r\n\r\n\r\n\r\nA trav\u00e9s de la Comisi\u00f3n Diocesana de Pastoral Social de la Di\u00f3cesis de Reconquista, la Iglesia norte\u00f1a advirti\u00f3 sobre &#8220;el peligro inminente del cierre definitivo de una fuente de trabajo importante para la regi\u00f3n y para 300 familias, como lo es la Algodonera Avellaneda&#8221;.\r\n\r\n \r\n\r\nEn un comunicado, la instancia eclesi\u00e1stica expres\u00f3 su &#8220;apoyo y acompa\u00f1amiento&#8221; a los trabajadores en sus esfuerzos por sostener abierta la f\u00e1brica textil. La Pastoral Social parafrase\u00f3 al Papa Le\u00f3n XIV, que al hablar de los trabajadores del mundo sostuvo que &#8220;hay muchos -hombres y mujeres- que trabajan desde la ma\u00f1ana hasta la noche, a veces recogiendo cartones o haciendo otras actividades, aunque este esfuerzo s\u00f3lo les sirva para sobrevivir y nunca para mejorar verdaderamente su vida\u201d.\r\n\r\n \r\n\r\n\u201cLa falta de trabajo es mucho m\u00e1s que la falta de una fuente de ingresos para poder vivir. El trabajo es tambi\u00e9n esto, pero es mucho, mucho m\u00e1s. Trabajando nosotros nos hacemos m\u00e1s personas, nuestra humanidad florece, los j\u00f3venes se convierten en adultos solamente trabajando&#8221;, cit\u00f3 al jefe de la grey cat\u00f3lica.\r\n\r\n \r\n\r\nAdem\u00e1s, la Comisi\u00f3n Diocesana hizo un &#8220;llamado a todos -tanto privados como al Estado- que tienen en sus manos realizar iniciativas para evitar el cierre no solo de una f\u00e1brica, sino de una fuente de vida para toda la comunidad&#8221;, y exhort\u00f3 a redoblar los esfuerzos buscando el bien de los trabajadores y el bien com\u00fan, que es el bien de todos.\r\n\r\n \r\n\r\nEnseguida, ofreci\u00f3 el espacio de la Pastoral Social Diocesana para &#8220;el di\u00e1logo y la b\u00fasqueda de caminos que permitan alcanzar una soluci\u00f3n equitativa a este drama que nos aflige&#8221;, en tanto rog\u00f3 a &#8220;Nuestra Madre, la Inmaculada Concepci\u00f3n, que desde nuestro Santuario diocesano nos acerque su protecci\u00f3n y bendici\u00f3n.\r\n\r\n \r\n<p class=\"has-large-font-size wp-block-paragraph\"><strong>Crisis terminal<\/strong><\/p>\r\n \r\n\r\nEl presente de penuria que atraviesa la textil del Grupo Vicentin muestras signos cada vez inequ\u00edvocos de un horizonte de quiebra. Sin poder reactivar la actividad industrial por motivos multicausales, como su ca\u00edda en concurso preventivo, el pasivo milmillonario, la falta de financiamiento y el contexto nacional donde las importaciones chinas act\u00faan como un certificado de defunci\u00f3n para el sector hilandero, AA enfrenta un cuello de botella que hace temer lo peor.\r\n\r\n \r\n\r\nEn la ma\u00f1ana del lunes, los trabajadores de la firma protagonizaron una caravana por las calles de Reconquista para visibilizar la problem\u00e1tica laboral que los angustia. Fuentes gremiales tomaron contacto con medios de prensa para expresar la preocupaci\u00f3n reinante por los empleos en riesgo: &#8220;Puede ser que lleguen a 350. Y, obviamente, con la expectativa de que en alg\u00fan momento se solucione si sale algo a fas\u00f3n, o si viene alguien y compra la empresa, que es algo raro porque debe mucho la empresa. Aparte, est\u00e1 en garant\u00eda en el Banco Naci\u00f3n, est\u00e1 concursada, es un tema muy complicado&#8221;.\r\n\r\n \r\n\r\nEn la audiencia convocada el 3 de octubre pasado para conocer de parte del directorio el cuadro de situaci\u00f3n actual, el juez del concurso Fabi\u00e1n Lorenzini fustig\u00f3 la falta de iniciativa de la patronal para intentar soluciones.\r\n\r\n \r\n\r\nEn la ocasi\u00f3n, el magistrado insisti\u00f3 con la posibilidad de que AA venda su sede administrativa de Buenos Aires, ante lo cual los directivos Dionisio Mosch\u00e9n y H\u00e9ctor Vicentin propusieron la venta o alquiler de una las desmotadoras del empresa. Al d\u00eda de hoy, no hubo novedades al respecto.\r\n\r\n \r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"text-align: left;\"><strong><span style=\"font-size: 14px; color: #ff0000;\">Carta<\/span><\/strong><\/p>\r\n\r\n<strong><span style=\"font-size: 14px; color: #ff0000;\"> <\/span><\/strong>\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong><span style=\"font-size: 14px; color: #ff0000;\">&#8220;Mientras nosotros ponemos el cuerpo d\u00eda a d\u00eda, ellos acumulan deudas con el Estado, con la EPE, con proveedores y acreedores, y con cada familia trabajadora que depende de este salario para vivir con dignidad. Han manejado el esfuerzo ajeno con soberbia y malicia, dejando a su paso una historia de promesas incumplidas y un profundo sentimiento de injusticia. Detr\u00e1s de cada m\u00e1quina parada hay una familia que sufre, un padre o una madre que no sabe qu\u00e9 decirle a sus hijos cuando pregunta si ma\u00f1ana podr\u00e1 ir a trabajar&#8221;. Extracto de una carta de un trabajador de la Algodonera Avellaneda a la sociedad.<\/span><\/strong><\/p>\r\n\r\n<\/blockquote>\r\n","protected":false},"excerpt":{"rendered":"<p>La Pastoral Social advirti\u00f3 por la desaparici\u00f3n de la fuente laboral. E hizo un llamado a evitar la zozobra de &#8220;una fuente de vida&#8221;. A trav\u00e9s de la Comisi\u00f3n Diocesana de Pastoral Social de la Di\u00f3cesis de Reconquista, la Iglesia norte\u00f1a advirti\u00f3 sobre &#8220;el peligro inminente del cierre definitivo de una fuente de trabajo importante [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[61],"tags":[],"class_list":["post-66975","post","type-post","status-publish","format-standard","has-post-thumbnail","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=66975"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/66976"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=66975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=66975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=66975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}