{"id":66866,"date":"2025-10-07T17:31:22","date_gmt":"2025-10-07T20:31:22","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=66866"},"modified":"2025-10-08T18:18:42","modified_gmt":"2025-10-08T21:18:42","slug":"seguiran-presos-los-imputados-por-robar-ganado-a-un-abogado-de-vera","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/10\/07\/seguiran-presos-los-imputados-por-robar-ganado-a-un-abogado-de-vera\/","title":{"rendered":"Seguir\u00e1n presos los imputados por robar ganado a un abogado de Vera"},"content":{"rendered":"<p><strong>El fiscal Leandro Benegas confirm\u00f3 que el juez Gustavo Olivera resolvi\u00f3 mantener la prisi\u00f3n preventiva para los tres imputados por el robo de animales vacunos ocurrido en zona rural de Vera, cuya v\u00edctima fue el abogado Cacho Thomas.<\/strong><\/p>\n<p>\u201cLa prisi\u00f3n preventiva se impuso sin plazos y el juez hab\u00eda acordado revisarla dentro de 45 d\u00edas. Lo que se hizo fue justamente esa revisi\u00f3n\u201d, explic\u00f3 Benegas.<\/p>\n<p>Durante la audiencia, la defensa solicit\u00f3 la morigeraci\u00f3n de la medida cautelar, proponiendo la libertad con restricciones para los acusados. Sin embargo, la fiscal\u00eda se opuso por considerar que \u201ca\u00fan subsisten los riesgos procesales y que el plazo de la detenci\u00f3n sigue siendo razonable\u201d.<\/p>\n<p>\u201cEl juez rechaz\u00f3 el pedido de morigeraci\u00f3n y dispuso que la medida se revise nuevamente dentro de 45 d\u00edas. La prisi\u00f3n preventiva contin\u00faa vigente sin plazos, pero se van fijando instancias de control para evaluar si aparecen elementos que modifiquen la situaci\u00f3n procesal de los imputados\u201d, a\u00f1adi\u00f3 el fiscal.<\/p>\n<p>De esta manera, <span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/infovera.com.ar\/web\/2025\/08\/15\/un-policia-y-otros-4-cuatreros-fueron-detenidos-por-el-robo-de-ganado-al-abogado-cacho-thomas\/\">continuar\u00e1n detenidos el expolic\u00eda Emanuel Pared, Luis Quintana y Juan Cruz Esquivel, mientras que otras dos mujeres -Etelvina Silva (48), dedicada al rubro carnicer\u00eda y Carmen Patricia Lugo (49)-,<\/a><\/strong><a style=\"color: #ff0000;\" href=\"https:\/\/infovera.com.ar\/web\/2025\/08\/15\/un-policia-y-otros-4-cuatreros-fueron-detenidos-por-el-robo-de-ganado-al-abogado-cacho-thomas\/\"><span style=\"color: #800000;\"> t<\/span><\/a><\/span><span style=\"color: #800000;\">a<\/span>mbi\u00e9n vinculadas a la causa, permanecer\u00e1n en libertad bajo restricciones.<\/p>\n<p>El caso, que en su momento fue investigado por la Secci\u00f3n 19 de la Guardia Rural \u201cLos Pumas\u201d, tuvo repercusi\u00f3n en la regi\u00f3n tras el operativo en el que los sospechosos fueron sorprendidos en flagrancia mientras sustra\u00edan los animales.<\/p>\n<p><strong>Delitos\u00a0<\/strong><\/p>\n<p>En la tarde noche del martes 20d e agosto, el fiscal Carlos Koguc imput\u00f3 a Luis Daniel Quintana, Juan Cruz Esquivel, Etelvina Silva, Carmen Patricia Lugo y Emanuel Jes\u00fas Pared (exfuncionario policial) por dos episodios de abigeato ocurridos en zona rural de la ciudad de Vera, en perjuicio del productor Julio Dante Thomas. La audiencia estuvo presidida por el juez Sergio Olivera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fiscal Leandro Benegas confirm\u00f3 que el juez Gustavo Olivera resolvi\u00f3 mantener la prisi\u00f3n preventiva para los tres imputados por el robo de animales vacunos ocurrido en zona rural de Vera, cuya v\u00edctima fue el abogado Cacho Thomas. \u201cLa prisi\u00f3n preventiva se impuso sin plazos y el juez hab\u00eda acordado revisarla dentro de 45 d\u00edas. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":65547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,53],"tags":[],"class_list":["post-66866","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=66866"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/65547"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=66866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=66866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=66866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}