{"id":66423,"date":"2025-09-21T17:02:49","date_gmt":"2025-09-21T20:02:49","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=66423"},"modified":"2025-09-23T11:00:56","modified_gmt":"2025-09-23T14:00:56","slug":"piden-ayuda-a-la-comunidad-para-recuperar-un-apero-robado-a-un-chico-en-el-aeroclub","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/09\/21\/piden-ayuda-a-la-comunidad-para-recuperar-un-apero-robado-a-un-chico-en-el-aeroclub\/","title":{"rendered":"Piden ayuda a la comunidad para recuperar un apero robado a un chico en el Aeroclub"},"content":{"rendered":"<p><strong>Se trata de Mateo Moreira.\u00a0<\/strong><\/p>\n<p>Un familiar del Mateo Moreira realiz\u00f3 un pedido de &#8220;solidaridad y un poco de empat\u00eda&#8221; para poder recuperar el apero que le sustrajeron en la noche del s\u00e1bado.<\/p>\n<p>&#8220;Anoche sustrajeron del Aeroclub el apero (pilchas) a Mateo Moreira, un nene de a penas 13 a\u00f1os, que se estaba divirtiendo en una fiesta de 15 y se tomaron el atrevimiento de llevarse sus pertenec\u00edas dej\u00e1ndolo desesperado y en llanto por sus herramientas utilitarias&#8221;, cont\u00f3 a <strong>InfoVera<\/strong> una t\u00eda de la v\u00edctima.<\/p>\n<p>&#8220;Solicito por favor a cada vecino y amigo de nuestro Vera que se solidaricen, el nene trabaja en el campo y adem\u00e1s de eso participa en fiesta de destrezas y dem\u00e1s eventos&#8221;, agreg\u00f3.<\/p>\n<p><strong>La mujer dijo que se agradece cualquier informaci\u00f3n que ayude a recuperar el apero, y dej\u00f3 tres tel\u00e9fonos para aportar datos: 3483453915 Mateo Moreira; 3483525100 del pap\u00e1; y 3483445778 de ella.<\/strong><\/p>\n<p>Seg\u00fan explic\u00f3, la fiesta ten\u00eda como consigna que los invitados que pod\u00edan asistieron vestidos de gauchos. As\u00ed concurri\u00f3 Mateo, que adem\u00e1s vive en el barrio lindante al club y que cerca de las 22 advirti\u00f3, para su pesar, que amigos de lo ajeno le hab\u00edan robado sus pertenencias.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de Mateo Moreira.\u00a0 Un familiar del Mateo Moreira realiz\u00f3 un pedido de &#8220;solidaridad y un poco de empat\u00eda&#8221; para poder recuperar el apero que le sustrajeron en la noche del s\u00e1bado. &#8220;Anoche sustrajeron del Aeroclub el apero (pilchas) a Mateo Moreira, un nene de a penas 13 a\u00f1os, que se estaba divirtiendo en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":{"0":"post-66423","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-vera"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=66423"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/66423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/66424"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=66423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=66423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=66423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}