{"id":65855,"date":"2025-08-29T14:21:54","date_gmt":"2025-08-29T17:21:54","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=65855"},"modified":"2025-08-29T14:21:54","modified_gmt":"2025-08-29T17:21:54","slug":"siete-personas-fueron-detenidas-en-allanamientos-por-microtrafico-realizados-en-san-javier","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/08\/29\/siete-personas-fueron-detenidas-en-allanamientos-por-microtrafico-realizados-en-san-javier\/","title":{"rendered":"Siete personas fueron detenidas en allanamientos por microtr\u00e1fico realizados en San Javier"},"content":{"rendered":"<p><strong>Seis hombres y una mujer fueron detenidos esta madrugada en el marco de cuatro allanamientos por microtr\u00e1fico llevados a cabo en viviendas del barrio Los Reubicados de la ciudad de San Javier (departamento San Javier)<\/strong><\/p>\n<p>Las diligencias fueron realizadas en el marco de un legajo penal que dirige el fiscal Guillermo Persello\u00a0de la Fiscal\u00eda Regional 1 del MPA.\u00a0La investigaci\u00f3n, que se\u00a0enmarca en los Objetivos Priorizados del Plan de Persecuci\u00f3n Penal de la Fiscal\u00eda General del MPA,\u00a0comenz\u00f3 en marzo del a\u00f1o pasado a ra\u00edz de reiterados hechos il\u00edcitos que se registraron en la zona en la que se hicieron los allanamientos de las primeras horas de hoy.<\/p>\n<p>Adem\u00e1s de la detenci\u00f3n de las siete personas, se secuestr\u00f3 coca\u00edna fraccionada y preparada para su venta al por menor en envoltorios de nylon; tel\u00e9fonos celulares; un postnet; dinero en efectivo; dos picadores de metal; una bolsa con bicabornato y recortes de papel con anotaciones de inter\u00e9s para la investigaci\u00f3n.<\/p>\n<p>Las diligencias de esta madrugada fueron llevadas a cabo\u00a0por personal de la Polic\u00eda de Investigaciones (PDI),\u00a0Distrito San Javier.<\/p>\n<p>El pr\u00f3ximo lunes, el fiscal Persello imputar\u00e1 a los siete detenidos\u00a0en una audiencia a realizarse en los tribunales de la ciudad de Santa Fe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seis hombres y una mujer fueron detenidos esta madrugada en el marco de cuatro allanamientos por microtr\u00e1fico llevados a cabo en viviendas del barrio Los Reubicados de la ciudad de San Javier (departamento San Javier) Las diligencias fueron realizadas en el marco de un legajo penal que dirige el fiscal Guillermo Persello\u00a0de la Fiscal\u00eda Regional [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":65856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,61],"tags":[],"class_list":["post-65855","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=65855"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/65856"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=65855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=65855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=65855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}