{"id":65742,"date":"2025-08-25T18:42:12","date_gmt":"2025-08-25T21:42:12","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=65742"},"modified":"2025-08-25T18:44:04","modified_gmt":"2025-08-25T21:44:04","slug":"cierre-por-balance-en-la-uaa","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/08\/25\/cierre-por-balance-en-la-uaa\/","title":{"rendered":"Cierre por balance en la UAA"},"content":{"rendered":"<p><strong>La Uni\u00f3n Agr\u00edcola de Avellaneda Coop. Ltda. informa a sus asociados, clientes y comunidad en general que, en el marco del cierre de ejercicio 2024\/2025<\/strong>, se llevar\u00e1n a cabo las tareas relacionadas al balance en las distintas sucursales y unidades de negocio de la Cooperativa. Por tal motivo, compartimos el cronograma previsto con los d\u00edas y horarios de cierre correspondientes en cada punto de atenci\u00f3n.<\/p>\n<p>Agradecemos la comprensi\u00f3n de asociados y clientes ante las modificaciones en la atenci\u00f3n durante este per\u00edodo.<\/p>\n<p>Uni\u00f3n Agr\u00edcola de Avellaneda Coop. Ltda.<\/p>\n<p><a href=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2025\/08\/u1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-65747\" src=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2025\/08\/u1.jpg\" alt=\"\" width=\"720\" height=\"1280\" srcset=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2025\/08\/u1.jpg 720w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2025\/08\/u1-696x1237.jpg 696w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2025\/08\/u1-236x420.jpg 236w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Agr\u00edcola de Avellaneda Coop. Ltda. informa a sus asociados, clientes y comunidad en general que, en el marco del cierre de ejercicio 2024\/2025, se llevar\u00e1n a cabo las tareas relacionadas al balance en las distintas sucursales y unidades de negocio de la Cooperativa. Por tal motivo, compartimos el cronograma previsto con los d\u00edas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":65743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[49,61],"tags":[],"class_list":["post-65742","post","type-post","status-publish","format-standard","has-post-thumbnail","category-empresariales","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=65742"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/65743"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=65742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=65742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=65742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}