{"id":65691,"date":"2025-08-25T13:03:22","date_gmt":"2025-08-25T16:03:22","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=65691"},"modified":"2025-08-26T11:03:11","modified_gmt":"2025-08-26T14:03:11","slug":"municipales-paran-24-hs-esta-semana-y-48-hs-la-proxima","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/08\/25\/municipales-paran-24-hs-esta-semana-y-48-hs-la-proxima\/","title":{"rendered":"Municipales paran 24 hs esta semana y 48 hs la pr\u00f3xima"},"content":{"rendered":"<p><strong>El Plenario de FESTRAM determin\u00f3 dos paros: 24 horas para esta semana y 48 horas para la pr\u00f3xima.<\/strong><\/p>\n<p>En el d\u00eda de la fecha se realiz\u00f3 el Plenario de Secretarios\/as Generales de FESTRAM a fin de resolver con la totalidad de los representantes de Sindicatos de base sobre el esquema salarial ofrecido por los de Intendentes y Presidentes Comunales en la mesa paritaria.<\/p>\n<p>Fue rechazada la propuesta salarial y se dispuso un Plan de Lucha consistente en un paro total de actividades de 24 horas para el pr\u00f3ximo viernes 29 de agosto, y un paro total de actividades de 48 horas, con movilizaciones, para los d\u00edas jueves 4 y viernes 5 de setiembre, cuya modalidad ser\u00e1 resuelta por cada Sindicato en su jurisdicci\u00f3n.<\/p>\n<p>El Plenario tambi\u00e9n resolvi\u00f3 facultar a los representantes paritarios de FESTRAM para continuar las negociaciones, mientras esperan una nueva convocatoria.<\/p>\n<p><strong>Las autoridades de Municipios y Comunas hab\u00edan trasladado una propuesta salarial por el plazo de 6 meses, con un porcentaje total de 7%, distribuido en 1,5 % en julio, 1,5% en agosto, 1% en septiembre, 1% en octubre, 1% en noviembre y 1% en diciembre.<\/strong><\/p>\n<p>FESTRAM adelant\u00f3 que continuar\u00e1 con los reclamos por &#8220;la falta de pago al sector pasivo de las anteriores actas paritarias2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Plenario de FESTRAM determin\u00f3 dos paros: 24 horas para esta semana y 48 horas para la pr\u00f3xima. En el d\u00eda de la fecha se realiz\u00f3 el Plenario de Secretarios\/as Generales de FESTRAM a fin de resolver con la totalidad de los representantes de Sindicatos de base sobre el esquema salarial ofrecido por los de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":65693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[27,60],"tags":[],"class_list":["post-65691","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gremiales","category-provinciales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=65691"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/65693"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=65691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=65691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=65691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}