{"id":65681,"date":"2025-08-24T19:05:53","date_gmt":"2025-08-24T22:05:53","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=65681"},"modified":"2025-08-25T17:57:10","modified_gmt":"2025-08-25T20:57:10","slug":"un-penal-le-dio-la-victoria-a-ferro-que-saco-ventaja-y-ahora-definira-de-local","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/08\/24\/un-penal-le-dio-la-victoria-a-ferro-que-saco-ventaja-y-ahora-definira-de-local\/","title":{"rendered":"Un penal le dio la victoria a Ferro que sac\u00f3 ventaja y ahora definir\u00e1 de local"},"content":{"rendered":"<p>Se jug\u00f3 la ida en la final del Torneo Apertura de la Liga Verense.<\/p>\n<p>Bajo un gran marco de p\u00fablico, en su casa, el CAFO cay\u00f3 1 a 0 ante Ferro de Vera, en un partido intenso, donde al Verde no le sali\u00f3 lo que ten\u00eda previsto, pero de igual manera dej\u00f3 todo en la cancha y nunca baj\u00f3 los brazos.<\/p>\n<p>El resultado se defini\u00f3 por detalles: un penal en contra que fue convertido por Alejandro Vel\u00e1zquez, y la falta de eficacia desde los doce pasos de Bautista Brunello.<\/p>\n<p>Cap\u00edtulo aparte lo de Alexis Pati Imhoff, que vio la roja y complic\u00f3 al equipo local en el tramo final.<\/p>\n<p>El desarrollo del encuentro mostr\u00f3 al CAFO con intenciones claras de protagonismo territorial, aunque sin la precisi\u00f3n necesaria en la zona de gestaci\u00f3n. El equipo intent\u00f3 sostener la posesi\u00f3n en campo rival, pero careci\u00f3 de sincron\u00eda en los \u00faltimos metros, lo que deriv\u00f3 en ataques con finalizaci\u00f3n apresurada o sin suficiente peso ofensivo.<\/p>\n<p>El tr\u00e1mite se abri\u00f3 en una acci\u00f3n aislada, producto de una desatenci\u00f3n en la cobertura interior que termin\u00f3 con infracci\u00f3n dentro del \u00e1rea. El penal ejecutado por Vel\u00e1zquez signific\u00f3 el \u00fanico tanto del partido. Desde all\u00ed, el conjunto fortinero busc\u00f3 variantes, ensanchando el campo con amplitud por las bandas y tratando de filtrar pases entre l\u00edneas, aunque sin concretar en el arco contrario.<\/p>\n<p>La situaci\u00f3n m\u00e1s clara para equilibrar el marcador lleg\u00f3 tambi\u00e9n desde los doce pasos, pero la ejecuci\u00f3n careci\u00f3 de eficacia, lo que prolong\u00f3 la ventaja adversaria. En el cierre, El Fort\u00edn acumul\u00f3 volumen ofensivo con centros frontales y presencia en zona de rebote, pero sin la contundencia necesaria para modificar el resultado.<\/p>\n<p>La terna arbitral de buen desempe\u00f1o, estuvo conformada por Mauricio Montiel, los asistentes Mariano Altamirano y Alejandro Almir\u00f3n, m\u00e1s Hugo Moreyra como cuarto \u00e1rbitro.<\/p>\n<p>Fuente: FM Vida Fort\u00edn Olmos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se jug\u00f3 la ida en la final del Torneo Apertura de la Liga Verense. Bajo un gran marco de p\u00fablico, en su casa, el CAFO cay\u00f3 1 a 0 ante Ferro de Vera, en un partido intenso, donde al Verde no le sali\u00f3 lo que ten\u00eda previsto, pero de igual manera dej\u00f3 todo en la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":65683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[31,53],"tags":[],"class_list":["post-65681","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=65681"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/65681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/65683"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=65681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=65681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=65681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}