{"id":64958,"date":"2025-07-29T19:42:44","date_gmt":"2025-07-29T22:42:44","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=64958"},"modified":"2025-07-29T19:43:00","modified_gmt":"2025-07-29T22:43:00","slug":"provincia-mantuvo-un-nuevo-encuentro-paritario-con-los-gremios-de-la-administracion-publica-central","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/07\/29\/provincia-mantuvo-un-nuevo-encuentro-paritario-con-los-gremios-de-la-administracion-publica-central\/","title":{"rendered":"Provincia mantuvo un nuevo encuentro paritario con los gremios de la Administraci\u00f3n P\u00fablica Central"},"content":{"rendered":"<p><strong>Este martes se realiz\u00f3 una nueva reuni\u00f3n de la paritaria docente entre el Gobierno de la Provincia y los gremios del sector. El encuentro se desarroll\u00f3 en un marco de di\u00e1logo abierto, y las partes acordaron volver a reunirse el martes de la semana pr\u00f3xima. Desde el Ejecutivo se present\u00f3 un diagn\u00f3stico de la situaci\u00f3n salarial, se expusieron los datos de la evoluci\u00f3n de los ingresos provinciales y se reafirm\u00f3 el compromiso con la mejora del sistema educativo, con foco en los aprendizajes.<\/strong><\/p>\n<p>El ministro de Econom\u00eda, Pablo Olivares, calific\u00f3 la reuni\u00f3n como \u201cfruct\u00edfera\u201d y sostuvo que el Ejecutivo \u201ccumple con lo comprometido en cada paritaria, que es volver a la mesa de di\u00e1logo una vez finalizado el per\u00edodo de vigencia del acuerdo salarial\u201d. En esa l\u00ednea, se\u00f1al\u00f3 que \u201cen el segundo trimestre los aumentos salariales de bolsillo, incluyendo el m\u00ednimo garantizado, colocaron a todos los cargos testigos por encima de la inflaci\u00f3n\u201d.<\/p>\n<p>\u201cLa realidad termin\u00f3 convalidando lo que hab\u00edamos anticipado: el incremento que se otorg\u00f3 para el segundo trimestre, del 8 % m\u00e1s el m\u00ednimo garantizado, super\u00f3 la inflaci\u00f3n del per\u00edodo. Eso nos da fundamentos objetivos para discutir c\u00f3mo avanzar\u201d, asegur\u00f3.<\/p>\n<p>Adem\u00e1s, Olivares destac\u00f3 que durante el encuentro tambi\u00e9n se comparti\u00f3 informaci\u00f3n detallada sobre la situaci\u00f3n de las finanzas provinciales: \u201cHicimos una exposici\u00f3n sobre c\u00f3mo fueron los ingresos y egresos del primer semestre, y cu\u00e1les son las proyecciones para la segunda mitad del a\u00f1o. En base a eso, expresamos la voluntad del Gobierno de construir una nueva propuesta, responsable y sostenible\u201d.<\/p>\n<p><strong>Foco en los aprendizajes<\/strong><\/p>\n<p>Por su parte, el ministro de Educaci\u00f3n, Jos\u00e9 Goity, enfatiz\u00f3 que \u201cla prioridad de esta gesti\u00f3n es garantizar los aprendizajes\u201d y que \u201cla pol\u00edtica educativa no puede quedar condicionada por l\u00f3gicas sectoriales\u201d. En ese sentido, afirm\u00f3: \u201cTenemos una responsabilidad como Gobierno, que es conducir el sistema educativo, y eso implica plantear pol\u00edticas orientadas a la mejora de los aprendizajes. Estoy orgulloso del compromiso de los docentes en el aula, pero muchas veces la agenda gremial no refleja ese compromiso cotidiano\u201d.<\/p>\n<p>Goity tambi\u00e9n defendi\u00f3 la continuidad del reconocimiento por asistencia, una pol\u00edtica que, seg\u00fan detall\u00f3, beneficia al 80 % del cuerpo docente: \u201cLa diferencia en la educaci\u00f3n la hace el docente en el aula. Por eso, premiar la regularidad es una forma de cuidar la calidad. Esta pol\u00edtica de incentivo no se aplica en otros sectores de la administraci\u00f3n p\u00fablica. Lo hacemos porque creemos que los aprendizajes son el eje central de nuestra gesti\u00f3n educativa\u201d.<\/p>\n<p>El Gobierno tambi\u00e9n destac\u00f3 la inversi\u00f3n en infraestructura escolar que se est\u00e1 llevando adelante en todo el territorio provincial. \u201cEstamos interviniendo en cientos de escuelas. No es lo mismo ense\u00f1ar en un edificio con filtraciones que en uno en condiciones. Falta mucho, pero estamos trabajando para mejorar las condiciones de trabajo y de aprendizaje\u201d, concluyeron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes se realiz\u00f3 una nueva reuni\u00f3n de la paritaria docente entre el Gobierno de la Provincia y los gremios del sector. El encuentro se desarroll\u00f3 en un marco de di\u00e1logo abierto, y las partes acordaron volver a reunirse el martes de la semana pr\u00f3xima. Desde el Ejecutivo se present\u00f3 un diagn\u00f3stico de la situaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":64959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-64958","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-provinciales"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/64958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=64958"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/64958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/64959"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=64958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=64958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=64958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}