{"id":64470,"date":"2025-07-13T19:24:29","date_gmt":"2025-07-13T22:24:29","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=64470"},"modified":"2025-07-14T12:41:45","modified_gmt":"2025-07-14T15:41:45","slug":"calchaqui-dos-jovenes-heridos-tras-una-violenta-pelea-familiar","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/07\/13\/calchaqui-dos-jovenes-heridos-tras-una-violenta-pelea-familiar\/","title":{"rendered":"Calchaqu\u00ed: dos j\u00f3venes heridos tras una violenta pelea familiar"},"content":{"rendered":"<p>Personal de la Comisar\u00eda 2da. de Calchaqu\u00ed intervino el viernes 12 de julio cerca de las 22 tras ser alertado por una mujer sobre una gresca en su vivienda.<\/p>\n<p>Al llegar, los efectivos constataron que dos j\u00f3venes, ambos mayores de edad, se hab\u00edan agredido mutuamente con elementos punzocortantes.<\/p>\n<p>Ambos fueron trasladados en ambulancia al Hospital local para recibir atenci\u00f3n m\u00e9dica.<\/p>\n<p>Adem\u00e1s, se procedi\u00f3 al secuestro preventivo de objetos de inter\u00e9s para la investigaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal de la Comisar\u00eda 2da. de Calchaqu\u00ed intervino el viernes 12 de julio cerca de las 22 tras ser alertado por una mujer sobre una gresca en su vivienda. Al llegar, los efectivos constataron que dos j\u00f3venes, ambos mayores de edad, se hab\u00edan agredido mutuamente con elementos punzocortantes. Ambos fueron trasladados en ambulancia al Hospital [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":41145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[52,30],"tags":[],"class_list":["post-64470","post","type-post","status-publish","format-standard","has-post-thumbnail","category-calchaqui","category-policiales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/64470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=64470"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/64470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/41145"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=64470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=64470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=64470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}