{"id":64328,"date":"2025-07-06T14:38:43","date_gmt":"2025-07-06T17:38:43","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=64328"},"modified":"2025-07-06T14:38:43","modified_gmt":"2025-07-06T17:38:43","slug":"campo-hardy-impactante-choque-de-camiones","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/07\/06\/campo-hardy-impactante-choque-de-camiones\/","title":{"rendered":"Campo Hardy: impactante choque de camiones"},"content":{"rendered":"<p><strong>Nuevamente la Ruta Nacional 11 como escenario de un siniestro vial de grandes proporciones.<\/strong><\/p>\n<p>En la tarde de este s\u00e1bado 5 de julio se produjo un violento choque entre dos camiones sobre Ruta nacional N\u00b011 Km 914 a la altura de Campo Hardy. Los veh\u00edculos involucrados fueron un cami\u00f3n de YPF y otro cami\u00f3n de la empresa Andreani.<\/p>\n<p>Si bien no hubo lesionados, se reportaron importantes da\u00f1os materiales e inconvenientes en el tr\u00e1nsito, ya que los dos camiones quedaron sobre la ruta. Los veh\u00edculos involucrados fueron un cami\u00f3n Volvo con tanque que tiene inscripciones de la empresa YPF, dominio AF762UK, con cisterna AF623QK, conducido por Miguel \u00c1ngel Francini, de 38 a\u00f1os, domiciliado en Barranqueras, Chaco; y un cami\u00f3n Volvo de la empresa Andreani, dominio ODT 454, con semirremolque AB451OR, conducido por Fabi\u00e1n Marcelo Oga, de 50 a\u00f1os, oriundo de Santa Mar\u00eda, C\u00f3rdoba.<\/p>\n<p>El informe policial indica que Francini circulaba rumbo al Sur, cuando el cami\u00f3n de Andreani, que ven\u00eda en sentido contrario, perdi\u00f3 el control y cruz\u00f3 de carril, provocando la colisi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevamente la Ruta Nacional 11 como escenario de un siniestro vial de grandes proporciones. En la tarde de este s\u00e1bado 5 de julio se produjo un violento choque entre dos camiones sobre Ruta nacional N\u00b011 Km 914 a la altura de Campo Hardy. Los veh\u00edculos involucrados fueron un cami\u00f3n de YPF y otro cami\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":64329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,61],"tags":[],"class_list":["post-64328","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/64328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=64328"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/64328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/64329"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=64328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=64328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=64328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}