{"id":63224,"date":"2025-05-27T14:50:29","date_gmt":"2025-05-27T17:50:29","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=63224"},"modified":"2025-05-27T14:50:29","modified_gmt":"2025-05-27T17:50:29","slug":"quedan-tres-zonas-con-problemas-de-escurrimiento-dijo-la-intendenta-mitre","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/05\/27\/quedan-tres-zonas-con-problemas-de-escurrimiento-dijo-la-intendenta-mitre\/","title":{"rendered":"&#8220;Quedan tres zonas con problemas de escurrimiento&#8221;, dijo la intendenta Mitre"},"content":{"rendered":"<p><strong>Se trata de Santa Rosa, Hospital y Mart\u00edn Fierro. La mandataria de la ciudad del norte santafesino actualiz\u00f3 el estado de situaci\u00f3n de la ciudad afectada por m\u00e1s de 400 mil\u00edmetros. Quedan 120 evacuados.<\/strong><\/p>\n<p>En los barrios Santa Rosa, Mart\u00edn Fierro y Hospital de la\u00a0ciudad de Vera, cabecera departamental, a\u00fan permanec\u00eda el agua en las viviendas y la Direcci\u00f3n de Recursos H\u00eddricos evaluaba la posibilidad de realizar alguna intervenci\u00f3n para agilizar el escurrimiento del agua.<\/p>\n<p>Seg\u00fan se inform\u00f3,\u00a0en el resto de la ciudad todo tend\u00eda a normalizarse durante la siesta de este martes, aunque hubo negocios que no abrieron y las escuelas tampoco dictaron clases.<\/p>\n<p>La intendenta Vera, junto al ministro Enrico y otros funcionarios provinciales, detallaron la situaci\u00f3n en la ciudad norte\u00f1a. Foto: Manuel Mudry<br \/>\nLos equipos t\u00e9cnicos y pol\u00edticos locales que conforman la Comisi\u00f3n de Protecci\u00f3n Civil act\u00faan coordinadamente para asistir a los damnificados y mantener la situaci\u00f3n bajo control.<\/p>\n<p>La intendente Mitre se\u00f1al\u00f3 que\u00a0se estaban distribuyendo unas 1.200 viandas entre los comedores municipales y el de San Mart\u00edn de Porres, ubicados en la periferia de la ciudad.<\/p>\n<p>Por \u00faltimo, la funcionaria destac\u00f3 la solidaridad de localidades vecinas traducida en la presencia de bomberos de Avellaneda, Reconquista, Malabrigo, Romang, Calchaqu\u00ed y Tostado, que se sumaron al operativo.<\/p>\n<p>Letyana Press<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de Santa Rosa, Hospital y Mart\u00edn Fierro. La mandataria de la ciudad del norte santafesino actualiz\u00f3 el estado de situaci\u00f3n de la ciudad afectada por m\u00e1s de 400 mil\u00edmetros. Quedan 120 evacuados. En los barrios Santa Rosa, Mart\u00edn Fierro y Hospital de la\u00a0ciudad de Vera, cabecera departamental, a\u00fan permanec\u00eda el agua en las [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":63225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-63224","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/63224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=63224"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/63224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/63225"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=63224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=63224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=63224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}