{"id":63110,"date":"2025-05-23T12:17:12","date_gmt":"2025-05-23T15:17:12","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=63110"},"modified":"2025-05-24T14:25:41","modified_gmt":"2025-05-24T17:25:41","slug":"semana-de-actividades-y-trabajos-en-la-gallareta","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2025\/05\/23\/semana-de-actividades-y-trabajos-en-la-gallareta\/","title":{"rendered":"Semana de actividades y trabajos en La Gallareta"},"content":{"rendered":"<p>As\u00ed lo inform\u00f3 la Comuna:<\/p>\n<p>Con mucho orgullo y satisfacci\u00f3n, compartimos con ustedes lo siguiente:<\/p>\n<p>Se est\u00e1 por concretar la obra en el Barrio Itat\u00ed. Con un circuito de 5 cuadras entre ripio y cord\u00f3n cuneta.<\/p>\n<p>Si el tiempo acompa\u00f1a, la semana entrante se terminar\u00e1 la misma. Este trabajo transformar\u00e1 la calidad de vida de todos los vecinos.<\/p>\n<p>Parte de la gesti\u00f3n, celebr\u00f3 los 20 a\u00f1os del Hogar &#8220;Viejo Pav\u00f3n&#8221;, junto al personal y residentes de la misma. Felicitando y agradeciendo por su entrega y dedicaci\u00f3n.<\/p>\n<p>Se comenzar\u00e1 en 6 cuadras, con la colocaci\u00f3n de 24 jirafas, sobre la calle Pellegrini hasta Bol\u00edvar.<\/p>\n<p>Se ripiar\u00e1 una cuadra m\u00e1s, sobre calle Mitre, que conecta con Bolivar. (Para completar el circuito).<\/p>\n<p>Contin\u00faan los trabajos de mantenimiento en espacios verdes.<\/p>\n<p>Limpieza y orden en el ejido urbano.<\/p>\n<p>Comuna de La Gallareta, agradece a sus operarios por llevar a cabo de manera responsable y efectiva, los trabajos de todos los d\u00edas. Su desempe\u00f1o es digno de admirar y felicitar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo inform\u00f3 la Comuna: Con mucho orgullo y satisfacci\u00f3n, compartimos con ustedes lo siguiente: Se est\u00e1 por concretar la obra en el Barrio Itat\u00ed. Con un circuito de 5 cuadras entre ripio y cord\u00f3n cuneta. Si el tiempo acompa\u00f1a, la semana entrante se terminar\u00e1 la misma. Este trabajo transformar\u00e1 la calidad de vida de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":63111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":["post-63110","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/63110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=63110"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/63110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/63111"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=63110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=63110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=63110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}