{"id":55668,"date":"2024-10-06T19:05:23","date_gmt":"2024-10-06T22:05:23","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=55668"},"modified":"2024-10-07T18:37:43","modified_gmt":"2024-10-07T21:37:43","slug":"el-gobierno-nacional-anuncio-la-desregulacion-del-transporte-automotor-de-media-y-larga-distancia","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/10\/06\/el-gobierno-nacional-anuncio-la-desregulacion-del-transporte-automotor-de-media-y-larga-distancia\/","title":{"rendered":"El gobierno nacional anunci\u00f3 la desregulaci\u00f3n del transporte automotor de media y larga distancia"},"content":{"rendered":"<p>A trav\u00e9s de un decreto que se publicar\u00e1 el lunes en el Bolet\u00edn Oficial crear\u00e1 un Registro Nacional de Transporte de Pasajeros p\u00fablico, online y gratuito. El nuevo sistema empezar\u00e1 a implementarse en 60 d\u00edas. No habr\u00e1 cambios en las reglas de seguridad. Con m\u00e1s competencia, apuntan a reducir los costos de transporte<\/p>\n<p>El gobierno nacional publicar\u00e1 este lunes en el Bolet\u00edn Oficial el decreto de desregulaci\u00f3n de media y larga distancia, anunciaron desde el Ministerio de Desregulaci\u00f3n y Transformaci\u00f3n del Estado, que encabeza el economista Federico Sturzenegger. A grandes rasgos, implicar\u00e1 que deje de ser considerado servicio p\u00fablico y, con esa medida, las firmas del sector tendr\u00e1n menos restricciones para establecer precios, modificar o discontinuar rutas que no sean rentables y permitir\u00eda el ingreso de nuevas compa\u00f1\u00edas al sistema.<\/p>\n<p>La medida, dijeron desde la cartera desregulatoria, que impuls\u00f3 esta medida junto a la Secretar\u00eda de Transporte del Ministerio de Econom\u00eda, a cargo de Franco Mogetta, generar\u00e1 beneficios para todos los actores del sector.<\/p>\n<p>Entre ellos se menciona la creaci\u00f3n de un nuevo Registro Nacional del Transporte de pasajeros, el libre establecimiento de recorridos, horarios, precios y duraci\u00f3n de los servicios por parte de los transportistas. Con esa medida y el decreto desregulatorio el gobierno reemplazar\u00e1 una norma con m\u00e1s de 30 a\u00f1os de antig\u00fcedad.<\/p>\n<p>El objetivo, se\u00f1al\u00f3 la cartera desregulatoria, \u201ces la liberalizaci\u00f3n, modernizaci\u00f3n y desregulaci\u00f3n del transporte automotor de pasajeros y su adaptaci\u00f3n a la din\u00e1mica de transporte actual\u201d.<\/p>\n<p><strong>P\u00fablico, gratuito y online<\/strong><\/p>\n<p>El Registro Nacional del Transporte de pasajeros ser\u00e1 de acceso p\u00fablico, sin costo y online, \u201cpara una mayor comodidad del transportista, el ahorro de tiempo en la gesti\u00f3n de tr\u00e1mites burocr\u00e1ticos y una mayor transparencia\u201d, se\u00f1al\u00f3 una comunicaci\u00f3n oficial.<\/p>\n<p>Las empresas y transportistas que ya estaban registradas no tendr\u00e1n que hacerlo nuevamente. En cambio, s\u00ed deber\u00e1n registrarse las empresas nuevas.<\/p>\n<p>Estas, una vez inscriptas, \u201cobtendr\u00e1n de manera autom\u00e1tica la habilitaci\u00f3n para operar luego de 5 d\u00edas post inscripci\u00f3n, aplicando de esta forma la nueva metodolog\u00eda de \u201cSilencio Positivo\u201d ya implementada por el Ministerio de Desregulaci\u00f3n y Transformaci\u00f3n del Estado que inici\u00f3 la cartera de Sturzenegger.<\/p>\n<p>Esto significa que, pasados los cinco d\u00edas y vencido el plazo administrativo del tr\u00e1mite, la inscripci\u00f3n ser\u00e1 concedida y autorizada. Esto es a fin, dijeron, de \u201cagilizar el procedimiento y no perjudicar al usuario\u201d.<\/p>\n<p>De todos modos, y probablemente buscando anticiparse a cr\u00edticas que seguramente surgir\u00e1n desde \u00e1mbitos pol\u00edticos y tambi\u00e9n empresarios, el mensaje oficial que se mantienen y mantendr\u00e1n \u201clas exigencias en materia de seguridad ya establecidas en la normativa vigente\u201d.<\/p>\n<p>La liberalizaci\u00f3n y desregulaci\u00f3n implica que a partir de la nueva normativa a oficializarse este lunes, \u201cse podr\u00e1n establecer libremente los recorridos, veh\u00edculos, horarios, precios, duraci\u00f3n de los servicios, e incluso los puntos de ascenso y descenso de pasajeros que est\u00e9n autorizados por la jurisdicci\u00f3n local respectiva.<\/p>\n<p>Esto, se\u00f1alaron desde el Ministerio de Desregulaci\u00f3n, \u201cgenerar\u00e1 una mayor oferta de servicios y competencia de precios que beneficiar\u00e1 tanto al usuario como a las empresas y transportistas\u201d.<\/p>\n<p>Eso s\u00ed, las empresas que se inscriban deber\u00e1n informar la capacidad de transporte de que disponen, detallando cantidad y tipo de veh\u00edculo, cantidad de asientos, seguros contratados, la n\u00f3mina de conductores a asignar y la informaci\u00f3n relativa a las licencias de conducir de los mismos, la periodicidad de los servicios declarados, el origen, las paradas intermedias y el destino del viaje.<\/p>\n<p><strong>Sin Registro no hay transporte<\/strong><\/p>\n<p>La cartera de Sturzenegger aclar\u00f3 que no se podr\u00e1n ofrecer al p\u00fablico servicios que no se encuentren informados en el Registro Nacional del Transporte de pasajeros y que la autoridad de aplicaci\u00f3n de la medida ser\u00e1 la Secretar\u00eda de Transporte de la Naci\u00f3n.<\/p>\n<p>El nuevo sistema, a partir del decreto a publicarse ma\u00f1ana, empezar\u00e1 a implementarse en 60 d\u00edas, \u201ccuando se realicen las actualizaciones tecnol\u00f3gicas necesarias\u201d.<\/p>\n<p>Con la iniciativa desreguladora y el nuevo sistema, dice la comunicaci\u00f3n oficial, el Gobierno Nacional elimina trabas innecesarias, garantiza una mayor liberalizaci\u00f3n en las condiciones de prestaci\u00f3n del servicio y agiliza los tiempos administrativos, con el fin de permitir la incorporaci\u00f3n de nuevos actores al sector. Este cambio les permitir\u00e1 a los usuarios gozar, con m\u00e1s competencia, de una mayor oferta en el transporte terrestre.<\/p>\n<p><strong>C\u00e1maras y Empresas del sector<\/strong><\/p>\n<p>El sector empresario del Transporte Automotor de Pasajeros incluye varias c\u00e1maras, como la C\u00e1mara Argentina de Transporte Automotor de Pasajeros (Catap), la Celadi (C\u00e1mara Empresaria de Larga Distancia), la C\u00e1mara Empresaria del Autotransporte de Pasajeros (CEAP) y la Asociaci\u00f3n Argentina de Empresarios del Transporte Automotor (Aaeta), entre otras.<\/p>\n<p>La c\u00e1mara de mayor peso, por el n\u00famero de empresas asociadas y el n\u00famero de destinos que cubre (1.600 en todo el pa\u00eds), a lo que se suma el peso de las firmas, parece ser Celadi, cuya n\u00f3mina de socios incluye empresas como Andesmar, Balut, Cata, Chevallier, C\u00f3ndor Estrella, Crucero del Norte, El Pr\u00e1ctico, El R\u00e1pido, Flecha Bus, Plusmar, R\u00e1pido Tata y Urquiza, entre otras.<\/p>\n<p>La C\u00e1mara fue creada en 1995 y precisa en su sitio en internet que el transporte terrestre de pasajeros da cuenta del 90% del total de usuarios del transporte p\u00fablico de larga distancia, y que solo 8% lo realiza en avi\u00f3n y apenas un 2 % lo hace en tren. Adem\u00e1s, subraya, se trata del \u00fanico sistema de \u201ctransporte Federal de pasajeros\u201d del pa\u00eds, porque une localidades \u201csin la necesidad de pasar por Capital Federal, fortaleciendo las econom\u00edas regionales\u201d.<\/p>\n<p>En cambio, resalta, \u201cel avi\u00f3n o el tren en cambio, mantienen a\u00fan hoy una l\u00f3gica de embudo: Todo empieza, termina o pasa por Buenos Aires\u201d. Catap, a su vez fue fundada a mediados de 2015, y tiene un n\u00famero m\u00e1s limitado de asociados, aunque varias firmas muy conocidas por quienes se desplazan por las rutas del pa\u00eds, como Expreso Tigre Iguaz\u00fa, Autotransportes Rutamar, Etap,V\u00eda Bariloche, Rutas del Sur y Transportes Don Otto, entre otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de un decreto que se publicar\u00e1 el lunes en el Bolet\u00edn Oficial crear\u00e1 un Registro Nacional de Transporte de Pasajeros p\u00fablico, online y gratuito. El nuevo sistema empezar\u00e1 a implementarse en 60 d\u00edas. No habr\u00e1 cambios en las reglas de seguridad. Con m\u00e1s competencia, apuntan a reducir los costos de transporte El gobierno [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":28431,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[62],"tags":[],"class_list":["post-55668","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/55668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=55668"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/55668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/28431"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=55668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=55668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=55668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}