{"id":54927,"date":"2024-09-11T10:04:25","date_gmt":"2024-09-11T13:04:25","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=54927"},"modified":"2024-09-11T17:35:22","modified_gmt":"2024-09-11T20:35:22","slug":"reimpulsan-el-proyecto-de-pavimentacion-de-hipolito-irigoyen-hasta-la-ruta-11","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/09\/11\/reimpulsan-el-proyecto-de-pavimentacion-de-hipolito-irigoyen-hasta-la-ruta-11\/","title":{"rendered":"Reimpulsan el proyecto de pavimentaci\u00f3n de Hip\u00f3lito Irigoyen hasta la Ruta 11"},"content":{"rendered":"<p>La intendente, Paula Mitre present\u00f3 esta ma\u00f1ana en el Ministerio de Obras P\u00fablicas de la provincia el proyecto que contempla la finalizaci\u00f3n de la pavimentaci\u00f3n de una arteria fundamental para el acceso a la ciudad, como lo es Hip\u00f3lito Irigoyen.<\/p>\n<p>Al respecto expres\u00f3: \u201cCon la presentaci\u00f3n de este proyecto, queremos cumplir con una importante demanda de nuestros verenses, ya que esta es una arteria de acceso muy importante para el sector noreste de la ciudad y que implica un ordenamiento y descongestionamiento de los accesos actuales.<\/p>\n<p>Son 800 metros de calzada natural que esperamos pavimentar con el apoyo del gobierno provincial y sumar una obra importante m\u00e1s para nuestra ciudad que mejorar\u00e1 la calidad de vida de todos\u201d.<\/p>\n<p>Acompa\u00f1aron a la intendente la coordinadora Ejecutiva de Gobierno, Norali Vicente y el concejal Marcos Rubianes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La intendente, Paula Mitre present\u00f3 esta ma\u00f1ana en el Ministerio de Obras P\u00fablicas de la provincia el proyecto que contempla la finalizaci\u00f3n de la pavimentaci\u00f3n de una arteria fundamental para el acceso a la ciudad, como lo es Hip\u00f3lito Irigoyen. Al respecto expres\u00f3: \u201cCon la presentaci\u00f3n de este proyecto, queremos cumplir con una importante demanda [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-54927","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=54927"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/54928"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=54927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=54927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=54927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}