{"id":54908,"date":"2024-09-10T13:52:17","date_gmt":"2024-09-10T16:52:17","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=54908"},"modified":"2024-09-11T10:13:34","modified_gmt":"2024-09-11T13:13:34","slug":"acto-por-el-dia-del-maestro-en-vera","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/09\/10\/acto-por-el-dia-del-maestro-en-vera\/","title":{"rendered":"Acto por el D\u00eda del Maestro en Vera"},"content":{"rendered":"<p>Como todos los a\u00f1os, Amsafe Vera y Sadop rindieron homenaje a los maestros en un acto desarrollado en la plazoleta de la Cooperaci\u00f3n, donde est\u00e1 el Monumento al Docente.<\/p>\n<p>Estuvieron presentes el senador Osvaldo Sosa; el director de Cultura Municipal, Eduardo Perot e integrantes del CM; el subjefe de la UR XIX, Dar\u00edo Lacuadra; el director de la UP N\u00ba 10, Roberto Zupel, delegaciones escolares con sus respectivas Banderas, al igual que las fuerza de seguridad e instituciones de la ciudad.<\/p>\n<p>El izamiento de la Bandera estuvo a cargo del senador Sosa, el director de Cultura y Educaci\u00f3n del municipio, Eduardo Perot; la delegada seccional de Amsafe, Nelcy Suligoy y la representante del Sadop Santa Fe, Fabiana Mordacini.<\/p>\n<p>El di\u00e1cono Horacio Gonz\u00e1lez procedi\u00f3 a la invocaci\u00f3n religiosa, mientras que las docentes Norma Aguila y Milena Cabrera fueron las encargadas de depositar la ofrenda al pie del monumento.<\/p>\n<p>Las palabras alusivas a la fecha fueron expresadas por Alejandra Salvagiot, quien reflexion\u00f3 sobre lo que significa ser docente en la actualidad, tiempo en que \u201cense\u00f1ar no es solo transferir conocimientos, es mucho m\u00e1s, se trata de saber crear las condiciones necesarias para que los alumnos aprendan a pensar y a construir sus propios saberes\u201d.<\/p>\n<p>Dijo tambi\u00e9n que \u201cnuestra sociedad est\u00e1 transitando por momentos especialmente complejos, las familias y por lo tanto los ni\u00f1os, llevan al aula muchas demandas que deben ser atendidas particularmente y es all\u00ed donde est\u00e1 el docente con todas sus capacidades para dar respuestas\u201d.<\/p>\n<p>En esa l\u00ednea dijo que \u201cun maestro nunca dice que no puede, ya que en todo momento pone en juego toda su creatividad, su empe\u00f1o, su magia para resolver todo lo que se presente\u201d.<br \/>\n\u201cPara nosotros, los maestros, este es un d\u00eda muy especial, es un d\u00eda en el que celebramos y renovamos nuestra misi\u00f3n, nuestras esperanzas, porque si hay algo que nos caracteriza es que somos so\u00f1adores, siempre esperamos un ma\u00f1ana mejor, un futuro venturoso, ya que nunca, nunca, bajamos los brazos\u201d, remarc\u00f3, para cerrar con un deseo de feliz d\u00eda para todos los maestros.<\/p>\n<p>El acto concluy\u00f3 con el Himno a Sarmiento y la desconcentraci\u00f3n de los abanderados.<\/p>\n<p><a href=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-54910\" src=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin.jpg\" alt=\"\" width=\"1527\" height=\"1046\" srcset=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin.jpg 1527w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin-218x150.jpg 218w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin-696x477.jpg 696w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin-1068x732.jpg 1068w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin-613x420.jpg 613w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/09\/sin-100x70.jpg 100w\" sizes=\"auto, (max-width: 1527px) 100vw, 1527px\" \/><\/a><\/p>\n<p>Manuel Mudry<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como todos los a\u00f1os, Amsafe Vera y Sadop rindieron homenaje a los maestros en un acto desarrollado en la plazoleta de la Cooperaci\u00f3n, donde est\u00e1 el Monumento al Docente. Estuvieron presentes el senador Osvaldo Sosa; el director de Cultura Municipal, Eduardo Perot e integrantes del CM; el subjefe de la UR XIX, Dar\u00edo Lacuadra; el [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-54908","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=54908"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/54909"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=54908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=54908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=54908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}