{"id":54264,"date":"2024-08-17T19:28:42","date_gmt":"2024-08-17T22:28:42","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=54264"},"modified":"2024-08-18T20:47:43","modified_gmt":"2024-08-18T23:47:43","slug":"amra-solicito-la-creacion-de-la-comision-conciliadora-ante-los-poderes-judicial-y-legislativo","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/08\/17\/amra-solicito-la-creacion-de-la-comision-conciliadora-ante-los-poderes-judicial-y-legislativo\/","title":{"rendered":"AMRA solicit\u00f3 la creaci\u00f3n de la comisi\u00f3n conciliadora ante los poderes judicial y legislativo"},"content":{"rendered":"<p>Ante la falta de llamado a reuni\u00f3n paritaria por parte Ejecutivo provincial, y dado que tampoco se incluir\u00edan a los Profesionales de la Salud en el aumento que pagaba el viernes el Gobierno a todos los estatales (hayan o no aceptado la paritaria) y a todas sus autoridades, AMRA ha convocado formalmente a los presidentes de la Corte Suprema de Justicia, de la C\u00e1mara de Senadores y de la C\u00e1mara de Diputados de la Provincia a los afectos de constituir la Comisi\u00f3n Conciliadora y poner fin a la actitud claramente discriminatoria que ejerce el Poder Ejecutivo santafesino (o al menos un sector) contra los trabajadores de salud.<\/p>\n<p>AMRA expres\u00f3:<\/p>\n<p>&#8220;Queda cada vez m\u00e1s claro como superada la pandemia Covid, y sin riesgos de ning\u00fan pico de enfermedades estacionales a la vista, c\u00f3mo las y los profesionales de la salud pasamos de esenciales a prescindibles.<\/p>\n<p>Ante este panorama nos preguntamos: \u00bfQu\u00e9 importancia tiene la Salud para la actual gesti\u00f3n gubernamental? \u00bfPor qu\u00e9 no convocan a paritarias y ejercen pol\u00edticas excluyentes y autoritarias a sus trabajadores de la salud?<\/p>\n<p>A\u00a0su vez, tampoco se ha efectivizado ni uno de los pases a planta previamente acordados.<br \/>\nDe no revertirse la actual situaci\u00f3n, indefectiblemente se generar\u00e1 un recrudecimiento del conflicto a trav\u00e9s de medidas de fuerza de las cuales el \u00fanico responsable ser\u00e1 el Ejecutivo Provincial.<\/p>\n<p>\u00bfEs \u00e9sta realmente la pol\u00edtica sanitaria que quiere implementar el Gobernador cuando p\u00fablicamente declar\u00f3 que &#8220;la salud es una de sus prioridades junto a la seguridad y la educaci\u00f3n&#8221;?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante la falta de llamado a reuni\u00f3n paritaria por parte Ejecutivo provincial, y dado que tampoco se incluir\u00edan a los Profesionales de la Salud en el aumento que pagaba el viernes el Gobierno a todos los estatales (hayan o no aceptado la paritaria) y a todas sus autoridades, AMRA ha convocado formalmente a los presidentes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39817,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":["post-54264","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provinciales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=54264"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/39817"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=54264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=54264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=54264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}