{"id":54225,"date":"2024-08-15T14:31:22","date_gmt":"2024-08-15T17:31:22","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=54225"},"modified":"2024-08-16T09:24:18","modified_gmt":"2024-08-16T12:24:18","slug":"en-los-amores-pullaro-anuncio-que-las-maquinas-vuelven-a-trabajar-para-terminar-la-ruta-3","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/08\/15\/en-los-amores-pullaro-anuncio-que-las-maquinas-vuelven-a-trabajar-para-terminar-la-ruta-3\/","title":{"rendered":"Pullaro anunci\u00f3 que las m\u00e1quinas vuelven a trabajar para terminar la Ruta 3"},"content":{"rendered":"<p>El gobernador Maximiliano Pullaro, acompa\u00f1ado por los ministros de Gobierno, Fabi\u00e1n Bastia, y de Trabajo, Roald B\u00e1scolo, formul\u00f3 el anuncio en la localidad del extremo norte verense.<\/p>\n<p>El mandatario anunci\u00f3 frente a autoridades y vecinos que &#8220;nosotros quer\u00edamos venir a decirles hoy aqu\u00ed que el d\u00eda puntualmente 3 del mes que viene, el mes de septiembre, vuelven las m\u00e1quinas a trabajar para terminar con esta ruta&#8221;.<\/p>\n<p>Ante los aplausos de los presentes, Pullaro sostuvo que &#8220;vamos a terminar con esa obra tan importante que ustedes tanto pero tanto anhelaban. Y la verdad, eso es gracias al esfuerzo de todos, al esfuerzo compartido, al esfuerzo que venimos llevando adelante a la provincia de Santa Fe&#8221;.<\/p>\n<p><a href=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/08\/los-amores.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-54227\" src=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/08\/los-amores.jpg\" alt=\"\" width=\"1350\" height=\"751\" srcset=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/08\/los-amores.jpg 1350w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/08\/los-amores-696x387.jpg 696w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/08\/los-amores-1068x594.jpg 1068w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2024\/08\/los-amores-755x420.jpg 755w\" sizes=\"auto, (max-width: 1350px) 100vw, 1350px\" \/><\/a><\/p>\n<p>En su mensaje, el gobernador manifest\u00f3 que &#8220;tenemos que generar trabajo, tenemos que generar empleo, tenemos que generar crecimiento econ\u00f3mico. Ustedes son gente de trabajo y que le pone mucho esfuerzo a la vida todos los d\u00edas. Por eso quiero agradecerle al presidente comunal, al senador, a todos quienes nos acompa\u00f1an. S\u00e9 que hay un anhelo muy importante de terminar con la ruta tres&#8221;.<\/p>\n<p>En tanto, asegur\u00f3 que &#8220;la provincia de Santa Fe va a seguir creciendo, va a ser la mejor provincia de la Rep\u00fablica Argentina, pero va a ser la provincia que le marque el cambio a nuestro pa\u00eds. Un aplauso para todos ustedes&#8221;.<\/p>\n<p>A su vez, en la localidad de Ca\u00f1ada Omb\u00fa, agradeci\u00f3 a los lugare\u00f1os que los fueron a recibir y dijo que &#8220;para m\u00ed es un honor venir la primera vez como gobernador de la provincia invencible de Santa Fe aqu\u00ed, al norte del departamento Vera a Ca\u00f1ada Omb\u00fa, para decirles que vamos a trabajar junto a ustedes. Ustedes son un pueblo de gente de trabajo, de gente que quiere salir adelante pero que necesita que el Estado pueda hacer inversiones importantes, inversiones que a ustedes les permitan integrarse primero, tener infraestructura y despu\u00e9s empezar a producir, empezar a trabajar para que toda esta regi\u00f3n se pueda desarrollar y que aqu\u00ed pueda haber empleo, que pueda haber crecimiento econ\u00f3mico, que es lo que todos los santafesinos queremos&#8221;.<\/p>\n<p>En tal sentido, compar\u00f3 que &#8220;lamentablemente e algunas regiones de la provincia han tenido m\u00e1s oportunidades que otras, por el clima, por las caracter\u00edsticas, por la ubicaci\u00f3n cercana a los puertos, pero han tenido m\u00e1s desarrollo. Nosotros lo dijimos en campa\u00f1a y lo decimos en este momento, yo tambi\u00e9n soy de un pueblo muy peque\u00f1o, de un poco m\u00e1s grande que este, de 5.000 habitantes, pero de un pueblo en general y s\u00e9 las cosas que vivimos los pueblos y las diferencias que tenemos con las grandes ciudades&#8221;.<\/p>\n<p>&#8220;Sabemos que hay un sue\u00f1o de ustedes hace muchos a\u00f1os, que pelean, que piden, que gestionan, que cada uno de los vecinos, vecinas, pero funcionarios tambi\u00e9n, siempre plantean que es fundamental estar integrados y falta un tramo muy peque\u00f1o de esta ruta para poder conectarla a todo el norte, norte de la provincia de Santa Fe, y lo que le venimos a decir hoy aqu\u00ed, no quer\u00edamos dejarlo pasar, el d\u00eda 3 de septiembre las m\u00e1quinas empiezan aqu\u00ed a ponerse en funcionamiento porque la obra la vamos a terminar. Se va a unir al norte de la provincia de Santa Fe, la vamos a terminar, vamos a hacer los seis puentes que faltan y vamos a hacer el asfalto para que puedan tener la conectividad que siempre anhelaron y que siempre so\u00f1aron y vamos a trabajar juntos para que todo el norte de la provincia de Santa Fe pueda tener el desarrollo que se merece&#8221;.<\/p>\n<p>Acompa\u00f1aron el senador Osvaldo Sosa, el presidente comunal Omar Walker, la subsecretaria de Asuntos Electorales y Vinculaci\u00f3n Regional del Ministerio de Gobierno, Dra. Juliana Caillat, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Maximiliano Pullaro, acompa\u00f1ado por los ministros de Gobierno, Fabi\u00e1n Bastia, y de Trabajo, Roald B\u00e1scolo, formul\u00f3 el anuncio en la localidad del extremo norte verense. El mandatario anunci\u00f3 frente a autoridades y vecinos que &#8220;nosotros quer\u00edamos venir a decirles hoy aqu\u00ed que el d\u00eda puntualmente 3 del mes que viene, el mes de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":["post-54225","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=54225"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/54234"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=54225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=54225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=54225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}