{"id":54133,"date":"2024-08-11T19:42:45","date_gmt":"2024-08-11T22:42:45","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=54133"},"modified":"2024-08-12T19:25:52","modified_gmt":"2024-08-12T22:25:52","slug":"el-radicalismo-se-quedo-con-las-comunas-de-golondrina-y-canada-ombu","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/08\/11\/el-radicalismo-se-quedo-con-las-comunas-de-golondrina-y-canada-ombu\/","title":{"rendered":"El radicalismo se qued\u00f3 con las comunas de Golondrina y Ca\u00f1ada Omb\u00fa"},"content":{"rendered":"<p>Ambos candidatos de Unidos ganaron en sus distritos. Las dos comunas hab\u00edan sido intervenidas por subversi\u00f3n del r\u00e9gimen democr\u00e1tico.<\/p>\n<p>En una jornada de pleno sol en todo el norte santafesino, las localidades de Golondrina y Ca\u00f1ada Omb\u00fa eligieron autoridades comunales para el periodo 2024 &#8211; 2026.<\/p>\n<p>Sin inconvenientes trascurrieron los actos comiciales en ambos pueblos del norte del departamento Vera y cerraron puntualmente a las 18, con una afluencia promedio del 76 %.<\/p>\n<p>En las dos mesas dispuestas en las dos escuelas de Golondrina para la elecci\u00f3n de presidente comunal, el actual interventor y radical Carlos Dom\u00ednguez obtuvo 144 votos -contra 126 de su competidor Diego B\u00e1ez, del PJ- y, con esa cosecha de sufragios, gan\u00f3 y se erigi\u00f3 en presidente comunal electo.<\/p>\n<p>En tanto, en Ca\u00f1ada Omb\u00fa, puerta de entrada a los Bajos Submeridionales, tambi\u00e9n el funcionario designado para intervenir la comuna local se qued\u00f3 con el triunfo. En este caso, se trat\u00f3 de un formalismo ya que Franco Huber no tuvo competidores en frente, ni en las Paso ni en la elecci\u00f3n general. Lo votaron 341 electores de un total.de 494.<\/p>\n<p>Acompa\u00f1aron al candidato ganador la subsecretaria de Asuntos Electorales y Vinculaci\u00f3n Regional del Ministerio de Gobierno, Dra. Juliana Caillat; el jefe del Nodo Reconquista, Oscar Duarte; el presidente comunal de Margarita, Ariel Bola\u00f1o; y el funcionario del Ministerio de Gobierno, Reynaldo Fabbroni.<\/p>\n<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/norte24cdn.eleco.com.ar\/media\/2024\/08\/huber.png\" alt=\"huber\" \/><figcaption>Franco Huber, presidente comunal electo de Ca\u00f1ada Omb\u00fa.<\/figcaption><\/figure>\n<p><strong>Normalizaci\u00f3n<\/strong><\/p>\n<p>El gobierno provincial intervino las comunas de Golondrina y Ca\u00f1ada Omb\u00fa el 29 de diciembre pasado mediante los decretos 0238 y 0239, respectivamente, a los fines de la normalizaci\u00f3n de la situaci\u00f3n institucional subvertida debido a la situaci\u00f3n producida en las comisiones comunales, que designaron como jefes de los gobiernos a candidatos que hab\u00edan perdido la compulsa electoral, en una actitud \u201cdecidida al margen y en contra de toda consideraci\u00f3n al status constitucional, desde\u00f1\u00e1ndose as\u00ed el emplazamiento de los partidos pol\u00edticos como instituciones fundamentales de la democracia\u201d.<\/p>\n<p>En las resoluciones, la Casa Gris hizo constar que correspond\u00eda entonces al Poder Ejecutivo \u201cresguardar la institucionalidad local&#8221; respetando las estructuras de poder fundamentales del Estado de derecho, y en consecuencia resultaba de \u201cimperiosa necesidad\u201d disponer la intervenciones a los efectos de constituir democr\u00e1ticamente sus autoridades y normalizar la situaci\u00f3n institucional subvertida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ambos candidatos de Unidos ganaron en sus distritos. Las dos comunas hab\u00edan sido intervenidas por subversi\u00f3n del r\u00e9gimen democr\u00e1tico. En una jornada de pleno sol en todo el norte santafesino, las localidades de Golondrina y Ca\u00f1ada Omb\u00fa eligieron autoridades comunales para el periodo 2024 &#8211; 2026. Sin inconvenientes trascurrieron los actos comiciales en ambos pueblos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":{"0":"post-54133","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=54133"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/54133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/54134"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=54133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=54133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=54133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}