{"id":53556,"date":"2024-07-18T08:48:31","date_gmt":"2024-07-18T11:48:31","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=53556"},"modified":"2024-07-19T08:44:18","modified_gmt":"2024-07-19T11:44:18","slug":"firma-de-convenios-del-programa-de-recreacion-para-adultos-mayores","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/07\/18\/firma-de-convenios-del-programa-de-recreacion-para-adultos-mayores\/","title":{"rendered":"Firma de convenios del &#8220;Programa de Recreaci\u00f3n para Adultos Mayores&#8221;"},"content":{"rendered":"<p>Con la presencia de la secretaria de Pol\u00edticas Sociales e Integraci\u00f3n Social, Viviana Foresi, se firmaron en la Municipalidad de Vera los convenios con municipios y comunas destinados a la recreaci\u00f3n de adultos mayores.<\/p>\n<p>&#8220;Este programa representa un gran paso hacia la inclusi\u00f3n y el bienestar de nuestros queridos mayores. Queremos expresar nuestro profundo agradecimiento al Gobierno de la Provincia de Santa Fe y a su Ministerio de Igualdad y Desarrollo Humano por brindarnos esta oportunidad tan importante para la recreaci\u00f3n de los adultos mayores de nuestro departamento&#8221;, manifest\u00f3 el senador Osvaldo Sosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la presencia de la secretaria de Pol\u00edticas Sociales e Integraci\u00f3n Social, Viviana Foresi, se firmaron en la Municipalidad de Vera los convenios con municipios y comunas destinados a la recreaci\u00f3n de adultos mayores. &#8220;Este programa representa un gran paso hacia la inclusi\u00f3n y el bienestar de nuestros queridos mayores. Queremos expresar nuestro profundo agradecimiento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":53557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":{"0":"post-53556","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-vera"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/53556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=53556"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/53556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/53557"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=53556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=53556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=53556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}