{"id":51813,"date":"2024-05-02T08:52:56","date_gmt":"2024-05-02T11:52:56","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=51813"},"modified":"2024-05-03T14:00:00","modified_gmt":"2024-05-03T17:00:00","slug":"prefectura-reconquista-secuestro-46-surubies-y-dorados-a-dos-pescadores","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/05\/02\/prefectura-reconquista-secuestro-46-surubies-y-dorados-a-dos-pescadores\/","title":{"rendered":"Prefectura Reconquista secuestr\u00f3 46 surub\u00edes y dorados a dos pescadores"},"content":{"rendered":"<p>Personal de Agencia de Seguridad Alimentaria Reconquista (ASSAL) certific\u00f3 que las especies no eran aptas para consumo. Posteriormente, las especies ict\u00edcolas fueron desnaturalizadas por la repartici\u00f3n municipal.<\/p>\n<p>Efectivos de la Prefectura Naval Argentina incautaron un cargamento de 46 especies de r\u00edo, capturada de manera furtiva y una red de pesca, en un operativo que tuvo lugar en \u00a0Reconquista<\/p>\n<p>Dos hombres que quedaron sujetos a la causa, se trata de Miguel G, de 41 a\u00f1os de edad, \u00a0y de Gustavo R, de 45 a\u00f1os de edad, ambos con domicilio en \u00a0Reconquista.<\/p>\n<p>El procedimiento comenz\u00f3 cuando el personal de la Fuerza, que se encontraba haciendo un patrullaje por la zona ribere\u00f1a a la altura del kil\u00f3metro 950 del r\u00edo Paran\u00e1, observ\u00f3 a dos individuos que estaban descargando bolsas desde una embarcaci\u00f3n hacia un autom\u00f3vil.<\/p>\n<p>A ra\u00edz de esto, Prefectura se aproxim\u00f3 al lugar y comprob\u00f3 que los dos hombres estaban manipulando 39 ejemplares de surub\u00ed, seis de dorado y una boga, capturadas en infracci\u00f3n a la ley provincial de pesca N\u00b0 12.212. Adem\u00e1s, se logr\u00f3 decomisar una red de tipo mall\u00f3n de 80 metros.<\/p>\n<p>Interiorizado el fiscal de turno, Dr. Juan Sebasti\u00e1n Marichal, orden\u00f3 el secuestro de todo ello por infracci\u00f3n a la Ley Provincial de Pesca N\u00b0 12.212 (en su art\u00edculo 10) y art\u00edculo 206 del C\u00f3digo Penal Argentino; como as\u00ed tambi\u00e9n dispuso la notificaci\u00f3n de los implicados, los dos hombres permanecen en libertad, pero ligados a la causa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal de Agencia de Seguridad Alimentaria Reconquista (ASSAL) certific\u00f3 que las especies no eran aptas para consumo. Posteriormente, las especies ict\u00edcolas fueron desnaturalizadas por la repartici\u00f3n municipal. Efectivos de la Prefectura Naval Argentina incautaron un cargamento de 46 especies de r\u00edo, capturada de manera furtiva y una red de pesca, en un operativo que tuvo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":51814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30,55,61],"tags":[],"class_list":["post-51813","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales","category-reconquista","category-regionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/51813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=51813"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/51813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/51814"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=51813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=51813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=51813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}