{"id":51785,"date":"2024-04-30T08:29:18","date_gmt":"2024-04-30T11:29:18","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=51785"},"modified":"2024-04-30T10:47:12","modified_gmt":"2024-04-30T13:47:12","slug":"1-de-mayo-a-puro-futbol","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/04\/30\/1-de-mayo-a-puro-futbol\/","title":{"rendered":"1 de mayo a puro f\u00fatbol"},"content":{"rendered":"<p>Se juega este mi\u00e9rcoles 1 de mayo la segunda fecha de la LVF los partidos que faltaban completar x las inclemencias de tiempo se estar\u00e1n disputando siempre y cuando el tiempo lo permita y todo se presta para vivir el s\u00faper cl\u00e1sico Estudiantes Unidos vs Gimnasia, unos de los cl\u00e1sicos m\u00e1s fuertes y antiguos de la Liga Verense&#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se juega este mi\u00e9rcoles 1 de mayo la segunda fecha de la LVF los partidos que faltaban completar x las inclemencias de tiempo se estar\u00e1n disputando siempre y cuando el tiempo lo permita y todo se presta para vivir el s\u00faper cl\u00e1sico Estudiantes Unidos vs Gimnasia, unos de los cl\u00e1sicos m\u00e1s fuertes y antiguos de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":51786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[31,53],"tags":[],"class_list":["post-51785","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/51785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=51785"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/51785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/51786"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=51785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=51785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=51785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}