{"id":50006,"date":"2024-02-14T13:48:20","date_gmt":"2024-02-14T16:48:20","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=50006"},"modified":"2024-02-14T13:48:20","modified_gmt":"2024-02-14T16:48:20","slug":"mas-de-50-mil-personas-disfrutaron-de-los-carnavales-en-espacios-culturales-de-la-provincia","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2024\/02\/14\/mas-de-50-mil-personas-disfrutaron-de-los-carnavales-en-espacios-culturales-de-la-provincia\/","title":{"rendered":"M\u00e1s de 50 mil personas disfrutaron de los carnavales en espacios culturales de la Provincia"},"content":{"rendered":"<p>Baile, talleres, juegos y muestras fueron algunas de las propuestas impulsadas por el Gobierno de la Provincia en espacios p\u00fablicos de las ciudades de Rosario y Santa Fe. Enmarcadas en el Operativo Verano, las propuestas organizadas por el Ministerio de Cultura pudieron disfrutarse de manera gratuita.<\/p>\n<p>En el marco de las acciones previstas en Operativo Verano, el Gobierno de la Provincia de Santa Fe se sum\u00f3 a las celebraciones de carnaval con diversas propuestas que se llevaron adelante en espacios culturales p\u00fablicos de Santa Fe y Rosario.<br \/>\nBailes, talleres, juegos y muestras formaron parte de una grilla de propuestas impulsadas por el Ministerio de Cultura que se desarrollaron a lo largo de todo el fin de semana largo y que fueron disfrutadas de manera gratuita por m\u00e1s de 50 mil personas.<\/p>\n<p>Mercado de Frutos Culturales<\/p>\n<p>El Mercado de Frutos Culturales de Rosario, ubicado en el Franja del R\u00edo del parque nacional a la Bandera, el s\u00e1bado 10 fue escenario para el desarrollo de juegos de kermes y de la vestuarioteca en familia. Adem\u00e1s, ni\u00f1as y ni\u00f1os pudieron deleitarse con la obra de teatro Lambe-Lambe y t\u00edteres \u2018El ni\u00f1o fantasma\u2019 de Alquimia T\u00edteres. El domingo 11 tuvo como punto alto el show de la banda \u2018Mu\u00f1a Mu\u00f1a\u2019; el lunes 12 las familias pudieron disfrutar de juegos, disfraces y de radio en vivo, de la mano de Cambalache Radio quienes presentaron \u2018Carnaval toda la vida\u2019; y el martes 13, en la explanada del Mercado, el p\u00fablico disfrut\u00f3 del espect\u00e1culo \u2018Los Magit\u00edteres de Ray Cristian\u2019, adem\u00e1s de juegos, talleres y vestuarioteca.<\/p>\n<p>El \u2018diablo\u2019 entr\u00f3 al Museo Gallardo<\/p>\n<p>El s\u00e1bado 10, sobre una de las vitrinas del Museo de Ciencias Naturales \u2018\u00c1ngel Gallardo\u2019 de Rosario, un diablo colorido y enmascarado recibi\u00f3 a las y los visitantes que instantes despu\u00e9s, junto a las educadoras Bel\u00e9n y Cecilia, recorrieron la exposici\u00f3n \u2018Relatos, Cr\u00edmenes, Territorios y Gigantes\u2019, en busca de diversos ritos y mitos vinculados a la celebraci\u00f3n del carnaval, tan antigua como diversa.<br \/>\nSobre una mesa que hizo las veces de altar, se destacaban algunos objetos: una caja coplera, harina, papel picado, una m\u00e1scara y un sikus, elementos que ayudaron a narrar la historia pol\u00edtica ideol\u00f3gica del carnaval y a desentra\u00f1ar sus significados. \u00bfQui\u00e9nes se apropian y se han apropiado a lo largo del tiempo de este festejo? \u00bfQui\u00e9nes lo han propiciado? \u00bfQui\u00e9nes lo han prohibido? Muchas preguntas sobre una celebraci\u00f3n del tiempo sin tiempo que tiene sus formas, historias y colores en cada rinc\u00f3n de nuestro pa\u00eds.<br \/>\nEl recorrido sum\u00f3 las voces de las y los visitantes, que contaron experiencias y recuerdos, desde el arrojo de bombuchas, espuma y bailes en los barrios rosarinos, a los cantos a capela en tablados porte\u00f1as, o comparsas, bailes y plumas al otro lado del Paran\u00e1.<\/p>\n<p>La Casa de la Cultura<\/p>\n<p>En la ciudad de Santa Fe, el domingo 11 quienes se acercaron hasta el emblem\u00e1tico edificio ubicado sobre Bv. G\u00e1lvez al 1200 pudieron disfrutar del carnaval de m\u00e1scaras.<br \/>\nLa celebraci\u00f3n incluy\u00f3 una intervenci\u00f3n art\u00edstica que invit\u00f3 al p\u00fablico a conocer c\u00f3mo se celebraba el carnaval en estos palacetes a principios del siglo XX. A su vez, hubo recorridos por el edificio, mientras que en los patios las familias disfrutaron de juegos y talleres de construcci\u00f3n de accesorios que luego decoraron el gran baile de m\u00e1scaras que coron\u00f3 la noche.<\/p>\n<p>Celebraci\u00f3n en La Redonda<\/p>\n<p>En el atardecer del martes 13, en el patio del edificio ubicado en Salvador del Carril y Belgrano de la capital provincial una multitud se acerc\u00f3 para \u2018despertar\u2019 al rey momo de su sue\u00f1o e invocar el calor de viejos carnavales. La puerta 20 del hemiciclo de La Redonda puso en funcionamiento la F\u00e1brica de la Alegr\u00eda que se colm\u00f3 de familias que disfrutaron de los dispositivos de juego y creaci\u00f3n dispuestos en el Jard\u00edn de Agua, la P\u00e9rgola de Sonido y la F\u00e1brica de M\u00e1scaras.<br \/>\nEl grupo \u2018Mira que quema\u2019 encendi\u00f3 la velada con su m\u00fasica y, tras el ritual de acompa\u00f1ar al momo a su descanso de ceniza, la fiesta culmin\u00f3 a puro baile con la presentaci\u00f3n del Grupo Macondo y su cumbia colombiana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baile, talleres, juegos y muestras fueron algunas de las propuestas impulsadas por el Gobierno de la Provincia en espacios p\u00fablicos de las ciudades de Rosario y Santa Fe. Enmarcadas en el Operativo Verano, las propuestas organizadas por el Ministerio de Cultura pudieron disfrutarse de manera gratuita. En el marco de las acciones previstas en Operativo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":50007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":["post-50006","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provinciales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/50006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=50006"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/50006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/50007"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=50006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=50006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=50006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}