{"id":48967,"date":"2023-12-27T09:37:56","date_gmt":"2023-12-27T12:37:56","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=48967"},"modified":"2023-12-27T17:03:27","modified_gmt":"2023-12-27T20:03:27","slug":"procedimiento-de-punta-de-lanza-para-trasladar-a-un-bebe-al-hospital","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/12\/27\/procedimiento-de-punta-de-lanza-para-trasladar-a-un-bebe-al-hospital\/","title":{"rendered":"Procedimiento de &#8220;punta de lanza&#8221; para trasladar a un beb\u00e9 al Hospital"},"content":{"rendered":"<p>Anoche, a las 21.35 y a ra\u00edz de un llamado a la central telef\u00f3nica 101 de emergencias, personal de turno de la Secci\u00f3n Comando Radioel\u00e9ctrico fueron enviados a calle Catamarca 1800 debido a la urgencia de trasladar a un beb\u00e9 (de 26 d\u00edas) con problemas de salud (problemas grave respiratorio).<\/p>\n<p>Por la premura del caso procedieron a trasladarlo junto a su madre\u00a0 en el m\u00f3vil policial , mientras que los dem\u00e1s m\u00f3viles hac\u00edan punta de lanza con balizas y sirenas encendidas para evitar entorpecimiento vehicular en el traslado.<\/p>\n<p>Arribados al nosocomio local, un m\u00e9dico de guardia le brind\u00f3 atenci\u00f3n inmediata. Presumiblemente, el lactante se habr\u00eda ahogado con leche materna, su madre es una joven de 17 a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anoche, a las 21.35 y a ra\u00edz de un llamado a la central telef\u00f3nica 101 de emergencias, personal de turno de la Secci\u00f3n Comando Radioel\u00e9ctrico fueron enviados a calle Catamarca 1800 debido a la urgencia de trasladar a un beb\u00e9 (de 26 d\u00edas) con problemas de salud (problemas grave respiratorio). Por la premura del caso [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17577,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-48967","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/48967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=48967"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/48967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/17577"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=48967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=48967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=48967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}