{"id":47006,"date":"2023-09-22T11:38:31","date_gmt":"2023-09-22T14:38:31","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=47006"},"modified":"2023-09-22T11:38:31","modified_gmt":"2023-09-22T14:38:31","slug":"aic-detuvo-a-un-hombre-por-narcomenudeo","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/09\/22\/aic-detuvo-a-un-hombre-por-narcomenudeo\/","title":{"rendered":"AIC detuvo a un hombre por narcomenudeo"},"content":{"rendered":"<p>Agentes de Narcocriminalidad detuvieron a un hombre de 24 a\u00f1os y secuestraron marihuana<\/p>\n<p>La Direcci\u00f3n de Investigaci\u00f3n Criminal sobre el Narcotr\u00e1fico de la Agencia de Investigaci\u00f3n Criminal dependiente del Ministerio de Seguridad, realiz\u00f3 un allanamiento en el marco a investigaciones sobre infracci\u00f3n a la Ley 23.737 en inmediaciones de calle San Martin al 100 de la Gobernador Crespo, en el que se logr\u00f3 detener a un hombre de 24 a\u00f1os. En el domicilio secuestraron m\u00e1s de 129 gramos de Cannabis Sativa, 1 frasco con cogollos, la suma de 179.000 pesos, 3 celulares, 1 CPU y 1 Notebook, estos \u00faltimos dispositivos revistan inter\u00e9s para la causa.<\/p>\n<p>Las disposiciones estuvieron a cargo del Dr. Rodr\u00edguez Reinaldo, quien opero en conjunto con la secretaria de la instancia Dr. Leticia del Fabro, del Juzgado Federal N\u00ba 1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agentes de Narcocriminalidad detuvieron a un hombre de 24 a\u00f1os y secuestraron marihuana La Direcci\u00f3n de Investigaci\u00f3n Criminal sobre el Narcotr\u00e1fico de la Agencia de Investigaci\u00f3n Criminal dependiente del Ministerio de Seguridad, realiz\u00f3 un allanamiento en el marco a investigaciones sobre infracci\u00f3n a la Ley 23.737 en inmediaciones de calle San Martin al 100 de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[30],"tags":[],"class_list":["post-47006","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/47006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=47006"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/47006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/47007"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=47006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=47006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=47006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}