{"id":46511,"date":"2023-09-03T10:34:43","date_gmt":"2023-09-03T13:34:43","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=46511"},"modified":"2023-09-03T10:34:43","modified_gmt":"2023-09-03T13:34:43","slug":"industria-nortena-matriz-diversificada-y-el-desafio-de-agregar-valor-a-las-materias-primas","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/09\/03\/industria-nortena-matriz-diversificada-y-el-desafio-de-agregar-valor-a-las-materias-primas\/","title":{"rendered":"Industria norte\u00f1a: matriz diversificada y el desaf\u00edo de agregar valor a las materias primas"},"content":{"rendered":"<p>Casi una decena de parques y \u00e1reas industriales concentran el alma productiva de la regi\u00f3n. El procesamiento de frutos de la tierra, la metalmec\u00e1nica, el sector maderero y el de servicios tecnologizados lideran el r\u00e1nking. Rechazo a medidas del gobierno nacional y perspectivas complicadas. Informe especial.<\/p>\n<p>En toda la zona noreste de la bota santafesina la industria florece en 9 parques y \u00e1reas industriales distribuidos en los departamentos Vera y General Obligado, con clara preeminencia de este \u00faltimo.<\/p>\n<p>Desde Calchaqu\u00ed hasta Villa Ocampo la matriz productiva norte\u00f1a se concentra en estos pol\u00edgonos que presentan distintos niveles de desarrollo en t\u00e9rminos de infraestructura, extensi\u00f3n y dinamismo.<\/p>\n<p>En cuanto a liderazgo, Avellaneda toma la delantera con un parque de servicios y otro industrial que ya sum\u00f3 un centenar de empresas radicadas. La ciudad cuenta con grandes industrias reconocidas a nivel provincial, nacional e internacional; dichas actividades econ\u00f3micas generan a su vez importantes cadenas productivas, comerciales y de servicios.<\/p>\n<p>De cerca, la sigue Reconquista con un parque eminentemente industrial, m\u00e1s uno denominado de Industrias y Talleres y otro que viene en camino producto de la sinergia p\u00fablico &#8211; privada.<\/p>\n<p>Las \u00e1reas industriales de Calchaqu\u00ed, Malabrigo y Villa Ocampo crecen en capacidad instalada, y se destaca la recientemente creada en Nicanor Molinas -distrito ubicado 23 kil\u00f3metros al oeste de Reconquista sobre a Ruta 40 S- de uso industrial y servicios.<\/p>\n<p>En la regi\u00f3n n\u00facleo -el \u00e1rea metropolitana Reconquista &#8211; Avellaneda- la actividad de muestra diversificada en frigor\u00edficos de aves y plantas de alimentos balanceado; la cadena completa del algod\u00f3n: desmotado, f\u00e1brica de algod\u00f3n hidr\u00f3filo, celulosa microcristalina, fabricaci\u00f3n de telas e indumentarias; refinadoras de aceites vegetales, f\u00e1brica de biodiesel y bioetanol, empresas metal\u00fargicas, entre las principales.<\/p>\n<p>La metalmec\u00e1nica, el sector maderero y el de servicios tecnologizados lideran el r\u00e1nking de manufacturas, siempre detr\u00e1s del procesamiento de frutos de la tierra provenientes del campo. Aqu\u00ed, es donde el norte tiene su fortaleza y, a la vez, su gran desaf\u00edo: industrializar las materias primas.<\/p>\n<p>La conversi\u00f3n de prote\u00ednas en carne que se exporta -para que el grano no se vaya \u201cdesnudo\u201d afuera- corre por cuenta del frigor\u00edfico Friar SA, una nave insignia de la industria regional con producci\u00f3n propia en un feed lot de 30 mil cabezas; otros actores hist\u00f3ricos fabrican aceites comestibles derivados de girasol, ya no para marcas propias sino para terceros.<\/p>\n<p>M\u00e1s all\u00e1 de estos ejemplos puntuales, la realidad marca que el norte est\u00e1 lejos a\u00fan de un nivel \u00f3ptimo de agregado de valor a sus producciones primarias. Los puertos del sur donde se muelen, procesan y cargan cereales y oleaginosas son los grandes destinatarios de las riquezas de una zona cuya impronta deficitaria de instalaciones fluviales de fuste le impide desarrollarse y competir de igual a igual.<\/p>\n<p><a href=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2023\/09\/industria-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-46491\" src=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2023\/09\/industria-1.jpg\" alt=\"\" width=\"1000\" height=\"600\" srcset=\"https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2023\/09\/industria-1.jpg 1000w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2023\/09\/industria-1-696x418.jpg 696w, https:\/\/infovera.com.ar\/web\/wp-content\/uploads\/2023\/09\/industria-1-700x420.jpg 700w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p><strong>D\u00f3lares, empleo y bono<\/strong><\/p>\n<p>La imposibilidad de acceder a d\u00f3lares para importaci\u00f3n impacta en las industrias con perfil exportador de igual manera que en el resto del pa\u00eds, sin embargo, el nivel de empleo no registra variaciones negativas, sin despidos ni merma de turnos en las plantas fabriles.<\/p>\n<p>Aun as\u00ed, la situaci\u00f3n de no dejar de ser cr\u00edtica. Las \u00faltimas disposiciones del gobierno nacional pusieron en alerta al sector empresarial que repudi\u00f3 \u201cfervientemente\u201d las medidas econ\u00f3micas sobre la suma fija para empleados.<\/p>\n<p>Por ejemplo, desde el Centro Industrial y Comercial de Avellaneda se expresaron ante los recientes anuncios que diera a conocer el Ministerio de Econom\u00eda de la Naci\u00f3n con relaci\u00f3n al pago de una suma fija para empleados, considerando que la medida es \u201ctotalmente perjudicial y maliciosa\u201d para el sector empresarial en un contexto nacional de \u201cdesequilibrio econ\u00f3mico\u201d.<\/p>\n<p>En primer lugar, asent\u00f3 la entidad, porque en el \u00e1mbito de las negociaciones paritarias es donde deben determinarse las remuneraciones, conciliando las leg\u00edtimas pretensiones de los trabajadores con las reales posibilidades de las empresas de cada sector.<\/p>\n<p>En segundo t\u00e9rmino, debido a que \u201ctodos los aportes o sumas no remunerativas realizadas en los \u00faltimos a\u00f1os se hicieron s\u00f3lo con el esfuerzo de los empleadores, sin ning\u00fan tipo de aporte por parte del Estado, como se hab\u00eda anunciado en un principio para la devoluci\u00f3n de dichos bonos\u201d.<\/p>\n<p>El CICA amonest\u00f3 que ahora los anuncios hacen referencia a la \u201cintenci\u00f3n\u201d de retribuir s\u00f3lo a micro y peque\u00f1as empresas, quedando el resto excluidas, y con la \u201cdesconfianza latente\u201d por las experiencias anteriores.<\/p>\n<p>En tercer lugar, argument\u00f3 que la dif\u00edcil situaci\u00f3n que cada sector de la econom\u00eda y cada empresa en particular vienen atravesando, la elevada inflaci\u00f3n y la consecuente ca\u00edda de las ventas, hacen \u201cinsostenible el pago a t\u00e9rmino de las contribuciones patronales por cada empleado. Por lo tanto, sumarle el otorgamiento de una suma fija a trabajadores del sector privado es inaudito\u201d.<\/p>\n<p>Por \u00faltimo, aclar\u00f3 que sus asociados son conscientes del \u201cdeterioro\u201d del poder adquisitivo de los salarios de los empleados, y juzg\u00f3 que la suma pretendida es \u201cinsignificante\u201d por la devaluaci\u00f3n del peso y la creciente inflaci\u00f3n, pero contrapuso que para el empleador es \u201csignificante, dif\u00edcil e imposible afrontar ese costo\u201d. \u201cEntonces, si el Estado pretende que los empleados cobren m\u00e1s, sugerimos que les reduzca o elimine los aportes que se les descuenta todos los meses, o que les pague y reduzca el impuesto a las ganancias\u201d, concluy\u00f3.<\/p>\n<p><strong>&#8220;Arbitraria e inconsulta&#8221;<\/strong><\/p>\n<p>Por los anuncios de pago de suma fija a trabajadores se sum\u00f3 otro rechazo de empresarios privados norte\u00f1os: &#8220;Los anuncios del gobierno nacional que expresan la intenci\u00f3n de obligar a las empresas privadas a pagar una suma fija a sus empleados generan el contundente descontento y rechazo&#8221;, sostuvo Corenosa.<\/p>\n<p>Para el Consejo Regional Econ\u00f3mico del Norte Santafesino, el gobierno sigue &#8220;poniendo en riesgo&#8221; a las empresas que hasta el momento resisten gracias a su propio esfuerzo la &#8220;elevad\u00edsima presi\u00f3n tributaria, la legislaci\u00f3n laboral desfavorable, los inconvenientes para exportar sus productos e importar insumos b\u00e1sicos&#8221;, m\u00e1s las regulaciones excesivas y la recesi\u00f3n que amenaza el consumo de manera creciente.<\/p>\n<p>El colectivo empresario e institucional fustig\u00f3 la &#8220;arbitrariedad y la intenci\u00f3n de atacar siempre al sector que mayoritariamente hace de soporte a la econom\u00eda nacional&#8221;, lo que &#8220;aumenta la incertidumbre y los riesgos de desaparici\u00f3n de estas empresas&#8221; que son importantes generadoras de empleo. &#8220;Para el ajuste salarial existen las paritarias&#8221;, sentenci\u00f3.<\/p>\n<p>En el mismo tono, evalu\u00f3: &#8220;Escasa es para cada uno de los trabajadores la suma fija de 60.000 pesos, preocupante es para el empleador no poder pagarla e injusto es el gobierno que pretende imponerlo&#8221;. Por lo expuesto, Corenosa dej\u00f3 en claro su rechazo contundente a la &#8220;intenci\u00f3n de imponer esta medida arbitraria e inconsulta&#8221;.<\/p>\n<p><strong>Contexto complejo<\/strong><\/p>\n<p>El presidente de la Uni\u00f3n Industrial de Santa Fe, Alejandro Taborda, admiti\u00f3 que, a diferencia de festejos de a\u00f1os anteriores, el sector est\u00e1 viviendo un momento &#8220;muy complejo&#8221; consecuencia de una hist\u00f3rica sequ\u00eda que afect\u00f3 con mucha fuerza la actividad en la provincia, y de una situaci\u00f3n econ\u00f3mica y financiera que no permite producir en condiciones de normalidad a las empresas de la regi\u00f3n.<\/p>\n<p>&#8220;Si tengo que hacer una recapitulaci\u00f3n de los \u00faltimos a\u00f1os de la actividad industrial, puedo decir que tuvimos hasta el 2011 un crecimiento muy importante, hubo un estancamiento hasta el 2015, una ca\u00edda estrepitosa del 2016 al 2019 y una recuperaci\u00f3n muy importante despu\u00e9s de la pandemia, con Santa Fe liderando esta recuperaci\u00f3n en todo el pa\u00eds, con sectores que crec\u00edan a tres d\u00edgitos como los vinculados a lo agroindustrial. Y cuando est\u00e1bamos en ese proceso de crecimiento, la invasi\u00f3n rusa a Ucrania nos trajo nuevos problemas como el precio de la energ\u00eda y despu\u00e9s una nueva restricci\u00f3n externa que nos tiene muy preocupados&#8221;, expres\u00f3.<\/p>\n<p><strong>&#8211; \u00bfCu\u00e1les fueron para ustedes las causas de esta nueva restricci\u00f3n externa?<\/strong><\/p>\n<p>&#8211; Nosotros creemos que fue una mala administraci\u00f3n de las divisas porque tuvimos a\u00f1os muy buenos. Hubo 40.000 millones de d\u00f3lares de super\u00e1vit en 2021 y 2022. Nosotros somos defensores de lo que llamamos la administraci\u00f3n inteligente del comercio exterior. Hay que hacer lo que hacen todos los pa\u00edses, dejar entrar al pa\u00eds lo que no se produce, como tecnolog\u00eda, y no aquello que se produce aqu\u00ed o que pueda afectar el trabajo de los argentinos. Bueno, eso no se hizo y llegamos a esta situaci\u00f3n. En junio de 2022 empezamos con problemas en el comercio internacional por el d\u00e9ficit que genera la importaci\u00f3n de combustibles, aument\u00f3 la brecha de los tipos de cambio y empezamos a tener problemas los exportadores. As\u00ed todo hasta fines del a\u00f1o 2022 el crecimiento se mantuvo, creci\u00f3 el empleo y la inversi\u00f3n, pero a fin de a\u00f1o nos cae la sequ\u00eda, que perjudic\u00f3 especialmente a Santa Fe.<\/p>\n<p><strong>&#8211; El primer semestre del 2023 fue un mal semestre, digamos, con ca\u00edda de la actividad, \u00bfqu\u00e9 sectores son los que peor la est\u00e1n pasando?<\/strong><\/p>\n<p>&#8211; El sector agroindustrial y metalmec\u00e1nico y todas aquellas que est\u00e1n vinculadas a la actividad del campo. De todas maneras, hay otros como el del cuero, textil, alimenticia, repuestos de automotores, que viven como una especie de microclima y se mantiene con n\u00fameros positivos. Pero todo lo que es el sector l\u00e1cteo, que es muy importante en la regi\u00f3n, se fue complicando por la sequ\u00eda y las perspectivas de la econom\u00eda.<\/p>\n<p><strong>&#8211; \u00bfQu\u00e9 segundo semestre esperan?<\/strong><\/p>\n<p>-Lamentablemente con incrementos important\u00edsimos de costos, con muchas complicaciones tambi\u00e9n con el comercio exterior, con una ca\u00edda importante en las ventas y en la actividad. Creemos que el primer trimestre del a\u00f1o pr\u00f3ximo tambi\u00e9n va a ser complicado y reci\u00e9n a mediados de 2024 creemos que la situaci\u00f3n va a ir encamin\u00e1ndose.<\/p>\n<p><strong>Desaliento exportador<\/strong><\/p>\n<p>Problemas con los insumos importados, impacto de la sequ\u00eda, inflaci\u00f3n acelerada que afecta la capacidad de compra en el mercado interno, incentivos del tipo de cambio que desalientan la exportaci\u00f3n. A nivel nacional o en la provincia, en indicadores oficiales o privados, la enorme capacidad fabril del pa\u00eds est\u00e1 estancada en los mercados y con inversiones apenas cautivas de empresarios que &#8220;huyen&#8221; sus pesos hacia inversiones menos de expansi\u00f3n que de mantenimiento. Eso a pesar del enorme aporte de la vinculaci\u00f3n tecnol\u00f3gica desde la econom\u00eda del conocimiento.<\/p>\n<p>El \u00faltimo informe disponible del \u00cdndice de Producci\u00f3n Industrial del Indec apunt\u00f3 que en junio hubo una ca\u00edda de 2,3 % respecto a igual mes de 2022. &#8220;El acumulado enero-junio de 2023 presenta un incremento de 1,3% respecto a igual per\u00edodo de 2022. En junio de 2023, el \u00edndice de la serie desestacionalizada muestra una variaci\u00f3n negativa de 1,3 % respecto al mes anterior y el \u00edndice serie tendencia-ciclo registra una variaci\u00f3n negativa de 0,2 % respecto al mes anterior&#8221;.<\/p>\n<p>Los datos del propio sector fabril son algo m\u00e1s severos. Seg\u00fan el \u00faltimo reporte de la Federaci\u00f3n Industrial de Santa Fe, \u201cen junio de 2023 el nivel de producci\u00f3n de la industria manufacturera en la provincia de Santa Fe registr\u00f3 una disminuci\u00f3n de 9,7% interanual, acumulando en el primer semestre una baja de 5,3% en relaci\u00f3n al mismo per\u00edodo del a\u00f1o pasado&#8221;.<\/p>\n<p>Los factores que precipitan el escenario son &#8220;las restricciones a las importaciones con los consecuentes inconvenientes en la provisi\u00f3n de insumos; el proceso inflacionario que altera los costos relativos, degrada los salarios (y por ende cae el poder adquisitivo en el mercado interno) y reduce la competitividad del tipo de cambio exportador; la sequ\u00eda que afect\u00f3 a las industrias vinculadas directa o indirectamente con el sector agropecuario, ya sea por la menores ventas de sus productos como as\u00ed tambi\u00e9n por la reducida provisi\u00f3n de materias primas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casi una decena de parques y \u00e1reas industriales concentran el alma productiva de la regi\u00f3n. El procesamiento de frutos de la tierra, la metalmec\u00e1nica, el sector maderero y el de servicios tecnologizados lideran el r\u00e1nking. Rechazo a medidas del gobierno nacional y perspectivas complicadas. Informe especial. En toda la zona noreste de la bota santafesina [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":46512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[49,48,61,50],"tags":[],"class_list":{"0":"post-46511","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-empresariales","8":"category-produccion","9":"category-regionales","10":"category-rurales"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/46511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=46511"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/46511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/46512"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=46511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=46511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=46511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}