{"id":44818,"date":"2023-06-23T12:16:36","date_gmt":"2023-06-23T15:16:36","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=44818"},"modified":"2023-06-23T16:54:02","modified_gmt":"2023-06-23T19:54:02","slug":"lewandosky-y-sosa-encabezaron-el-lanzamiento-de-la-lista-elijo-hacer","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/06\/23\/lewandosky-y-sosa-encabezaron-el-lanzamiento-de-la-lista-elijo-hacer\/","title":{"rendered":"Lewandosky y Sosa encabezaron el lanzamiento de la lista &#8220;Elijo Hacer&#8221;"},"content":{"rendered":"<p><strong>Ante un sal\u00f3n colmado por militantes que presentaba una escenograf\u00eda adornada con pancartas con los principales referentes se presentaron los precandidatos de todo el departamento Vera, de la lista \u201cElijo hacer\u201d en la alianza \u201cJuntos avancemos\u201d.<\/strong><\/p>\n<p>Luego de la presentaci\u00f3n individual de los precandidatos a presidentes comunales, concejales, diputados, intendente, senador y a gobernador, comenz\u00f3 la lista de oradores.<\/p>\n<p>Rodrigo Acevedo, presidente comunal de Fort\u00edn Olmos y precandidato por la reelecci\u00f3n fue el primero en dirigirse a los presentes, para luego dar paso al precandidato a concejal de Vera, Mario Souilh\u00e9; ambos con encendidos discursos apostando a la militancia.<\/p>\n<p>Luego lo hizo el intendente de Calchaqu\u00ed, Rub\u00e9n Cuello cuyo eje fue la gesti\u00f3n, para luego dar paso al precandidato a diputado provincial Fabricio Medina quien destac\u00f3 la atenci\u00f3n del gobierno provincial para el sector productivo, \u00e1rea que conoce muy bien por su actual funci\u00f3n en el Ministerio de la Producci\u00f3n.<\/p>\n<p>En este momento del acto apareci\u00f3 en escena a trav\u00e9s de un video el gobernador Omar Perotti, precandidato a diputado provincial, quien salud\u00f3 a los presentes y destac\u00f3 el trabajo colectivo de los presidentes comunales y del senador Osvaldo Sosa en todo el departamento.<\/p>\n<p>Luego, la pantalla mostr\u00f3 un resumen de la gesti\u00f3n del senador Sosa, quien seguidamente hizo uso de la palabra para destacar el trabajo en cada comuna y los cambios positivos que hicieron que\u201d algunos presidentes comunales de otro signo pol\u00edtico se sumen a nuestro espacio\u201d.<\/p>\n<p>Sosa asegur\u00f3 que \u201clo esencial es mantener la unidad que hemos logrado para que el departamento Vera sea el que m\u00e1s votos le aporte a Marcelo para que sea el futuro gobernador\u201d.<\/p>\n<p>Finalmente, tom\u00f3 la palabra Marcelo Lewandowski, precandidato a gobernador de la provincia por \u201cElijo hacer\u201d en \u201cJuntos avancemos\u201d, quien resumi\u00f3 los principales aspectos de su propuesta, sin perder de vista lo que est\u00e1 en juego el pr\u00f3ximo 16 de julio, d\u00eda en que \u201ctenemos que hacer todo lo necesario para que el peronismo siga gobernando Santa Fe\u201d.<\/p>\n<p>Letyana Press<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante un sal\u00f3n colmado por militantes que presentaba una escenograf\u00eda adornada con pancartas con los principales referentes se presentaron los precandidatos de todo el departamento Vera, de la lista \u201cElijo hacer\u201d en la alianza \u201cJuntos avancemos\u201d. Luego de la presentaci\u00f3n individual de los precandidatos a presidentes comunales, concejales, diputados, intendente, senador y a gobernador, comenz\u00f3 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":44819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-44818","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/44818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=44818"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/44818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/44819"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=44818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=44818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=44818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}