{"id":44120,"date":"2023-05-22T20:10:36","date_gmt":"2023-05-22T23:10:36","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=44120"},"modified":"2023-05-22T20:10:36","modified_gmt":"2023-05-22T23:10:36","slug":"la-intendente-realiza-gestiones-para-vera-en-casa-rosada","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/05\/22\/la-intendente-realiza-gestiones-para-vera-en-casa-rosada\/","title":{"rendered":"La Intendente realiza gestiones para Vera en Casa Rosada"},"content":{"rendered":"<p>Terminal de \u00f3mnibus, Cine Teatro Espa\u00f1ol, emprendedores y servicios para familias vulnerables fueron algunos de los proyectos abordados.<\/p>\n<p>El anfitri\u00f3n del encuentro fue el Jefe de Gabinete de Ministros, Agust\u00edn Rossi, quien recibi\u00f3 en su despacho a la Intendente, Paula Mitre, a la Presidente del Concejo, Nancy Senn y al Concejal, Marcos Rubianes.<\/p>\n<p>La Intendente se\u00f1al\u00f3 &#8220;ha sido una reuni\u00f3n muy productiva, el Jefe de Gabinete nos ha escuchado y se interioriz\u00f3 de cada uno de los expedientes de Vera que est\u00e1n en curso, por lo que comprometi\u00f3 todo esfuerzo en dinamizar el tratamiento de los mismos manifestando que es su deseo que se concreten para la ciudad de Vera a la que considera con mucho afecto.<\/p>\n<p>Agradezco el acompa\u00f1amiento de Nancy y Marcos, porque desde su representaci\u00f3n Legislativa trabajan estas gestiones junto al Ejecutivo de nuestro municipio para beneficio de todos los verenses&#8221;.<\/p>\n<p>Los temas abordados en la reuni\u00f3n fueron los proyectos presentados ante el Ministro de Obras P\u00fablicas de la Naci\u00f3n (Terminal de Omnibus, D\u00e1rsena de Estacionamiento para el Colegio Superior N\u00b042); Vialidad Nacional (Ampliaci\u00f3n de la traves\u00eda sobre el frente de la Ciudad y retraso en la culminaci\u00f3n de la ruta 36 donde se conecta a la Ruta Nacional 11); INAES, Ministerio de Desarrollo Social de la Naci\u00f3n (Cine Teatro Espa\u00f1ol, Feria Comunitaria para emprendedores) y Ministerio de Seguridad de la Naci\u00f3n (Proyecto para equipamiento).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terminal de \u00f3mnibus, Cine Teatro Espa\u00f1ol, emprendedores y servicios para familias vulnerables fueron algunos de los proyectos abordados. El anfitri\u00f3n del encuentro fue el Jefe de Gabinete de Ministros, Agust\u00edn Rossi, quien recibi\u00f3 en su despacho a la Intendente, Paula Mitre, a la Presidente del Concejo, Nancy Senn y al Concejal, Marcos Rubianes. La Intendente [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":44121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51,53],"tags":[],"class_list":["post-44120","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/44120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=44120"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/44120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/44121"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=44120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=44120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=44120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}