{"id":43708,"date":"2023-04-28T19:28:35","date_gmt":"2023-04-28T22:28:35","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=43708"},"modified":"2023-05-02T08:11:48","modified_gmt":"2023-05-02T11:11:48","slug":"programa-de-naciones-unidas-financiara-tres-proyectos-nortenos-para-preservacion-del-medio-ambiente","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/04\/28\/programa-de-naciones-unidas-financiara-tres-proyectos-nortenos-para-preservacion-del-medio-ambiente\/","title":{"rendered":"Programa de Naciones Unidas financiar\u00e1 tres proyectos norte\u00f1os para preservaci\u00f3n del medio ambiente"},"content":{"rendered":"<p><strong>Los fondos provendr\u00e1n del Programa Peque\u00f1as Donaciones, una iniciativa institucional del Fondo para el Medio Ambiente Mundial, implementado por el Programa de las Naciones Unidas para el Desarrollo. Es articulado por los ministerios de Producci\u00f3n, Ciencia y Tecnolog\u00eda, y de Ambiente y Cambio Clim\u00e1tico de la provincia.<\/strong><\/p>\n<p>El PNUD Argentina, a trav\u00e9s de un trabajo articulado con los ministerios de Producci\u00f3n, Ciencia y Tecnolog\u00eda y de Ambiente y Cambio Clim\u00e1tico, financiar\u00e1 tres proyectos provinciales vinculados a la preservaci\u00f3n del medio ambiente. Dicha financiaci\u00f3n proviene del Programa Peque\u00f1as Donaciones (PPD), el cual es un programa institucional del Fondo para el Medio Ambiente Mundial (FMAM), implementado por el Programa de las Naciones Unidas para el Desarrollo (PNUD) y administrado por UNOPS &#8211; United Nations Office for Project Services. El objetivo es continuar apoyando a las organizaci\u00f3n de base asociativista y apostando al fortalecimiento de dicho sector en nuestra provincia.<\/p>\n<p>Al respecto, el secretario de Desarrollo Territorial y Arraigo, Fabricio Medina, destac\u00f3 la colaboraci\u00f3n del PPD y su coordinador, Francisco L\u00f3pez Sastre, con las instituciones provinciales para promover el Programa entre las organizaciones territoriales. Asimismo, detall\u00f3: \u201cLos tres proyectos a financiar son acciones que buscan hacer frente al cambio clim\u00e1tico, protegiendo la biodiversidad y evitando la degradaci\u00f3n de la tierra, todo ello en un trabajo articulado con las comunidades locales\u201d.<\/p>\n<p><strong>Los elegidos\u00a0<\/strong><\/p>\n<p>Uno de los proyectos elegidos es \u201cEl bosque nos encuentra &#8211; Desarrollo de pr\u00e1cticas sostenibles con integraci\u00f3n comunitaria, para j\u00f3venes de la Cu\u00f1a Boscosa Santafesina\u201d, presentado por la Asociaci\u00f3n Cultural para el Desarrollo Integral. Se encuentra orientado al trabajo en la Cu\u00f1a Boscosa Santafesina, implementando pr\u00e1cticas de manejo de bosque nativo con perspectiva de g\u00e9nero, con j\u00f3venes de la Escuela de la Familia Agroforestal (EFA) N\u00b0 8.249 de Intiyaco y dos familias de peque\u00f1os productores.<\/p>\n<p>Desde la organizaci\u00f3n destacaron: \u201cEl proyecto se ha construido de manera colaborativa, con la participaci\u00f3n activa de diversas instituciones y las familias de la zona, que trabajaron junto con la comunidad escolar para dise\u00f1ar una estrategia de acci\u00f3n que fortaleciera el sistema foresto-ganadero y la sostenibilidad de la biodiversidad de la Cu\u00f1a Boscosa Santafesina, a trav\u00e9s de pr\u00e1cticas de manejo de bosque nativo con perspectiva de g\u00e9nero\u201d.<\/p>\n<p>El segundo proyecto seleccionado es \u201cMujeres Huerteras y Algodoneras Agroecol\u00f3gicas\u201d, presentado por la Asociaci\u00f3n Civil Caminos del Norte, propuesta que busca fortalecer la oferta de fibra de algod\u00f3n y de alimentos agroecol\u00f3gicos de las mujeres de la Comunidad Mocov\u00ed que integran la Red de Mujeres Algodoneras de Argentina.<\/p>\n<p>En referencia a ello, desde la Asociaci\u00f3n expresaron: \u201cEstamos felices de que nuestro proyecto haya sido seleccionado, ya que es una iniciativa que tiene como objetivo fortalecer las producciones y la autonom\u00eda de mujeres que est\u00e1n al frente de huertas comunitarias y de la producci\u00f3n de algod\u00f3n agroecol\u00f3gico en la localidad de Tostado\u201d.<\/p>\n<p>Por \u00faltimo, fue incluido el proyecto \u201cCreciendo juntos por un territorio donde el arraigo sea genuino, el desarrollo comunitario posible y el bosque nativo cuidado\u201d, presentado por el Instituto de Cultura Popular Asociaci\u00f3n Civil (INCUPO), que tiene como fin fortalecer el arraigo en el medio rural, a trav\u00e9s del agregado de valor, el comercio justo y la capacitaci\u00f3n, mejorando la calidad de vida y permitiendo la conservaci\u00f3n del Bosque Nativo en Colonia Dur\u00e1n, departamento San Javier.<\/p>\n<p>Desde INCUPO destacaron: \u201cEl proyecto es formulado desde la Organizaci\u00f3n Sectorial Creciendo Juntos y consiste en la finalizaci\u00f3n y equipamiento de un sal\u00f3n multiuso, ya que hace aproximadamente 10 a\u00f1os comenz\u00f3 la construcci\u00f3n de su propia sede para la producci\u00f3n artesanal y usos m\u00faltiples. De esta manera, los fondos permitir\u00e1n la autonom\u00eda para llevar adelante las actividades vinculadas al agregado de valor de la producciones primarias del \u00e1rea urbana y periurbana del distrito\u201d.<\/p>\n<p><strong>Sobre el Programa de Peque\u00f1as Donaciones<\/strong><\/p>\n<p>El PPD Argentina comenz\u00f3 a ejecutarse en 2006 y es un programa que desde all\u00ed ha implementado 257 proyectos, con una inversi\u00f3n total de 7.340.385 de d\u00f3lares entregados mediante aportes a cada proyecto. Esto permiti\u00f3 que 50.000 familias pudieran mejorar sus condiciones de vida y al mismo tiempo, contribuir a la defensa del derecho constitucional que tiene cada habitante a vivir en un ambiente sano, a partir de acciones e iniciativas locales de conservaci\u00f3n y desarrollo sostenible.<\/p>\n<p>Adem\u00e1s, el Comit\u00e9 Directivo Nacional del PPD aprob\u00f3 47 proyectos que se ejecutar\u00e1n en las provincias de Chaco, Formosa, Santiago del Estero, Santa Fe, Misiones y Corrientes durante los pr\u00f3ximos 24 meses. Quienes recibir\u00e1n un total de 796.541 de d\u00f3lares provenientes del Fondo Mundial para el Medio Ambiente. Los mismos est\u00e1n orientados a la diversidad biol\u00f3gica, degradaci\u00f3n de tierras y cambio clim\u00e1tico y tendr\u00e1n un impacto positivo en 3465 familias.<\/p>\n<p><strong>En 170 pa\u00edses<\/strong><\/p>\n<p>El PNUD trabaja en 170 pa\u00edses y territorios con el objetivo de erradicar la pobreza y reducir la desigualdad, a trav\u00e9s del desarrollo de pol\u00edticas, habilidades de liderazgo, habilidades de asociaci\u00f3n, capacidades institucionales. Su trabajo se enfoca en las siguientes \u00e1reas: desarrollo sostenible, democracia, consolidaci\u00f3n de la paz y resiliencia clim\u00e1tica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los fondos provendr\u00e1n del Programa Peque\u00f1as Donaciones, una iniciativa institucional del Fondo para el Medio Ambiente Mundial, implementado por el Programa de las Naciones Unidas para el Desarrollo. Es articulado por los ministerios de Producci\u00f3n, Ciencia y Tecnolog\u00eda, y de Ambiente y Cambio Clim\u00e1tico de la provincia. El PNUD Argentina, a trav\u00e9s de un trabajo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":43709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":["post-43708","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/43708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=43708"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/43708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/43709"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=43708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=43708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=43708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}