{"id":43679,"date":"2023-04-27T10:20:13","date_gmt":"2023-04-27T13:20:13","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=43679"},"modified":"2023-04-27T10:20:13","modified_gmt":"2023-04-27T13:20:13","slug":"fortalecimiento-a-emprendedores-locales","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/04\/27\/fortalecimiento-a-emprendedores-locales\/","title":{"rendered":"Fortalecimiento a emprendedores locales"},"content":{"rendered":"<p>La Municipalidad de Vera entreg\u00f3 aportes econ\u00f3micos a grupo de emprendedores y artesanos verenses.<\/p>\n<p>Esta acci\u00f3n se enmarca en el plan de Fortalecimiento Econ\u00f3mico a Emprendedores Locales que persigue el objetivo de impulsar sus producciones, mediante el acompa\u00f1amiento grupal y personalizado.<\/p>\n<p>La Intendente, Paula Mitre, expres\u00f3: \u201cmediante este importante plan, el equipo de gobierno busca la modernizaci\u00f3n, tanto de la producci\u00f3n, como del \u00e1nimo del emprendedor, que ve en su gobierno un apoyo constante y el fomento del comercio local\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Vera entreg\u00f3 aportes econ\u00f3micos a grupo de emprendedores y artesanos verenses. Esta acci\u00f3n se enmarca en el plan de Fortalecimiento Econ\u00f3mico a Emprendedores Locales que persigue el objetivo de impulsar sus producciones, mediante el acompa\u00f1amiento grupal y personalizado. La Intendente, Paula Mitre, expres\u00f3: \u201cmediante este importante plan, el equipo de gobierno busca [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":43680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":{"0":"post-43679","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/43679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=43679"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/43679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/43680"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=43679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=43679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=43679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}