{"id":43087,"date":"2023-03-20T17:42:44","date_gmt":"2023-03-20T20:42:44","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=43087"},"modified":"2023-03-20T17:42:44","modified_gmt":"2023-03-20T20:42:44","slug":"la-provincia-abrio-la-inscripcion-a-los-juegos-santafesinos-2023-camino-a-los-evita","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2023\/03\/20\/la-provincia-abrio-la-inscripcion-a-los-juegos-santafesinos-2023-camino-a-los-evita\/","title":{"rendered":"La provincia abri\u00f3 la inscripci\u00f3n a los Juegos Santafesinos 2023, camino a los Evita"},"content":{"rendered":"<p>El Gobierno de Santa Fe, a trav\u00e9s de la secretar\u00eda de Deportes del Ministerio de Desarrollo Social y en conjunto con el Ministerio de Educaci\u00f3n, abri\u00f3 la inscripci\u00f3n a los Juegos Santafesinos 2023, Camino a los Evita.<\/p>\n<p>La propuesta, destinada a ni\u00f1as, ni\u00f1os y j\u00f3venes de 12 a 18 a\u00f1os, incluye m\u00e1s de 50 disciplinas entre convencionales y adaptadas para personas con discapacidad, que ser\u00e1n clasificatorias a los Juegos Nacionales Evita, a disputarse en el mes de septiembre en la ciudad de Mar del Plata.<\/p>\n<p>Al respecto, el ministro de Desarrollo Social, Danilo Capitani, expres\u00f3: \u201cEstos Juegos fueron pensados como una herramienta para la inclusi\u00f3n social, resultando una oportunidad in\u00e9dita para que miles de ni\u00f1os participen de actividades deportivas organizadas. Para la provincia de Santa Fe constituyen una importante posibilidad de encuentro y desarrollo del sentido de pertenencia\u201d.<\/p>\n<p>\u201cEn la edici\u00f3n 2022 tuvimos m\u00e1s de 80.000 participantes de toda la provincia, por lo que el deporte es nuevamente una poderosa herramienta de convocatoria, de promoci\u00f3n de valores y de construcci\u00f3n de h\u00e1bitos, con un claro sentido social\u201d, agreg\u00f3 Capitani.<\/p>\n<p>Por su parte, la secretaria de Deportes de la provincia, Florencia Molinero, resalt\u00f3 que &#8220;los Juegos Santafesinos son una propuesta que extiende su participaci\u00f3n a las 365 localidades que tienen nuestros 19 departamentos, en m\u00e1s de 50 disciplinas. El objetivo de la propuesta es potenciar el deporte y la convivencia, que el desarrollo deportivo siga creciendo, y por supuesto continuar acompa\u00f1ando y captando talentos, para que m\u00e1s atletas se sumen al alto rendimiento&#8221;.<\/p>\n<p>&#8220;Esta iniciativa del gobierno provincial, ser\u00e1 clasificatoria a los Juegos Nacionales Evita, a desarrollarse con sede en Mar del Plata durante el mes de septiembre, donde viajaremos con una delegaci\u00f3n por encima de los 1.000 deportistas&#8221;, a lo que agreg\u00f3 que &#8220;el trabajo en coordinaci\u00f3n junto al Ministerio de Educaci\u00f3n, la asociaciones y federaciones, son fundamentales para que los Juegos Santafesinos contin\u00faen siendo un \u00e9xito&#8221;, destac\u00f3 Molinero.<\/p>\n<p><strong>JUEGOS SANTAFESINOS<\/strong><\/p>\n<p>Los Juegos Santafesinos son un programa deportivo y educativo impulsado por el gobierno de la provincia de Santa Fe, orientado a ni\u00f1as, ni\u00f1os y j\u00f3venes de 12 a 18 a\u00f1os de edad que tiene como objetivo el desarrollo deportivo, la promoci\u00f3n de derechos y el fortalecimiento de la convivencia.<\/p>\n<p>El certamen, en su edici\u00f3n 2022, cont\u00f3 con la participaci\u00f3n de 80.000 deportistas de las 365 localidades que tienen nuestros 19 departamentos, 1.014 escuelas, m\u00e1s de 500 clubes y 35 federaciones y asociaciones deportivas.<\/p>\n<p>En la nueva edici\u00f3n, los ni\u00f1os, ni\u00f1as y j\u00f3venes podr\u00e1n inscribirse en 57 disciplinas, entre convencionales y adaptadas, que ser\u00e1n clasificatorias a los Juegos Nacionales Evita 2023, a desarrollarse en la ciudad de Mar del Plata, durante el mes de septiembre.<\/p>\n<p><strong>PROPUESTAS DEPORTIVAS<\/strong><\/p>\n<p>Atletismo, acuatl\u00f3n, ajedrez, arquer\u00eda, b\u00e1dminton, b\u00e1squet, boxeo, cestoball, f\u00fatbol 11 masculino y femenino, f\u00fatsal femenino, f\u00fatbol mixto, handball, beach handball, canotaje, ciclismo, ciclismo de monta\u00f1a, esgrima, escalada, gimnasia art\u00edstica, gimnasia r\u00edtmica, hockey, judo, karate, lucha libre, lucha greco-romana, nataci\u00f3n art\u00edstica, nataci\u00f3n, levantamiento ol\u00edmpico, optimist, pat\u00edn, pat\u00edn art\u00edstico, pat\u00edn carrera, pelota paleta, padel, rugby, skate, tenis, tenis de mesa, tiro, taekwondo, trampol\u00edn, triatl\u00f3n, voleibol, windsurf, v\u00f3ley de playa, y deportes adaptados: boccia, goalball, powerlifting, atletismo, f\u00fatbol 5, b\u00e1squet 3 vs. 3, v\u00f3ley sentado, tenis, tenis de mesa, nataci\u00f3n, b\u00e1dminton y taekwondo.<\/p>\n<p><strong>INSCRIPCI\u00d3N HASTE EL 28 DE ABRIL<\/strong><\/p>\n<p>Las mismas se har\u00e1n por medio de dos plataformas: las instituciones educativas deber\u00e1n hacerlo a trav\u00e9s del Sistema inform\u00e1tico integrado provisto por el Ministerio de Educaci\u00f3n de la Provincia de Santa Fe, SIGAE<\/p>\n<p>WEB:\u00a0<a href=\"https:\/\/www.santafe.gob.ar\/sigae-web\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.santafe.gob.ar\/sigae-web\/&amp;source=gmail&amp;ust=1679431182000000&amp;usg=AOvVaw0mchQET-noMfaTnzueTYrx\">https:\/\/www.santafe.gob.ar\/<wbr \/>sigae-web\/<\/a><\/p>\n<p>Por su parte, los clubes, tendr\u00e1n que inscribirse por intermedio del Sistema que depende del ministerio de Desarrollo Social:<\/p>\n<p><a href=\"https:\/\/www.santafe.gob.ar\/mds\/juegos_santafesinos\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.santafe.gob.ar\/mds\/juegos_santafesinos\/&amp;source=gmail&amp;ust=1679431182000000&amp;usg=AOvVaw2o-nkpN8-Rg3A0BA_70Wco\">https:\/\/www.santafe.gob.ar\/<wbr \/>mds\/juegos_santafesinos\/<\/a><\/p>\n<p><strong>CONSULTAS<\/strong><\/p>\n<p>Para m\u00e1s informaci\u00f3n escribir al mail\u00a0<a href=\"mailto:juegossantafesinos2023@gmail.com\" target=\"_blank\" rel=\"noopener\">juegossantafesinos2023@gmail.<wbr \/>com<\/a>\u00a0o comunicarse al tel\u00e9fono 342-6460075.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Santa Fe, a trav\u00e9s de la secretar\u00eda de Deportes del Ministerio de Desarrollo Social y en conjunto con el Ministerio de Educaci\u00f3n, abri\u00f3 la inscripci\u00f3n a los Juegos Santafesinos 2023, Camino a los Evita. La propuesta, destinada a ni\u00f1as, ni\u00f1os y j\u00f3venes de 12 a 18 a\u00f1os, incluye m\u00e1s de 50 disciplinas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":43088,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":["post-43087","post","type-post","status-publish","format-standard","has-post-thumbnail","category-provinciales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/43087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=43087"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/43087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/43088"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=43087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=43087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=43087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}