{"id":41656,"date":"2022-12-05T19:16:35","date_gmt":"2022-12-05T22:16:35","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=41656"},"modified":"2022-12-05T19:16:35","modified_gmt":"2022-12-05T22:16:35","slug":"diputados-y-senadores-del-fdt-por-lago-escondido-con-la-mafia-no-hay-democracia","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2022\/12\/05\/diputados-y-senadores-del-fdt-por-lago-escondido-con-la-mafia-no-hay-democracia\/","title":{"rendered":"Diputados y senadores del FdT por Lago Escondido: &#8220;Con la mafia no hay democracia&#8221;"},"content":{"rendered":"<p><strong>Los bloques de legisladores oficialistas repudieron el supuesto contenido de los chats de los jueces, fiscales, empresarios de medios, ex agentes de inteligencia y funcionarios p\u00fablicos y reclamaron una investigaci\u00f3n.<\/strong><\/p>\n<p>Los bloques de diputados y de senadores del Frente de Todos repudiaron el supuesto contenido de los chats de los jueces, fiscales, empresarios de medios, ex agentes de inteligencia y funcionarios p\u00fablicos y reclamaron una investigaci\u00f3n que aclare todo los sucesos.<\/p>\n<p>Seg\u00fan el comunicado de presa divulgado por las bancadas oficialistas, &#8220;este nuevo esc\u00e1ndalo institucional muestra claramente que con pr\u00e1cticas de mafiosos est\u00e1n hiriendo de muerte a la democracia argentina&#8221;.<\/p>\n<p>&#8220;Repudiamos y exigimos una inmediata investigaci\u00f3n y condena por los hechos de p\u00fablico conocimiento que involucran a jueces, fiscales, empresarios del Grupo Clar\u00edn, publicistas, un ex agente de inteligencia y el Ministro de Seguridad de la Ciudad de Buenos Aires&#8221;, afirmaron los diputados y senadores del interbloque.<\/p>\n<p>Asimismo, los legisladores del FdT sostuvieron que &#8220;jueces y fiscales que participaron activamente de la persecuci\u00f3n pol\u00edtico-judicial de Cristina Fern\u00e1ndez de Kirchner y que est\u00e1n vinculados a la jueza que no investiga el atentado en su contra, aparecen cometiendo una serie de delitos graves inadmisibles&#8221;.<\/p>\n<p>Tambi\u00e9n remarcaron que esos funcionarios judiciales &#8220;reciben costosos favores y d\u00e1divas de empresarios a los cuales les resuelven sus causas, encubren delitos, inducen al falso testimonio, presionan a la fiscal de Bariloche que investiga el hecho, falsifican documentos, pagos y facturas, y amenazan con continuar armando causas a quien hable de ellos, y hasta la aplicaci\u00f3n de torturas y encarcelamientos ilegales&#8221;.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"es\" dir=\"ltr\">\ud83d\udcc3Comunicado conjunto de Diputados\/as y Senadores\/as Nacionales del <a href=\"https:\/\/twitter.com\/FrenteDeTodos?ref_src=twsrc%5Etfw\">@FrenteDeTodos<\/a>.<\/p>\n<p>Con la mafia no hay democracia\u2935\ufe0f <a href=\"https:\/\/t.co\/IFYS1NEE5d\">pic.twitter.com\/IFYS1NEE5d<\/a><\/p>\n<p>&mdash; Diputados de TOD\u2600S (@Diputados_Todos) <a href=\"https:\/\/twitter.com\/Diputados_Todos\/status\/1599766876057645062?ref_src=twsrc%5Etfw\">December 5, 2022<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>La revelaci\u00f3n del fin de semana pasado puso luz sobre el encuentro de jueces federales, directivos del Grupo Clar\u00edn, un ministro porte\u00f1o y el jefe de los fiscales de la Ciudad, a quien se sum\u00f3 un empresario con pasado en la Agencia Federal de Inteligencia (AFI). Coordinaron as\u00ed, a trav\u00e9s de la aplicaci\u00f3n Telegram, difundir una versi\u00f3n falsa para justificar la participaci\u00f3n de varios de ellos en un vuelo privado a Bariloche. Esto abri\u00f3 un esc\u00e1ndalo sobre la presunta entrega de d\u00e1divas a magistrados y funcionarios.<\/p>\n<p>El retiro de este grupo se llev\u00f3 a cabo en\u00a0Lago Escondido, la propiedad del multimillonario\u00a0Joe Lewis, amigo de Macri, y quien tiene sus tierras cercadas al acceso p\u00fablico pese a que la Justicia lo oblig\u00f3 a brindar un paso libre hacia el espejo de agua. All\u00ed, el brit\u00e1nico tiene una mansi\u00f3n de 3.200 metros cuadrados, con amenities dignas de un jeque \u00e1rabe.<\/p>\n<p>De ese c\u00f3nclave, que se habr\u00eda tratado de disimular luego de la filtraci\u00f3n como una \u201cexcursi\u00f3n de pesca\u201d, no hay certezas de lo que se habl\u00f3. Tambi\u00e9n se certific\u00f3 la veracidad de los chats que se filtraron en las \u00faltimas horas, en los que los involucrados habr\u00edan planificado c\u00f3mo esconder los hechos.<\/p>\n<p>De confirmarse no solo la reuni\u00f3n, sino tambi\u00e9n la veracidad de los chats \u2013que se habr\u00eda producido en un grupo del servicio encriptado de mensajer\u00eda Telegram- ser\u00eda\u00a0un nuevo cap\u00edtulo del lawfare, que tendr\u00e1 tambi\u00e9n otro episodio este martes, cuando se conozca el veredicto en el juicio por la causa Vialidad, en la que est\u00e1 acusada la vicepresidenta\u00a0Cristina Kirchner.<\/p>\n<p>Seg\u00fan los diputados y senadores del FdT, &#8220;en ese viaje y en ese nefasto grupo de chats, estaban ni m\u00e1s ni menos que el juez y el padre y hermano del fiscal que \u201cinvestigaron\u201d la\u00a0Causa Vialidad, donde est\u00e1 acusada la vicepresidenta.\u00a0&#8220;El mal desempe\u00f1o de sus funciones, la comisi\u00f3n de delitos, y las graves y escandalosas inconductas \u00e9ticas est\u00e1n confesas. Exigimos la inmediata regularizaci\u00f3n institucional del Consejo de la Magistratura paralizado por el accionar nada inocente de la Corte Suprema de Justicia, la renuncia de los funcionarios p\u00fablicos involucrados y una seria y profunda investigaci\u00f3n&#8221;, enfatizaron.<\/p>\n<p>&#8220;Siempre supimos que se manejaban al margen de la ley, las instituciones y las reglas de nuestra Rep\u00fablica. Pero verlo y escucharlo de su propia voz, excede todo lo imaginado. No vamos a permitir que la mafia se apodere de la democracia&#8221;, concluyeron desde los bloques del Frente de Todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los bloques de legisladores oficialistas repudieron el supuesto contenido de los chats de los jueces, fiscales, empresarios de medios, ex agentes de inteligencia y funcionarios p\u00fablicos y reclamaron una investigaci\u00f3n. Los bloques de diputados y de senadores del Frente de Todos repudiaron el supuesto contenido de los chats de los jueces, fiscales, empresarios de medios, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":41657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[56],"tags":[],"class_list":{"0":"post-41656","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacados"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=41656"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/41657"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=41656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=41656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=41656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}