{"id":41552,"date":"2022-11-30T09:23:25","date_gmt":"2022-11-30T12:23:25","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=41552"},"modified":"2022-12-03T12:48:04","modified_gmt":"2022-12-03T15:48:04","slug":"cronograma-de-pago-de-haberes-a-empleados-publicos-correspondiente-a-noviembre","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2022\/11\/30\/cronograma-de-pago-de-haberes-a-empleados-publicos-correspondiente-a-noviembre\/","title":{"rendered":"Cronograma de pago de haberes a empleados p\u00fablicos correspondiente a noviembre"},"content":{"rendered":"<p><strong>Incluir\u00e1 el aumento remunerativo y bonificable del 7% acordado con los diferentes gremios, incremento que tambi\u00e9n ser\u00e1 percibido por el sector pasivo.<\/strong><\/p>\n<p>El Ministerio de Econom\u00eda de la provincia difundi\u00f3 el cronograma de pago de sueldos y jubilaciones correspondiente a noviembre de 2022.\u00a0 La cartera inform\u00f3 que los haberes incluyen el aumento remunerativo y bonificable del 7% acordado en las paritarias con los diferentes gremios de la administraci\u00f3n p\u00fablica provincial.Asimismo, dicho incremento ser\u00e1 percibido simult\u00e1neamente por el sector pasivo.<\/p>\n<p>El cronograma de pagos de sueldos y jubilaciones de noviembre es el siguiente:<\/p>\n<p>&gt;&gt; Jueves 1\u00b0 de diciembre: pasivos a los que les corresponde percibir un monto de bolsillo de hasta 144.000 pesos; y Escalaf\u00f3n policial<\/p>\n<p>&gt;&gt; Viernes 2 de diciembre: activos a los que les corresponde percibir un monto de bolsillo de hasta 138.000 pesos; y docentes de Escuelas Privadas Transferidas 1\u00ba y 2\u00ba Convenio<\/p>\n<p>&gt;&gt; Lunes 5 de diciembre: resto de Activos a los que les corresponde percibir un monto de bolsillo superior a 138.000 pesos; y Docentes de Escuelas Privadas Hist\u00f3ricas<\/p>\n<p>&gt;&gt; Martes 6 de diciembre: resto de Pasivos a los que les corresponde percibir un monto de bolsillo superior a 144.000 pesos<\/p>\n<p>&gt;&gt; Mi\u00e9rcoles 7 de diciembre: autoridades superiores Poder Judicial, Poder Legislativo y Poder Ejecutivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incluir\u00e1 el aumento remunerativo y bonificable del 7% acordado con los diferentes gremios, incremento que tambi\u00e9n ser\u00e1 percibido por el sector pasivo. El Ministerio de Econom\u00eda de la provincia difundi\u00f3 el cronograma de pago de sueldos y jubilaciones correspondiente a noviembre de 2022.\u00a0 La cartera inform\u00f3 que los haberes incluyen el aumento remunerativo y bonificable [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":["post-41552","post","type-post","status-publish","format-standard","category-provinciales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=41552"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41552\/revisions"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=41552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=41552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=41552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}