{"id":41111,"date":"2022-10-30T07:13:30","date_gmt":"2022-10-30T10:13:30","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=41111"},"modified":"2022-11-01T11:46:13","modified_gmt":"2022-11-01T14:46:13","slug":"causa-por-abigeato-denuncian-que-la-investigacion-del-fiscal-fue-muy-inconsistente","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2022\/10\/30\/causa-por-abigeato-denuncian-que-la-investigacion-del-fiscal-fue-muy-inconsistente\/","title":{"rendered":"Causa por abigeato: denuncian que la investigaci\u00f3n del fiscal fue &#8220;muy inconsistente&#8221;"},"content":{"rendered":"<p><strong>Los abogados defensores Ariel Willambi y Gabriel Baucero dijeron que &#8220;no se tuvo en cuenta mucha evidencia&#8221;.<\/strong><\/p>\n<p>Luego de que en la audiencia de medida cautelar realizada el s\u00e1bado, los abogados defensores de Hern\u00e1n Viano y Atilio Mazz\u00f3n tildaron de &#8220;inconsistente&#8221; la investigaci\u00f3n penal realizada por el fiscal Alejandro Rodr\u00edguez, a cargo de la causa.<\/p>\n<p>&#8220;Consideramos que la investigaci\u00f3n penal realizada por el fiscal fue muy inconsistente, no se tuvo en cuenta mucha evidencia&#8221;, afirm\u00f3 el Dr. Ariel Willambi a <strong>InfoVera<\/strong>.<\/p>\n<p>En tal sentido, el profesional dijo acerca de la actuaci\u00f3n del representante del MPA que &#8220;la verdad es que hizo agua en la investigaci\u00f3n, tuvo una actitud muy discrecional respecto de qu\u00e9 personas imputar o no imputar&#8221;.<\/p>\n<p>En cuanto al pedido del fiscal Rodr\u00edguez de prisi\u00f3n preventiva sin plazos, el abogado asegur\u00f3: &#8220;Consideramos con el Dr. Baucero que nuestros defendidos actuaron dentro del marco de la legalidad y que no hab\u00eda, no se daba ninguno de los requisitos del C\u00f3digo Procesal &#8211; art\u00edculos 220 y 221 &#8211; para que tanto Mazz\u00f3n como Viano tuvieran que purgar una prisi\u00f3n preventiva&#8221;.<\/p>\n<p>Luego, expres\u00f3 que &#8220;en un largo derrotero en la audiencia de medida cautelar, que comenz\u00f3 a las 10 de la ma\u00f1ana luego de un cuarto intermedio donde nos pudimos imponer del contenido de las actuaciones de la carpeta judicial, consideramos muy satisfactoria la resoluci\u00f3n del juez de la Investigaci\u00f3n Penal Satisfactoria, el Dr. Mauricio Martelossi, ya que a entender de esta defensa y la defensa conjunta del los doctores Baralle y Degoumois no hab\u00eda ning\u00fan tipo de evidencia que convalidara la prisi\u00f3n preventiva de nuestros defendidos&#8221;.<\/p>\n<p>Argument\u00f3 su apreciaci\u00f3n en &#8220;la mala investigaci\u00f3n que se realiz\u00f3&#8221;, y en que &#8220;ni hab\u00eda ning\u00fan elemento de peligrosidad procesal ni entorpecimiento probatorio&#8221;.<\/p>\n<p>Con relaci\u00f3n al futuro de la causa, el Dr. Willambi consign\u00f3: &#8220;Esperamos seguir adelante con la causa, entendemos que fue direccionada la investigaci\u00f3n sobre nuestros defendidos. Con el correr del tiempo vamos a terminar con esta cuesti\u00f3n lo m\u00e1s pronto posible en el marco de la investigaci\u00f3n penal&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los abogados defensores Ariel Willambi y Gabriel Baucero dijeron que &#8220;no se tuvo en cuenta mucha evidencia&#8221;. Luego de que en la audiencia de medida cautelar realizada el s\u00e1bado, los abogados defensores de Hern\u00e1n Viano y Atilio Mazz\u00f3n tildaron de &#8220;inconsistente&#8221; la investigaci\u00f3n penal realizada por el fiscal Alejandro Rodr\u00edguez, a cargo de la causa. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":41076,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-41111","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=41111"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/41076"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=41111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=41111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=41111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}