{"id":41017,"date":"2022-10-27T07:48:10","date_gmt":"2022-10-27T10:48:10","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=41017"},"modified":"2022-10-27T07:48:10","modified_gmt":"2022-10-27T10:48:10","slug":"la-fraternidad-cedio-su-edificio-filial-a-la-municipalidad-de-vera","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2022\/10\/27\/la-fraternidad-cedio-su-edificio-filial-a-la-municipalidad-de-vera\/","title":{"rendered":"La Fraternidad cedi\u00f3 su edificio filial a la Municipalidad de Vera"},"content":{"rendered":"<p>La Intendente Municipal, Ing. Paula Mitre, firm\u00f3 un convenio de comodato con el Sindicato de Conductores de Trenes de la Rep\u00fablica Argentina \u201cLa Fraternidad\u201d, donde \u00e9ste cede al municipio el edificio de la sede Vera.<\/p>\n<p>Al respecto, la Intendente expres\u00f3 \u201cfirmamos este convenio, donde el gremio \u201cLa Fraternidad\u201d nos autoriza a disponer de la Filial Vera para que el municipio realice la puesta en valor del edificio y una vez reaccionado poder desarrollar el proyecto presentado que propone actividades culturales.<\/p>\n<p>Este comodato tiene una validez de 5 a\u00f1os, con opci\u00f3n a ampliarlo por 2 a\u00f1os m\u00e1s.<\/p>\n<p>Logramos disponer de ese espacio de manera institucional y legal en beneficio de la comunidad, para darle un fin social. Hoy sentimos una gran satisfacci\u00f3n por este logro, y compartimos la emoci\u00f3n con todas las familias ferroviarias que tienen un afecto particular hacia este lugar.<\/p>\n<p>Tambi\u00e9n, entregamos a Omar Maturano, Secretario General del Gremio, dos obras con un sentido muy especial y que nos enorgullecen, una escultura de Eduardo Perot, artista pl\u00e1stico verense, hijo de ferroviarios, como as\u00ed tambi\u00e9n el libro \u201cMemorias de un Ferroviario\u201d de Edgardo Daniel Mudry, \u00faltimo afiliado de La Fraternidad de la ciudad de Vera y que deseaba profundamente que la rubrica de este convenio se hiciera realidad\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Intendente Municipal, Ing. Paula Mitre, firm\u00f3 un convenio de comodato con el Sindicato de Conductores de Trenes de la Rep\u00fablica Argentina \u201cLa Fraternidad\u201d, donde \u00e9ste cede al municipio el edificio de la sede Vera. Al respecto, la Intendente expres\u00f3 \u201cfirmamos este convenio, donde el gremio \u201cLa Fraternidad\u201d nos autoriza a disponer de la Filial [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":41018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":{"0":"post-41017","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-vera"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=41017"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/41017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/41018"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=41017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=41017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=41017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}