{"id":36326,"date":"2022-06-29T10:34:03","date_gmt":"2022-06-29T13:34:03","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=36326"},"modified":"2022-06-30T18:27:34","modified_gmt":"2022-06-30T21:27:34","slug":"cronograma-de-pago-de-sueldos-correspondientes-al-mes-de-junio-a-los-agentes-provinciales","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2022\/06\/29\/cronograma-de-pago-de-sueldos-correspondientes-al-mes-de-junio-a-los-agentes-provinciales\/","title":{"rendered":"Cronograma de pago de sueldos correspondientes al mes de junio a los agentes provinciales"},"content":{"rendered":"<p><strong>El calendario se inicia el viernes 1\u00b0 de julio.<\/strong><\/p>\n<p>El Ministerio de Econom\u00eda difundi\u00f3 el cronograma de pago de sueldos y jubilaciones correspondiente al mes de junio de 2022.Viernes 1\u00b0 de julio<\/p>\n<p>&gt;&gt; Pasivos a los que les corresponde percibir un monto de bolsillo de hasta 109.000 pesos.<\/p>\n<p>&gt;&gt; Escalaf\u00f3n policial.<\/p>\n<p>Lunes 4 de julio<\/p>\n<p>&gt;&gt; Activos a los que les corresponde percibir un monto de bolsillo de hasta 104.000 pesos.<\/p>\n<p>&gt;&gt; Docentes de Escuelas Privadas Transferidas 1\u00ba y 2\u00ba Convenio.<\/p>\n<p>Martes 5 de julio<\/p>\n<p>&gt;&gt; Resto de activos a los que les corresponde percibir un monto de bolsillo superior a 104.000 pesos.<\/p>\n<p>&gt;&gt; Docentes de Escuelas Privadas Hist\u00f3ricas.<\/p>\n<p>Mi\u00e9rcoles 6 de julio<\/p>\n<p>&gt;&gt; Resto de pasivos a los que les corresponde percibir un monto de bolsillo superior a 109.000 pesos.<\/p>\n<p>Jueves 7 de julio<\/p>\n<p>&gt;&gt; Autoridades Superiores Poder Judicial, Poder Legislativo y Poder Ejecutivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El calendario se inicia el viernes 1\u00b0 de julio. El Ministerio de Econom\u00eda difundi\u00f3 el cronograma de pago de sueldos y jubilaciones correspondiente al mes de junio de 2022.Viernes 1\u00b0 de julio &gt;&gt; Pasivos a los que les corresponde percibir un monto de bolsillo de hasta 109.000 pesos. &gt;&gt; Escalaf\u00f3n policial. Lunes 4 de julio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":{"0":"post-36326","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-provinciales"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/36326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=36326"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/36326\/revisions"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=36326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=36326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=36326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}