{"id":34782,"date":"2022-05-06T10:15:32","date_gmt":"2022-05-06T13:15:32","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=34782"},"modified":"2022-05-07T10:30:52","modified_gmt":"2022-05-07T13:30:52","slug":"la-justicia-federal-ordeno-a-una-prepaga-restablecer-la-cobertura-medica-a-una-embarazada","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2022\/05\/06\/la-justicia-federal-ordeno-a-una-prepaga-restablecer-la-cobertura-medica-a-una-embarazada\/","title":{"rendered":"La justicia federal orden\u00f3 a una prepaga restablecer la cobertura m\u00e9dica a una embarazada de gemelas"},"content":{"rendered":"<p><strong>El juez Aldo Alurralde hizo lugar al amparo de una gestante. La obra social le hab\u00eda suspendido el servicio por entender que minti\u00f3 sobre su estado. El magistrado juzg\u00f3 el caso como una \u201cdiscriminaci\u00f3n inadmisible\u201d.<\/strong><\/p>\n<p>En una medida cautelar celer\u00edsima, el juez federal de Reconquista, Dr. Aldo Mario Alurralde, resolvi\u00f3 ordenar a una prestadora de medicina prepaga el restablecimiento inmediato de la afiliaci\u00f3n y la cobertura de los servicios m\u00e9dicos asistenciales a una mujer embarazada de gemelas.<\/p>\n<p>M. J. S., tal las iniciales de la demandante, <strong>con el patrocinio legal de los abogados Josefina Haidar y Juan Manuel Andrade<\/strong>, radic\u00f3 en el juzgado de fuero federal una acci\u00f3n de amparo el 1 de noviembre que fue resuelta por el juez el 4 de noviembre, para contrarrestar la decisi\u00f3n de AMS Salud de disponer la baja de su cobertura en lo ateniente a la ces\u00e1rea y consecuente internaci\u00f3n, por entender que significar\u00eda la \u201cflagrante violaci\u00f3n al derecho a la salud y a la vida\u201d.<\/p>\n<p><strong>Esta medida adoptada en el tramo final del a\u00f1o pasado adquiere especial relevancia en este tiempo en el que las obras sociales atraviesan una crisis de dimensiones.<\/strong><\/p>\n<p>De acuerdo al fallo, la mujer inici\u00f3 el tr\u00e1mite de afiliaci\u00f3n en el mes de abril del a\u00f1o pasado, para al mes siguiente, en mayo, presentar la declaraci\u00f3n jurada acerca de su estado de salud general. En uno de los \u00edtems a informar figuraba la palabra embarazada, a lo cual M. J. S. respondi\u00f3 con un &#8220;no&#8221;.<\/p>\n<p>Empero, cuando ya hab\u00edan transcurrido semanas de aquel cuestionario a rellenar surgi\u00f3 la novedad de su embarazo, sobre lo cual la peticionante <strong>aleg\u00f3 no haber tenido conocimiento con anterioridad<\/strong>.<\/p>\n<p>Exactamente, el 9 de septiembre de 2021, AMS Salud remiti\u00f3 una carta documento a M. J. S. en la que le comunic\u00f3 que <strong>deber\u00eda abonar una suma de 4 millones de pesos para en concepto de plus<\/strong> para mantenerse dentro de las prestaciones, y que de no acceder a esa petici\u00f3n ser\u00eda dada de baja. Enseguida, recibi\u00f3 otra de similar tenor, pero esta vez con la leyenda de <strong>rescisi\u00f3n del contrato por parte de la prepaga.<\/strong><\/p>\n<blockquote><p><span style=\"font-size: 12pt;\"><strong>Los interesados en contactar a los abogados que asesoraron a la mujer en este caso, pueden contactarse a los siguientes n\u00fameros de celular: <\/strong><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Josefina Haidar &#8211; 3483 443305 &#8211; Ludue\u00f1a 887 &#8211; Reconquista<\/strong><\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Juan Manuel Andrade &#8211; 3482 667349 &#8211; San Mart\u00edn 877 &#8211; Reconquista<\/strong><\/span><\/p><\/blockquote>\n<p>En su resoluci\u00f3n, el juez Alurralde dej\u00f3 en claro que el contrato que ligaba a M.J.S. con A MS Salud fue \u201cperfeccionado y se encuentra vigente en la forma y condiciones en que las partes primigeniamente han establecido\u201d, y \u201cas\u00ed deber\u00e1 permanecer hasta tanto se verifique una nueva situaci\u00f3n jur\u00eddica por cualquier causa que fuera\u201d. Entre tanto y hasta que ello no ocurra, deber\u00e1 la prepaga \u201ccontinuar brindando la prestaci\u00f3n a la que se hab\u00eda comprometido\u201d, siendo \u201cinoficiosa y jur\u00eddicamente inadmisible la desafiliaci\u00f3n unilateral y\/o la exigencia de pagos adicionales para mantener la cobertura\u201d, agreg\u00f3.<\/p>\n<p><strong>Proteger derechos<\/strong><\/p>\n<p>El magistrado del fuero federal norte\u00f1o sostuvo la aplicaci\u00f3n de la interpretaci\u00f3n m\u00e1s extensiva para proteger los derechos de las personas y afirm\u00f3 que \u201cla protecci\u00f3n del ni\u00f1o por nacer, de raigambre constitucional; sometida a tensi\u00f3n con una alegada y no probada \u2018falsedad de la madre\u2019 al momento de contratar, invita a <strong>proteger a la persona por nacer por encima del conflicto en el que pudieren hallarse las partes\u201d<\/strong>.<\/p>\n<p>M\u00e1s adelante, asever\u00f3 que si la obra social no hubiera aceptado la contrataci\u00f3n &#8211; y recibido el pago-, bien podr\u00eda haberse negado a cubrir la asistencia complementaria del Estado; pero que, en caso contrario, se coloca junto al Estado mismo en la garant\u00eda de los derechos del ni\u00f1o, para lo cual \u201cpercibi\u00f3 la contraprestaci\u00f3n econ\u00f3mica que exigi\u00f3 como condici\u00f3n\u201d.<\/p>\n<p>Sobre ese punto, indic\u00f3 que \u201c<strong>antes de contratar, con un simple an\u00e1lisis de sangre, pudo verificar la existencia o no de persona por nacer;<\/strong> la aceptaci\u00f3n sin cotejo alguno hace presumir un obrar cuanto menos desentendido por tal eventualidad. N\u00f3tese que la cocontratante es una mujer presumiblemente \u2013desde el punto de vista biol\u00f3gico- en plena etapa f\u00e9rtil\u201d.<\/p>\n<p>Su apreciaci\u00f3n al respecto de volvi\u00f3 m\u00e1s di\u00e1fana a\u00fan al sopesar que \u201ces la obra social quien en mejores condiciones est\u00e1 de exigir y establecer los requisitos previos para evaluar a quienes se le presentan como requirentes del servicio\u201d.<\/p>\n<p><strong>G\u00e9nero<\/strong><\/p>\n<p>En cuanto a cuesti\u00f3n de g\u00e9nero, tuvo para s\u00ed que resultar\u00eda una i<strong>nterpretaci\u00f3n discriminatoria la revisi\u00f3n de un contrato en plena v\u00eda de ejecuci\u00f3n cuando una mujer gestante,<\/strong> a quien no se le exigiera examen alguno para comprobar si estaba o no en estado de gravidez, luego de conocida tal circunstancia se le pretende interrumpir un servicio de salud que se le estaba brindando.<\/p>\n<p>Dijo asimismo que la pretensi\u00f3n de prepaga se encaminaba a que \u201cla mujer tenga un conocimiento pleno y cabal de su cuerpo, m\u00e1s a\u00fan de su ciclo menstruar y de su posible estado de embarazo; superior al que puede ser constatado por la propia obra social con simples an\u00e1lisis previos\u201d. \u201cEsta exigencia coloca a la mujer en una situaci\u00f3n de discriminaci\u00f3n inadmisible\u201d, sentenci\u00f3.<\/p>\n<p>Sustent\u00f3 el fallo puntualizando que \u201cla exigencia previa de la obra social tiende a generar restricciones a la libertad reproductiva de la mujer, penaliz\u00e1ndola por la toma de decisiones en tal sentido, dej\u00e1ndola tanto a ella como a la persona por nacer sin el resguardo m\u00e9dico elegido por la actora. Se agrega a mayor abundamiento que la decisi\u00f3n de tener hijos debe adoptarse en el seno \u00edntimo e intrafamiliar, lejos de cualquier interferencia arbitraria de una obra social\u201d.<\/p>\n<p><strong>Marco legal<\/strong><\/p>\n<p>En el final, contempl\u00f3 que el prisma de la protecci\u00f3n de los derechos de la mujer, sumado al de las personas por nacer, ofrecen un \u201cmarco legal suficientemente fuerte como para conservar el acto jur\u00eddico creado por las partes\u201d en la misma forma y condiciones en que ambos contratantes lo han concebido; con prescindencia de presunciones posteriores que unilateralmente se efectuaran sin sustento f\u00e1ctico irrefutable, m\u00e1xime si ello obedece a omisiones de la prestadora por lo que \u201cno puede alegar su propia imprevisi\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El juez Aldo Alurralde hizo lugar al amparo de una gestante. La obra social le hab\u00eda suspendido el servicio por entender que minti\u00f3 sobre su estado. El magistrado juzg\u00f3 el caso como una \u201cdiscriminaci\u00f3n inadmisible\u201d. En una medida cautelar celer\u00edsima, el juez federal de Reconquista, Dr. Aldo Mario Alurralde, resolvi\u00f3 ordenar a una prestadora de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":34787,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55],"tags":[],"class_list":["post-34782","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reconquista"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/34782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=34782"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/34782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/34787"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=34782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=34782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=34782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}