{"id":33664,"date":"2022-04-06T13:00:52","date_gmt":"2022-04-06T16:00:52","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=33664"},"modified":"2022-04-07T10:41:01","modified_gmt":"2022-04-07T13:41:01","slug":"con-el-transcurso-de-los-dias-se-intensifico-el-movimiento-de-equipos-y-cosechadoras","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2022\/04\/06\/con-el-transcurso-de-los-dias-se-intensifico-el-movimiento-de-equipos-y-cosechadoras\/","title":{"rendered":"Con el transcurso de los d\u00edas, se intensific\u00f3 el movimiento de equipos y cosechadoras"},"content":{"rendered":"<p><strong>En el centro norte, se ha cosechado el 8% de la superficie sembrada con soja temprana y el 85% del ma\u00edz de primera.<\/strong><\/p>\n<p>La semana comprendida entre el 30 de marzo y el 5 de abril de 2022, en su comienzo, present\u00f3 inestabilidad clim\u00e1tica: totalmente nublado con precipitaciones de variadas intensidades, distribuci\u00f3n geogr\u00e1fica muy heterog\u00e9nea con mayor impacto en los departamentos del centro &#8211; norte del \u00e1rea de estudio.<\/p>\n<p>Los montos pluviom\u00e9tricos acumulados fluctuaron entre m\u00ednimos de 01 a 10 mm. La situaci\u00f3n cambi\u00f3 a inicios del jueves 31 a estabilidad clim\u00e1tica, con sol, temperaturas diarias en descenso y se registraron las primeras heladas, con escaso a nulo impacto en los cultivos.<\/p>\n<p>Luego, buen tiempo, vientos suaves de bajas intensidades, despejado, situaci\u00f3n que se extendi\u00f3 hasta el final del per\u00edodo, en todo el SEA.<\/p>\n<p>Con el buen tiempo permiti\u00f3 incrementar el movimiento de equipos y cosechadoras, por lo que el proceso de cosecha de la soja temprana avanz\u00f3 un 8 % y un adelanto de 19 puntos porcentuales, en comparaci\u00f3n a la campa\u00f1a pasada.<\/p>\n<p>Los rendimientos promedios m\u00ednimos y m\u00e1ximos logrados en el per\u00edodo, en las diferentes \u00e1reas fueron:<\/p>\n<p>a) sur: departamentos San Mart\u00edn y San Jer\u00f3nimo, entre 20 &#8211; 30 qq\/ha hasta 45 a 48 qq\/ha, con lotes puntuales de 54 y 58 qq\/ha, y<\/p>\n<p>b) centro: departamentos San Crist\u00f3bal, San Justo, Castellanos, Las Colonias y La Capital, entre 15 &#8211; 18 qq\/ha hasta 30 &#8211; 45 qq\/ha, con lotes puntuales de 50 a 53 qq\/ha.<\/p>\n<p>Para el intervalo comprendido entre el 6 y el 12 de abril, los pron\u00f3sticos prev\u00e9n desde su comienzo, estabilidad clim\u00e1tica, despejado, buen tiempo, temperaturas diarias medias en ascenso, condiciones que el jueves 7 comenzar\u00edan a variar, con un aumento de la nubosidad y altas probabilidades de precipitaciones de distintas intensidades, en los departamentos del norte del \u00e1rea de estudio y en el resto se mantendr\u00eda estable.<\/p>\n<p>Esta condici\u00f3n cambiar\u00eda a fines del domingo 10 hacia inestabilidad clim\u00e1tica con altas posibilidades de lluvias de diversos montos en todo el SEA.<\/p>\n<p><strong>Ma\u00edz Temprano<\/strong><\/p>\n<p>El proceso de la cosecha del ma\u00edz temprano estuvo condicionado clim\u00e1ticamente, por lo que las tareas se ralentizaron ante la humedad ambiente y del grano, en los distintos departamentos del SEA.<\/p>\n<p>El grado de avance de la trilla hasta la fecha fue del 85 %, con un progreso intersemanal de 10 puntos y un adelanto de 15 puntos porcentuales, en comparaci\u00f3n a la campa\u00f1a pasada.<\/p>\n<p>Los rendimientos promedios m\u00ednimos y m\u00e1ximos logrados en el per\u00edodo, en las diferentes \u00e1reas fueron:<\/p>\n<blockquote><p><strong><span style=\"font-size: 12pt;\">a) Norte: departamentos Nueve de Julio, General Obligado, Vera y norte de San Javier, entre 7 &#8211; 9 a 12 qq\/ha hasta 35 &#8211; 40 a 51 qq\/ha, con lotes puntuales de 60 a 68 qq\/ha,<\/span><\/strong><\/p><\/blockquote>\n<p>b) Centro: departamentos San Crist\u00f3bal, San Justo, Castellanos, Las Colonias y La Capital, entre 45 &#8211; 50 a 55 qq\/ha hasta 60 &#8211; 75 a 85 qq\/ha, con lotes puntuales de 70 a 90 qq\/ha,<\/p>\n<p>c) Sur: departamentos San Mart\u00edn y San Jer\u00f3nimo, entre 24 &#8211; 28 a 32 qq\/ha hasta 75 a 90 qq\/ha, con lotes puntuales de 95 y 110 qq\/ha. La sanidad de los sembrad\u00edos se encontr\u00f3 muy bien.<\/p>\n<p><strong>Algod\u00f3n<\/strong><\/p>\n<p>Las condiciones ambientales del per\u00edodo y las precipitaciones registradas la semana anterior, favorecieron el nuevo ciclo de floraci\u00f3n de los algodonales que se dejaron para una nueva carga. Pero, las bajas temperaturas no beneficiaron dicho proceso, sino que afectaron a los cultivares y se sum\u00f3 a ello el temor de heladas tempranas, que interrumpir\u00edan totalmente el nuevo ciclo.<\/p>\n<p>Adem\u00e1s, las caracter\u00edsticas h\u00famedas favorecieron el rebrote de los lotes que se encontraban pr\u00f3ximos a la recolecci\u00f3n, principalmente en la zona sur, en donde las consecuencias de la sequ\u00eda fueron levemente menores.<\/p>\n<p>El proceso de cosecha avanz\u00f3 lentamente en los predios con madurez fisiol\u00f3gica, recordando que los rendimientos alcanzados hasta la fecha, oscilaron desde 4 a 8 qq\/ha y los de mejores condiciones de 10 a 15 qq\/ha, que fueron considerados para su recolecci\u00f3n o no, quedando el resto de los cultivares a la espera de una nueva etapa de floraci\u00f3n.<\/p>\n<p>Los estados de los algodonales continuaron siendo muy variables a nivel general, debido a las precipitaciones ocurridas en cada zona, desde mediados del ciclo hasta la fecha, <strong>los m\u00e1s perjudicados fueron los de la regi\u00f3n norte de los departamentos General Obligado y Vera, donde las p\u00e9rdidas se incrementaron con el transcurso de los d\u00edas y alcanzaron situaciones irreversibles en el 95 al 100 % de ellos.<\/strong><\/p>\n<p><strong>Soja de Primera<\/strong><\/p>\n<p>El cultivo de soja temprana concentr\u00f3 el mayor movimiento de equipos y cosechadoras, observ\u00e1ndose con el transcurso de los d\u00edas un ritmo m\u00e1s intenso de trilla, principalmente, en los departamentos del sur y centro del \u00e1rea del SEA.<\/p>\n<p>Los rendimientos promedios m\u00ednimos y m\u00e1ximos logrados en el per\u00edodo, en las diferentes \u00e1reas fueron:<\/p>\n<p>a) Sur: departamentos San Mart\u00edn y San Jer\u00f3nimo, entre 20 &#8211; 30 qq\/ha hasta 45 a 48 qq\/ha, con lotes puntuales de 54 y 58 qq\/ha;<\/p>\n<p>b) Centro: departamentos San Crist\u00f3bal, San Justo, Castellanos, Las Colonias y La Capital, entre 15 &#8211; 18 qq\/ha hasta 30 &#8211; 45 qq\/ha, con lotes puntuales de 50 a 53 qq\/ha.<\/p>\n<p>El 80 % de los cultivares en pie, se mostr\u00f3 en estado bueno a muy bueno, con algunos lotes excelentes. En el 20 % restante del \u00e1rea implantada, el impacto de la ausencia de precipitaciones y el elevado r\u00e9gimen t\u00e9rmico durante los primeros 16 d\u00edas del a\u00f1o, dejaron indicadores muy marcados, tales como, limitaciones en el crecimiento de las plantas, amarillamiento o marchitamiento de las hojas basales y en lotes puntuales, la p\u00e9rdida de ejemplares por mortandad, realidad irreversible. Se aplicaron insecticidas para el \u00f3ptimo control de las plagas.<\/p>\n<p><strong>Soja de Segunda<\/strong><\/p>\n<p>Los sojales de segunda continuaron sin inconvenientes su evoluci\u00f3n y desarrollo, estabiliz\u00e1ndose sus estados y manteni\u00e9ndose un 60 % de los mismos en buen a muy buen estado, con mejor desarrollo de las estructuras de los ejemplares y un importante n\u00famero de ellos, lleg\u00f3 a los cierres parciales o totales de los surcos.<\/p>\n<p>Un 20% reaccion\u00f3 m\u00e1s lentamente, dadas las precipitaciones irregulares o a la etapa fenol\u00f3gica en que se encontraban. El 20% restante continu\u00f3 en situaci\u00f3n irreversible, con p\u00e9rdida por mortandad de plantas, especialmente en los sembrad\u00edos con limitaciones ed\u00e1ficas en sus suelos. Se aplicaron insecticidas para el \u00f3ptimo control de las plagas.<\/p>\n<p><strong>Ma\u00edz de Segunda<\/strong><\/p>\n<p>Las condiciones clim\u00e1ticas que reinaron en el transcurso de los d\u00edas fueron favorables para los maizales de segunda, los que continuaron manifestando gran amplitud de estados vegetativos, incluso en un mismo departamento, como consecuencia de las distintas fechas de siembra y debido a la particular situaci\u00f3n que se present\u00f3 en toda el \u00e1rea de estudio, dadas las precipitaciones irregulares.<\/p>\n<p>Un 90 % de los maizales tard\u00edos presentaron un buen a muy buen estado, con vigoroso desarrollo de las estructuras de las plantas, uniformes y se hallaron cursando la etapa reproductiva, sin inconvenientes.<\/p>\n<p>El 10 % restante, mostr\u00f3 secuelas por las escasas a nulas lluvias, en el inicio del ciclo 2022. El estado sanitario en general fue muy bueno, sin presencia de plagas ni de enfermedades.<\/p>\n<p><strong>Ma\u00edz Tard\u00edo<\/strong><\/p>\n<p>Continuaron siendo muy favorables las condiciones clim\u00e1ticas para los maizales de segunda, los que manifestaron gran amplitud de estados vegetativos, incluso en un mismo departamento, como consecuencia de las distintas fechas de siembra y debido a la particular situaci\u00f3n que se present\u00f3 en toda el \u00e1rea de estudio, por las precipitaciones irregulares de la campa\u00f1a.<\/p>\n<p>Un 90 % de los maizales tard\u00edos presentaron un buen a muy buen estado, con vigoroso desarrollo de las estructuras de las plantas, uniformes y se hallaron cursando la etapa reproductiva, sin inconvenientes. El 10 % restante, mostr\u00f3 secuelas por las escasas a nulas lluvias, en el inicio del ciclo 2022. El estado sanitario en general fue muy bueno, sin presencia de plagas ni de enfermedades.<\/p>\n<p><strong>Agua \u00fatil<\/strong><\/p>\n<p>En la superficie total del \u00e1rea de estudio del centro norte santafesino, constituida por los departamentos Nueve de Julio, Vera, General Obligado, San Crist\u00f3bal, San Justo, San Javier, Garay, Castellanos, Las Colonias, La Capital, San Mart\u00edn y San Jer\u00f3nimo, la disponibilidad de agua \u00fatil en los primeros 20 cm de los suelos cubri\u00f3 en forma regular las necesarias demandas de los diferentes cultivos, seg\u00fan los estadios fenol\u00f3gicos de cada uno de ellos, que fueron favorecidos con las nuevas precipitaciones ocurridas en la semana y por el almacenamiento del agua ca\u00edda.<\/p>\n<p>En algunos departamentos con posiciones topogr\u00e1ficas bajas se observaron suelos saturados, sobresaturados y algunos encharcamientos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el centro norte, se ha cosechado el 8% de la superficie sembrada con soja temprana y el 85% del ma\u00edz de primera. La semana comprendida entre el 30 de marzo y el 5 de abril de 2022, en su comienzo, present\u00f3 inestabilidad clim\u00e1tica: totalmente nublado con precipitaciones de variadas intensidades, distribuci\u00f3n geogr\u00e1fica muy heterog\u00e9nea [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":33665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":["post-33664","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/33664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=33664"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/33664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/33665"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=33664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=33664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=33664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}