{"id":28666,"date":"2021-10-21T11:00:48","date_gmt":"2021-10-21T14:00:48","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=28666"},"modified":"2021-10-22T14:13:38","modified_gmt":"2021-10-22T17:13:38","slug":"paritarias-el-proyecto-de-ley-de-pase-a-planta-entro-a-la-legislatura","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/10\/21\/paritarias-el-proyecto-de-ley-de-pase-a-planta-entro-a-la-legislatura\/","title":{"rendered":"Paritarias: el proyecto de ley de pase a planta entr\u00f3 a la Legislatura"},"content":{"rendered":"<p><strong>El Sindicato de M\u00e9dicos de la Rep\u00fablica Argentina (AMRA) Seccional Santa Fe inform\u00f3 que luego de los reiterados pedidos de nuestra entidad gremial en el marco de la negociaci\u00f3n paritaria,<\/strong> el Poder Ejecutivo, a trav\u00e9s del senador Marcos Castell\u00f3, ingres\u00f3 formalmente a la Legislatura el proyecto de Ley &#8220;Excepciones Sindicatos&#8221; para la creaci\u00f3n de cargos de los profesionales de la salud que ingresaron como trabajadores del Estado en calidad de contratados y monotributistas hasta diciembre de 2018.<\/p>\n<p>&#8220;Ante este escenario que afortunadamente despu\u00e9s de meses de lucha pondr\u00e1 fin a la injusticia que padecen gran parte de compa\u00f1eros y compa\u00f1eras que trabajan en condiciones precarias, AMRA, mediante Asamblea de Delegados, decide aceptar la propuesta paritaria pero mantiene el estado de alerta y movilizaci\u00f3n hasta tanto la Legislatura convierta en Ley dicho proyecto.<\/p>\n<p>Por \u00faltimo exigimos en car\u00e1cter de urgencia una reuni\u00f3n con las autoridades del Ministerio de Salud para solicitar que cuanto antes los profesionales y las profesionales que trabajan como contratados y monotributistas cobren el aumento otorgado en paritarias para este tramo final del a\u00f1o al igual que lo percibir\u00e1n los colegas y las colegas de planta permanente&#8221;, consign\u00f3 Amra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Sindicato de M\u00e9dicos de la Rep\u00fablica Argentina (AMRA) Seccional Santa Fe inform\u00f3 que luego de los reiterados pedidos de nuestra entidad gremial en el marco de la negociaci\u00f3n paritaria, el Poder Ejecutivo, a trav\u00e9s del senador Marcos Castell\u00f3, ingres\u00f3 formalmente a la Legislatura el proyecto de Ley &#8220;Excepciones Sindicatos&#8221; para la creaci\u00f3n de cargos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[60],"tags":[],"class_list":["post-28666","post","type-post","status-publish","format-standard","category-provinciales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/28666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=28666"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/28666\/revisions"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=28666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=28666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=28666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}