{"id":26477,"date":"2021-09-08T11:15:23","date_gmt":"2021-09-08T14:15:23","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=26477"},"modified":"2021-09-08T11:15:23","modified_gmt":"2021-09-08T14:15:23","slug":"espaldarazo-de-bullrich-a-angelini-y-granata","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/09\/08\/espaldarazo-de-bullrich-a-angelini-y-granata\/","title":{"rendered":"Espaldarazo de Bullrich a Angelini y Granata"},"content":{"rendered":"<p><strong>\u201cEs muy importante tener hoy una lista que encabece Federico Angelini\u201d, afirm\u00f3 la presidenta del PRO Argentina.<\/strong><\/p>\n<p>La actual presidenta del PRO y exministra de Seguridad, Patricia Bullrich, lleg\u00f3 a la ciudad de Rosario este martes para brindarles un fuerte espaldarazo a las precandidaturas a senadores nacionales de Federico Angelini y Amalia Granata, que encabezan la lista Santa Fe Nos Une, de cara a las PASO de este domingo.<\/p>\n<p>\u201cPara nosotros, es muy importante tener hoy una lista que encabece Federico Angelini, que es el vicepresidente nacional del PRO, y que lo acompa\u00f1e Amalia Granata, porque nuestro objetivo es tener una lista que represente el coraz\u00f3n de lo que es Santa Fe\u201d, afirm\u00f3 Bullrich ante los medios, minutos antes del acto en Salones Puerto Norte, donde tanto la exministra de Seguridad como los candidatos fueron ovacionados por el p\u00fablico.<\/p>\n<p>\u201cFederico y Amalia vienen recorriendo Santa Fe hace much\u00edsimos a\u00f1os y conocen el coraz\u00f3n del sue\u00f1o santafesino, que es poder progresar y lograr que sus hijos progresen. Ese sue\u00f1o del porvenir, de la educaci\u00f3n y la cultura del trabajo es lo que representa nuestra lista. Y por eso, yo, como presidenta nacional del PRO, apoyo esta lista, porque tambi\u00e9n es importante ir proyectando una Santa Fe 2023\u201d, expres\u00f3 Bullrich.<\/p>\n<p>Adem\u00e1s, destac\u00f3 que Angelini \u201cestuvo en los momentos m\u00e1s dif\u00edciles, defendiendo a los santafesinos\u201d y, en ese sentido, indic\u00f3: \u201c\u00a1Qui\u00e9n no vio a Federico en cada uno de los pueblos de la provincia de Santa Fe!\u201d.<\/p>\n<p>En tanto, el precandidato a senador y actual vicepresidente del PRO afirm\u00f3 que \u201ces un gran honor y orgullo contar con el apoyo de Patricia Bullrich\u201d, y tambi\u00e9n una gran responsabilidad para poder seguir defendiendo los intereses de los santafesinos, como lo venimos haciendo actualmente, y poder frenar los avances y las amenazas del Kirchnerismo en el Senado, porque si el oficialismo logra las mayor\u00edas especiales, ser\u00eda el fin de la Rep\u00fablica\u201d.<\/p>\n<p>\u201cEste domingo 12 de septiembre es el primer paso para decirle basta a los corruptos, basta a los narcotraficantes, basta a los que quieren coartar nuestras libertades, basta a los que quieren llevarse puestas las instituciones y basta a los que quieren fomentar el pobrismo\u201d, manifest\u00f3 Angelini.<\/p>\n<p>LUCHA CONTRA EL NARCOTR\u00c1FICO<\/p>\n<p>Bullrich sostuvo que \u201clo primero que falta hoy en Santa Fe es seguridad\u201d y consider\u00f3 que \u201cla situaci\u00f3n es terrible\u201d. \u201cDespu\u00e9s de todo el trabajo profundo que nosotros hab\u00edamos hecho contra el narcotr\u00e1fico en Santa Fe, vino un gobierno que dijo que todo eso no serv\u00eda y ahora nos encontramos con aumento de las muertes por narcotr\u00e1fico y venganzas\u201d, expres\u00f3 la exministra, quien agreg\u00f3: \u201cNunca hay que dejar que se reproduzca el narcotr\u00e1fico, como pas\u00f3 en este a\u00f1o y medio, con una pol\u00edtica de anti combate al narcotr\u00e1fico, que le hace muy mal a la ciudadan\u00eda\u201d.<\/p>\n<p>Por su parte, Angelini apunt\u00f3 que \u201cen Santa Fe se viv\u00eda mejor cuando Patricia Bullrich estaba a cargo del Ministerio de Seguridad\u201d y remarc\u00f3: \u201cNosotros trabaj\u00e1bamos espalda con espalda, avanzando contra los narcotraficantes. Entonces, no tenemos que resignarnos a vivir as\u00ed; yo estoy convencido de que hay una salida, porque ya hemos enfrentado las mafias con Patricia y hemos bajado los \u00edndices delictivos; sabemos c\u00f3mo hacerlo\u201d.<\/p>\n<p>DERROTAR LA PATRIA DEL POBRISMO<\/p>\n<p>Quien tambi\u00e9n particip\u00f3 del acto en Rosario para brindar su apoyo a la f\u00f3rmula Angelini-Granata fue el exsenador y actual auditor general de la Naci\u00f3n, Miguel \u00c1ngel Pichetto, quien asegur\u00f3 que \u201cestamos frente a una elecci\u00f3n fundamental en Argentina\u201d, en la que \u201ctenemos que derrotar la patria del pobrismo\u201d.<\/p>\n<p>El excandidato a vicepresidente junto a Mauricio Macri consider\u00f3 que \u201cnuestros candidatos tienen que ir al Congreso con un compromiso, que es no votar ning\u00fan impuesto m\u00e1s en Argentina\u201d, y llam\u00f3 a \u201cderrotar a este gobierno, que limita las exportaciones de carne y jode a todos los sectores productivos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEs muy importante tener hoy una lista que encabece Federico Angelini\u201d, afirm\u00f3 la presidenta del PRO Argentina. La actual presidenta del PRO y exministra de Seguridad, Patricia Bullrich, lleg\u00f3 a la ciudad de Rosario este martes para brindarles un fuerte espaldarazo a las precandidaturas a senadores nacionales de Federico Angelini y Amalia Granata, que encabezan [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[66],"tags":[],"class_list":["post-26477","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/26477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=26477"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/26477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/26479"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=26477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=26477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=26477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}